{"id":85576,"date":"2020-10-31T01:44:07","date_gmt":"2020-10-31T06:44:07","guid":{"rendered":"https:\/\/elinformanteperu.com\/?p=85576"},"modified":"2020-10-31T01:44:07","modified_gmt":"2020-10-31T06:44:07","slug":"elecciones-2021-keiko-fujimori-inscribe-su-precandidatura-presidencial-en-fuerza-popular","status":"publish","type":"post","link":"https:\/\/elinformanteperu.com\/index.php\/2020\/10\/31\/elecciones-2021-keiko-fujimori-inscribe-su-precandidatura-presidencial-en-fuerza-popular\/","title":{"rendered":"Elecciones 2021: Keiko Fujimori inscribe su precandidatura presidencial en Fuerza Popular"},"content":{"rendered":"<p><span style=\"color: #000000;\"><strong>Lima, 30 Octubre 2020, (ANDINA).<\/strong>&#8211; Keiko Fujimori inscribi\u00f3 su precandidatura a la presidencia de la Rep\u00fablica para participar en las elecciones internas del partido Fuerza Popular para las elecciones generales del 2021.<\/span><\/p>\n<p><span style=\"color: #000000;\">Completan su plancha presidencial, Luis Galarreta Velarde y Patricia Ju\u00e1rez Gallegos como precandidatos a la primera y segunda vicepresidencia de la Rep\u00fablica.<\/span><\/p>\n<p><span style=\"color: #000000;\">\u00abAcabo de firmar la inscripci\u00f3n de la plancha presidencial de Fuerza Popular para las elecciones internas de nuestro partido\u00bb, se\u00f1al\u00f3 Fujimori Higuchi en su cuenta de Twitter.<\/span><\/p>\n<p><span style=\"color: #000000;\">Galarreta Velarde fue congresista del Parlamento anterior, mientras que Ju\u00e1rez Gallegos fue teniente alcaldesa en la gesti\u00f3n municipal de Luis Casta\u00f1eda Lossio.<\/span><\/p>\n<p><span style=\"color: #000000;\">De acuerdo al cronograma electoral aprobado por el Jurado Nacional de Elecciones (JNE), ma\u00f1ana vence el plazo para que las organizaciones pol\u00edticas presenten a la Oficina Nacional de Procesos Electorales (ONPE) la lista de precandidatos que participar\u00e1n en las internas con miras al proceso electoral de abril pr\u00f3ximo.<\/span><\/p>\n<p><span style=\"color: #000000;\">Por primera vez en la historia electoral del pa\u00eds, la ONPE organizar\u00e1, de manera simult\u00e1nea, las elecciones internas de los partidos como parte del proceso electoral 2021.<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Lima, 30 Octubre 2020, (ANDINA).&#8211; Keiko Fujimori inscribi\u00f3 su precandidatura a la presidencia de la Rep\u00fablica para participar en las elecciones internas del partido Fuerza Popular para las elecciones generales del 2021. Completan su plancha presidencial, Luis Galarreta Velarde y Patricia Ju\u00e1rez Gallegos como precandidatos a la primera y segunda vicepresidencia de la Rep\u00fablica. \u00abAcabo [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":85577,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"rop_custom_images_group":[],"rop_custom_messages_group":[],"rop_publish_now":"initial","rop_publish_now_accounts":[],"rop_publish_now_history":[],"rop_publish_now_status":"pending","footnotes":""},"categories":[5],"tags":[5461,295,557,150],"class_list":["post-85576","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualidad-informativa","tag-elecciones-2021","tag-fuerza-popular","tag-keiko-fujimori","tag-onpe"],"_links":{"self":[{"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/posts\/85576","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/comments?post=85576"}],"version-history":[{"count":1,"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/posts\/85576\/revisions"}],"predecessor-version":[{"id":85578,"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/posts\/85576\/revisions\/85578"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/media\/85577"}],"wp:attachment":[{"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/media?parent=85576"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/categories?post=85576"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/tags?post=85576"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}