{"id":83155,"date":"2020-09-28T20:13:57","date_gmt":"2020-09-29T01:13:57","guid":{"rendered":"https:\/\/elinformanteperu.com\/?p=83155"},"modified":"2020-09-28T20:13:57","modified_gmt":"2020-09-29T01:13:57","slug":"carlos-zambrano-es-ratificado-como-titular-en-boca-juniors-ante-libertad-en-la-bombonera","status":"publish","type":"post","link":"https:\/\/elinformanteperu.com\/index.php\/2020\/09\/28\/carlos-zambrano-es-ratificado-como-titular-en-boca-juniors-ante-libertad-en-la-bombonera\/","title":{"rendered":"Carlos Zambrano es ratificado como titular en Boca Juniors ante Libertad en La Bombonera"},"content":{"rendered":"<p><span style=\"color: #000000;\"><strong>Buenos Aires, 28 Setiembre 2020, (ANDINA).-<\/strong> El defensa peruano Carlos Zambrano prolonga su excelente presente en el Boca Juniors al ser uno de los elegidos por Miguel Angel Russo para enfrentar este martes al Libertad de Paraguay por la Copa Libertadores en La Bombonera de Buenos Aires.<\/span><\/p>\n<p><span style=\"color: #000000;\">El diario Ol\u00e9 indic\u00f3 que Carlos Zambrano, de muy buenos partidos junto a Carlos Izquierdoz, mantendr\u00e1 su lugar en la zaga boquense, relegando en el banco de suplentes a Lisandro L\u00f3pez, titular habitual en la oncena aurizul antes de la consolidaci\u00f3n del back de la selecci\u00f3n peruana.<\/span><\/p>\n<p><span style=\"color: #000000;\">Zambrano ha tenido destacadas actuaciones ante el Libertad en Paraguay y ante el Deportivo Independiente Medell\u00edn en Colombia, con triunfos de los boquenses, lo cual le ha valido el reconocimiento de la prensa argentina.<\/span><\/p>\n<p><span style=\"color: #000000;\">Incluso, en una reciente encuesta elaborada por el Diario Ol\u00e9, sus lectores eligieron a Carlos Zambrano para integrar la pareja de defensas centrales en Boca Juniors hasta en dos oportunidades.<\/span><\/p>\n<p><span style=\"color: #000000;\">Uno de los cambios para el cotejo con el Libertad que ensayar\u00eda Russo, seg\u00fan la p\u00fablicaci\u00f3n, ser\u00eda el ingreso del colombiano Frank Fabra por Emmanuel Mas, para darle m\u00e1s peso ofensivo a Boca Juniors.<\/span><\/p>\n<p><span style=\"color: #000000;\">La otra variante, obligada por la lesi\u00f3n de Gonzalo Maroni, ser\u00e1 el ingreso de Agust\u00edn Obando.<\/span><\/p>\n<p><span style=\"color: #000000;\">El partido ante Libertad correspondiente a la quinta fecha del grupo H se disputar\u00e1 este martes desde las 21.30 en la Bombonera. A Boca Juniors le alcanzar\u00e1 con sumar un punto para asegurarse la clasificaci\u00f3n a los octavos de final de la Copa Libertadores.<\/span><\/p>\n<p><span style=\"color: #000000;\">El probable once de Boca Juniors ser\u00e1 con Esteban Andrada; Leonardo Jara, Carlos Zambrano, Carlos Izquierdoz, Fabra; Eduardo Salvio, Jorman Campuzano, Pol Fern\u00e1ndez, Obando; Carlos Tevez y Franco Soldano.<\/span><\/p>\n<p><img fetchpriority=\"high\" decoding=\"async\" class=\"aligncenter size-full wp-image-64369\" src=\"https:\/\/elinformanteperu.com\/wp-content\/uploads\/2020\/02\/carlos-zambrano-boca-juniors-1.jpg\" alt=\"\" width=\"1800\" height=\"1205\" srcset=\"https:\/\/elinformanteperu.com\/wp-content\/uploads\/2020\/02\/carlos-zambrano-boca-juniors-1.jpg 1800w, https:\/\/elinformanteperu.com\/wp-content\/uploads\/2020\/02\/carlos-zambrano-boca-juniors-1-300x201.jpg 300w, https:\/\/elinformanteperu.com\/wp-content\/uploads\/2020\/02\/carlos-zambrano-boca-juniors-1-1024x686.jpg 1024w, https:\/\/elinformanteperu.com\/wp-content\/uploads\/2020\/02\/carlos-zambrano-boca-juniors-1-768x514.jpg 768w, https:\/\/elinformanteperu.com\/wp-content\/uploads\/2020\/02\/carlos-zambrano-boca-juniors-1-1536x1028.jpg 1536w, https:\/\/elinformanteperu.com\/wp-content\/uploads\/2020\/02\/carlos-zambrano-boca-juniors-1-128x86.jpg 128w, https:\/\/elinformanteperu.com\/wp-content\/uploads\/2020\/02\/carlos-zambrano-boca-juniors-1-32x21.jpg 32w\" sizes=\"(max-width: 1800px) 100vw, 1800px\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Buenos Aires, 28 Setiembre 2020, (ANDINA).- El defensa peruano Carlos Zambrano prolonga su excelente presente en el Boca Juniors al ser uno de los elegidos por Miguel Angel Russo para enfrentar este martes al Libertad de Paraguay por la Copa Libertadores en La Bombonera de Buenos Aires. El diario Ol\u00e9 indic\u00f3 que Carlos Zambrano, de [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":83156,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"rop_custom_images_group":[],"rop_custom_messages_group":[],"rop_publish_now":"initial","rop_publish_now_accounts":[],"rop_publish_now_history":[],"rop_publish_now_status":"pending","footnotes":""},"categories":[8],"tags":[2642,1885],"class_list":["post-83155","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-disciplinas-deportivas","tag-boca-juniors","tag-carlos-zambrano"],"_links":{"self":[{"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/posts\/83155","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/comments?post=83155"}],"version-history":[{"count":1,"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/posts\/83155\/revisions"}],"predecessor-version":[{"id":83157,"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/posts\/83155\/revisions\/83157"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/media\/83156"}],"wp:attachment":[{"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/media?parent=83155"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/categories?post=83155"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/tags?post=83155"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}