{"id":83149,"date":"2020-09-28T20:03:22","date_gmt":"2020-09-29T01:03:22","guid":{"rendered":"https:\/\/elinformanteperu.com\/?p=83149"},"modified":"2020-09-28T20:03:22","modified_gmt":"2020-09-29T01:03:22","slug":"christian-ramos-asegura-que-la-seleccion-peruana-se-ha-ganado-un-nombre","status":"publish","type":"post","link":"https:\/\/elinformanteperu.com\/index.php\/2020\/09\/28\/christian-ramos-asegura-que-la-seleccion-peruana-se-ha-ganado-un-nombre\/","title":{"rendered":"Christian Ramos asegura que la selecci\u00f3n peruana se ha ganado un nombre"},"content":{"rendered":"<p><span style=\"color: #000000;\"><strong>Lima, 28 Setiembre 2020, (ANDINA).<\/strong>&#8211; El defensa de la selecci\u00f3n peruana, Christian Ramos destac\u00f3 que ve bien a la bicolor porque se ha ganado un nombre y un respeto, adem\u00e1s manifest\u00f3 que fue una buena decisi\u00f3n que las Eliminatorias se inicien en octubre.<\/span><\/p>\n<p><span style=\"color: #000000;\">Ramos dej\u00f3 ver su emoci\u00f3n por volver a la escuadra nacional y se\u00f1al\u00f3 que fue recibido bien en su regreso a un combinado patrio en el primer d\u00eda de entrenamiento en la Villa Deportiva Nacional (Videna).<\/span><\/p>\n<p><span style=\"color: #000000;\">\u00abNo lo tomo como el primer d\u00eda de clases, pero s\u00ed estoy contento y muy emocionado por volver a la selecci\u00f3n, por estar en este grupo que se ha formado\u00bb, declar\u00f3 Ramos en Movistar Deportes.<\/span><\/p>\n<p><span style=\"color: #000000;\">Agreg\u00f3: \u00abMe han recibido bien, con toda la picard\u00eda que tenemos, siempre molest\u00e1ndonos y haciendo bromas. No estuve jugando mucho y eso era el primer factor, que hizo que no est\u00e9 en la selecci\u00f3n\u00bb.<\/span><\/p>\n<p><span style=\"color: #000000;\">Christian Ramos dio a conocer que convers\u00f3 con el t\u00e9cnico Ricardo Gareca, a quien le manifest\u00f3 que siempre quer\u00eda regresar a la selecci\u00f3n<\/span><\/p>\n<p><span style=\"color: #000000;\">Destac\u00f3 la jerarqu\u00eda que viene teniendo el combinado patrio. \u00abVeo a la selecci\u00f3n muy bien, nos hemos ganado un nombre. Me parece que est\u00e1 bien que las Clasificatorias comiencen en octubre\u00bb.<\/span><\/p>\n<p><span style=\"color: #000000;\">La escuadra nacional inici\u00f3 hoy sus trabajos con miras a sus partidos contra Paraguay (8 de octubre), en Asunci\u00f3n, y frente a Brasil, el 13 de octubre, en Lima, por la fecha 1 y 2 de las Eliminatorias al Mundial Catar 2022.<\/span><\/p>\n<p><img fetchpriority=\"high\" decoding=\"async\" class=\"aligncenter size-full wp-image-26733\" src=\"https:\/\/elinformanteperu.com\/wp-content\/uploads\/2018\/05\/Christian-Ramos-entrenamiento.jpg\" alt=\"\" width=\"1800\" height=\"1200\" srcset=\"https:\/\/elinformanteperu.com\/wp-content\/uploads\/2018\/05\/Christian-Ramos-entrenamiento.jpg 1800w, https:\/\/elinformanteperu.com\/wp-content\/uploads\/2018\/05\/Christian-Ramos-entrenamiento-300x200.jpg 300w, https:\/\/elinformanteperu.com\/wp-content\/uploads\/2018\/05\/Christian-Ramos-entrenamiento-768x512.jpg 768w, https:\/\/elinformanteperu.com\/wp-content\/uploads\/2018\/05\/Christian-Ramos-entrenamiento-1024x683.jpg 1024w, https:\/\/elinformanteperu.com\/wp-content\/uploads\/2018\/05\/Christian-Ramos-entrenamiento-128x85.jpg 128w, https:\/\/elinformanteperu.com\/wp-content\/uploads\/2018\/05\/Christian-Ramos-entrenamiento-32x21.jpg 32w\" sizes=\"(max-width: 1800px) 100vw, 1800px\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Lima, 28 Setiembre 2020, (ANDINA).&#8211; El defensa de la selecci\u00f3n peruana, Christian Ramos destac\u00f3 que ve bien a la bicolor porque se ha ganado un nombre y un respeto, adem\u00e1s manifest\u00f3 que fue una buena decisi\u00f3n que las Eliminatorias se inicien en octubre. Ramos dej\u00f3 ver su emoci\u00f3n por volver a la escuadra nacional y [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":83150,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"rop_custom_images_group":[],"rop_custom_messages_group":[],"rop_publish_now":"initial","rop_publish_now_accounts":[],"rop_publish_now_history":[],"rop_publish_now_status":"pending","footnotes":""},"categories":[8],"tags":[138,137],"class_list":["post-83149","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-disciplinas-deportivas","tag-christian-ramos","tag-seleccion-peruana"],"_links":{"self":[{"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/posts\/83149","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/comments?post=83149"}],"version-history":[{"count":1,"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/posts\/83149\/revisions"}],"predecessor-version":[{"id":83151,"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/posts\/83149\/revisions\/83151"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/media\/83150"}],"wp:attachment":[{"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/media?parent=83149"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/categories?post=83149"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/tags?post=83149"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}