{"id":80822,"date":"2020-08-25T23:48:57","date_gmt":"2020-08-26T04:48:57","guid":{"rendered":"https:\/\/elinformanteperu.com\/?p=80822"},"modified":"2020-08-25T23:48:57","modified_gmt":"2020-08-26T04:48:57","slug":"devolucion-de-aportes-onp-aprobada-por-el-congreso-costaria-s-18000-millones","status":"publish","type":"post","link":"https:\/\/elinformanteperu.com\/index.php\/2020\/08\/25\/devolucion-de-aportes-onp-aprobada-por-el-congreso-costaria-s-18000-millones\/","title":{"rendered":"Devoluci\u00f3n de aportes ONP aprobada por el Congreso costar\u00eda S\/ 18,000 millones"},"content":{"rendered":"<p><strong><span style=\"color: #000000;\">Jorge Carrillo afirma que con ese monto se entregar\u00edan tres bonos universales a los peruanos vulnerables<\/span><\/strong><\/p>\n<p><span style=\"color: #000000;\"><strong>Lima, 25 Agosto, (ANDINA).-<\/strong> La medida aprobada por el Congreso para entregar hasta 1 UIT a los aportantes y exaportantes de la Oficina de Normalizaci\u00f3n Previsional (ONP) y una retribuci\u00f3n extraordinaria de una remuneraci\u00f3n m\u00ednima vital a los actuales pensionistas le costar\u00eda al Estado casi 18,000 millones de soles, se\u00f1al\u00f3 hoy el profesor de la Pac\u00edfico Business School Jorge Carrillo Acosta.<\/span><\/p>\n<p><span style=\"color: #000000;\">Explic\u00f3 que esta medida resulta perjudicial porque no resuelve los problemas de fondo que tiene el sistema de pensiones e incluso los agudiza porque mina los esfuerzos que se hacen por lograr una reforma integral, que aborde las distintas aristas del problema.<\/span><\/p>\n<p><span style=\"color: #000000;\">Carrillo Acosta tambi\u00e9n sostuvo que lo aprobado por el Parlamento compromete la disponibilidad de recursos necesarios para auxiliar a la poblaci\u00f3n m\u00e1s afectada por la pandemia, ya que no contempla mecanismos para seleccionar a los beneficiarios, de acuerdo con su nivel de vulnerabilidad.<\/span><\/p>\n<p><span style=\"color: #000000;\">\u201cA diferencia de lo declarado por la congresista Omonte, nosotros s\u00ed creemos que cualquier iniciativa aislada puede ir en contra de una soluci\u00f3n m\u00e1s integral porque, por ejemplo, con la aprobaci\u00f3n de esta disposici\u00f3n, no habr\u00e1 caja suficiente para plantear una pensi\u00f3n proporcional que solucione las inequidades que existen entre los aportantes de la ONP\u201d, dijo.<\/span><\/p>\n<p><span style=\"color: #000000;\">El experto consider\u00f3 que lo m\u00e1s probable es que la medida se declare inconstitucional.<\/span><\/p>\n<p><span style=\"color: #000000;\">\u201cEl Congreso, como es sabido, no tiene iniciativa de gasto, por lo tanto si el Ejecutivo presenta la demanda de inconstitucionalidad que ha anunciado lo m\u00e1s probable es que la gane, con lo cual se generar\u00e1 en la poblaci\u00f3n una falsa expectativa de recibir recursos adicionales\u201d, afirm\u00f3.<\/span><\/p>\n<p><span style=\"color: #000000;\">Por \u00faltimo, Carrillo Acosta resalt\u00f3 que el gasto que supondr\u00eda esta medida aprobada por el Congreso es casi el doble del presupuesto que hab\u00eda previsto entregar el Ejecutivo a la poblaci\u00f3n afectada por la pandemia, a trav\u00e9s de bonos.<\/span><\/p>\n<p><span style=\"color: #000000;\">\u201cCon ese dinero se podr\u00edan entregar tres bonos universales para las familias que lo necesiten\u201d, refiri\u00f3.<\/span><\/p>\n<p><span style=\"color: #000000;\">El ministro Walter Martos anunci\u00f3 que el paquete fiscal destinado a la atenci\u00f3n de la pandemia sumar\u00eda 128,000 millones de soles en total. De esa partida, 90,000 millones se utilizar\u00e1n en garant\u00edas y ahorro privado, 16,000 millones para alivio tributario y el monto destinado a la poblaci\u00f3n estar\u00eda en alrededor de 22,000 millones de soles.<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Jorge Carrillo afirma que con ese monto se entregar\u00edan tres bonos universales a los peruanos vulnerables Lima, 25 Agosto, (ANDINA).- La medida aprobada por el Congreso para entregar hasta 1 UIT a los aportantes y exaportantes de la Oficina de Normalizaci\u00f3n Previsional (ONP) y una retribuci\u00f3n extraordinaria de una remuneraci\u00f3n m\u00ednima vital a los actuales [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":38574,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"rop_custom_images_group":[],"rop_custom_messages_group":[],"rop_publish_now":"initial","rop_publish_now_accounts":[],"rop_publish_now_history":[],"rop_publish_now_status":"pending","footnotes":""},"categories":[10],"tags":[2131,2317,5243],"class_list":["post-80822","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualidad-municipal","tag-onp","tag-presidencia-del-consejo-de-ministros","tag-walter-martos"],"_links":{"self":[{"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/posts\/80822","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/comments?post=80822"}],"version-history":[{"count":1,"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/posts\/80822\/revisions"}],"predecessor-version":[{"id":80823,"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/posts\/80822\/revisions\/80823"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/media\/38574"}],"wp:attachment":[{"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/media?parent=80822"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/categories?post=80822"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/tags?post=80822"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}