{"id":80817,"date":"2020-08-25T23:41:40","date_gmt":"2020-08-26T04:41:40","guid":{"rendered":"https:\/\/elinformanteperu.com\/?p=80817"},"modified":"2020-08-25T23:41:40","modified_gmt":"2020-08-26T04:41:40","slug":"mazzetti-debemos-reconstruir-nuestro-sistema-de-salud-tras-la-pandemia","status":"publish","type":"post","link":"https:\/\/elinformanteperu.com\/index.php\/2020\/08\/25\/mazzetti-debemos-reconstruir-nuestro-sistema-de-salud-tras-la-pandemia\/","title":{"rendered":"Mazzetti: debemos reconstruir nuestro sistema de salud tras la pandemia"},"content":{"rendered":"<p><strong><span style=\"color: #000000;\">Resalta el uso de la modalidad de gobierno a gobierno por ser una herramienta eficiente y transparente<\/span><\/strong><\/p>\n<p><span style=\"color: #000000;\"><strong>Lima, 25 Agosto, (ANDINA).-<\/strong> Despu\u00e9s de la pandemia por el covid-19 nos toca reconstruir nuestro sistema de salud y para ello ser\u00e1n necesarias herramientas eficientes y transparentes, como la modalidad de gobierno a gobierno emprendida entre Per\u00fa y Francia, que permitan cerrar la infraestructura hospitalaria, afirm\u00f3 hoy la ministra de Salud, Pilar Mazzetti.<\/span><\/p>\n<p><span style=\"color: #000000;\">Destac\u00f3 que la modalidad de contrato de gobierno a gobierno le permitir\u00e1 al pa\u00eds recibir asistencia t\u00e9cnica en gesti\u00f3n y supervisi\u00f3n para la construcci\u00f3n de los hospitales Antonio Lorena (Cusco) y Sergio Bernales (Lima) en 17 y 34 meses, respectivamente.<\/span><\/p>\n<p><span style=\"color: #000000;\">La titular de Salud particip\u00f3 en el seminario web sobre los alcances generales de los acuerdos del contrato de gobierno a gobierno, organizado por la C\u00e1mara de Comercio de Lima (CCL) y la Embajada de Francia en el Per\u00fa.<\/span><\/p>\n<p><span style=\"color: #000000;\">\u201cEstamos partiendo en una aventura conjunta, la cual marcar\u00e1 un hito en lo que respecta a la infraestructura y organizaci\u00f3n en salud porque nos permitir\u00e1 ejecutar y tener listos hospitales de alta complejidad\u201d, precis\u00f3.<\/span><\/p>\n<p><strong><span style=\"color: #000000;\">Cerrando brechas de infraestructura hospitalaria<\/span><\/strong><\/p>\n<p><span style=\"color: #000000;\">El coordinador general del Programa Nacional de Inversiones en Salud (Pronis), Fredy Jord\u00e1n Medina, explic\u00f3 que el alcance de la asistencia t\u00e9cnica del Consorcio Franc\u00e9s Egis-APHP incluye la gesti\u00f3n de los proyectos, supervisi\u00f3n t\u00e9cnica de la construcci\u00f3n y transferencia de conocimientos para personal m\u00e9dico, t\u00e9cnico y administrativo de los hospitales.<\/span><\/p>\n<p><span style=\"color: #000000;\">\u201cEl Pronis pertenece al Minsa y tiene el enlace contractual con el consorcio franc\u00e9s. Tendr\u00e1 a cargo la administraci\u00f3n y supervisi\u00f3n de la ejecuci\u00f3n del contrato, garantizar\u00e1 que los plazos sean cumplidos y asegurar\u00e1 que participe activamente la Contralor\u00eda de la Rep\u00fablica para evitar actos de corrupci\u00f3n\u201d, se\u00f1al\u00f3.<\/span><\/p>\n<p><span style=\"color: #000000;\">Por su parte, los representantes del Consorcio Franc\u00e9s Egis-APHP indicaron que el pr\u00f3ximo mes estar\u00edan arribando al Per\u00fa con sus especialistas para iniciar los trabajos de campo necesarios en esta primera etapa del proyecto.<\/span><\/p>\n<p><span style=\"color: #000000;\">En el webinar participaron el embajador franc\u00e9s, Antoine Grassin, quien resalt\u00f3 la experiencia del consorcio franc\u00e9s en la construcci\u00f3n de hospitales; el gobernador regional del Cusco, Jean Paul Benavente; y representantes de la C\u00e1mara de Comercio de Lima, sector Salud, empresariado y p\u00fablico.<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Resalta el uso de la modalidad de gobierno a gobierno por ser una herramienta eficiente y transparente Lima, 25 Agosto, (ANDINA).- Despu\u00e9s de la pandemia por el covid-19 nos toca reconstruir nuestro sistema de salud y para ello ser\u00e1n necesarias herramientas eficientes y transparentes, como la modalidad de gobierno a gobierno emprendida entre Per\u00fa y [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":80818,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"rop_custom_images_group":[],"rop_custom_messages_group":[],"rop_publish_now":"initial","rop_publish_now_accounts":[],"rop_publish_now_history":[],"rop_publish_now_status":"pending","footnotes":""},"categories":[10],"tags":[1381,6068,5364,388,431,5400],"class_list":["post-80817","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualidad-municipal","tag-camara-de-comercio-de-lima","tag-coron","tag-covid-19","tag-ministerio-de-salud","tag-minsa","tag-pilar-mazzetti"],"_links":{"self":[{"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/posts\/80817","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/comments?post=80817"}],"version-history":[{"count":1,"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/posts\/80817\/revisions"}],"predecessor-version":[{"id":80819,"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/posts\/80817\/revisions\/80819"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/media\/80818"}],"wp:attachment":[{"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/media?parent=80817"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/categories?post=80817"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/tags?post=80817"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}