{"id":71426,"date":"2020-05-15T19:37:53","date_gmt":"2020-05-16T00:37:53","guid":{"rendered":"http:\/\/elinformanteperu.com\/?p=71426"},"modified":"2020-05-15T19:37:53","modified_gmt":"2020-05-16T00:37:53","slug":"prince-royce-vende-mascarillas-para-ayudar-a-ninos-en-pandemia","status":"publish","type":"post","link":"https:\/\/elinformanteperu.com\/index.php\/2020\/05\/15\/prince-royce-vende-mascarillas-para-ayudar-a-ninos-en-pandemia\/","title":{"rendered":"Prince Royce vende mascarillas para ayudar a ni\u00f1os en pandemia"},"content":{"rendered":"<p><strong><span style=\"color: #000000;\">El cantante Prince Royce lanz\u00f3 una iniciativa para ayudar a ni\u00f1os en el condado de El Bronx, donde creci\u00f3 en Nueva York, con la donaci\u00f3n de fondos de la venta de mascarillas.<\/span><\/strong><\/p>\n<p><span style=\"color: #000000;\"><strong>Nueva York, 15 Mayo 2020, (ANDINA).-<\/strong> El cantante Prince Royce lanz\u00f3 una iniciativa para ayudar a ni\u00f1os en el condado de El Bronx, donde creci\u00f3 en Nueva York, con la donaci\u00f3n de fondos de la venta de mascarillas impresas con una corona y el nombre de su \u00faltima gira, Alter Ego.<\/span><\/p>\n<p><span style=\"color: #000000;\">La totalidad de los fondos de la venta ser\u00e1n donados por el artista a la Fundaci\u00f3n Ni\u00f1o de la Caridad, organizaci\u00f3n sin \u00e1nimo de lucro dedicada a empoderar y mejorar la calidad de vida de los ni\u00f1os en El Bronx, condado de mayor\u00eda latina y con el mayor n\u00famero de casos per c\u00e1pita del coronavirus.<\/span><\/p>\n<p><span style=\"color: #000000;\">El p\u00fablico puede elegir entre tres modelos de mascarillas, negras y adornadas con una corona, y en una de ellas, que simula un pa\u00f1uelo, se lee \u00abPermanezca Seguro\u00bb y Alter Ego, el nombre de la gira de Prince Royce, que fue cancelada debido a la pandemia.<\/span><\/p>\n<p><span style=\"color: #000000;\">Las mascarillas se adquieren a trav\u00e9s de la p\u00e1gina del int\u00e9rprete de bachata por 15 d\u00f3lares.<\/span><\/p>\n<p><span style=\"color: #000000;\">\u00abAhora m\u00e1s que nunca, siento la necesidad de encontrar formas de ayudar a las familias y los ni\u00f1os en la ciudad donde fui criado. Estoy orgulloso de trabajar con una organizaci\u00f3n que aboga por un cambio positivo a trav\u00e9s de la educaci\u00f3n\u00bb, afirm\u00f3 el cantautor.<\/span><\/p>\n<p><iframe title=\"Prince Royce - El Amor Que Perdimos (Official Video)\" width=\"615\" height=\"346\" src=\"https:\/\/www.youtube.com\/embed\/OST41MmjdTQ?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/p>\n","protected":false},"excerpt":{"rendered":"<p>El cantante Prince Royce lanz\u00f3 una iniciativa para ayudar a ni\u00f1os en el condado de El Bronx, donde creci\u00f3 en Nueva York, con la donaci\u00f3n de fondos de la venta de mascarillas. Nueva York, 15 Mayo 2020, (ANDINA).- El cantante Prince Royce lanz\u00f3 una iniciativa para ayudar a ni\u00f1os en el condado de El Bronx, [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":71427,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"rop_custom_images_group":[],"rop_custom_messages_group":[],"rop_publish_now":"initial","rop_publish_now_accounts":[],"rop_publish_now_history":[],"rop_publish_now_status":"pending","footnotes":""},"categories":[69],"tags":[5236,5364,1246],"class_list":["post-71426","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-musica","tag-coronavirus","tag-covid-19","tag-prince-royce"],"_links":{"self":[{"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/posts\/71426","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/comments?post=71426"}],"version-history":[{"count":1,"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/posts\/71426\/revisions"}],"predecessor-version":[{"id":71428,"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/posts\/71426\/revisions\/71428"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/media\/71427"}],"wp:attachment":[{"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/media?parent=71426"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/categories?post=71426"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/tags?post=71426"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}