{"id":70002,"date":"2020-04-30T20:21:10","date_gmt":"2020-05-01T01:21:10","guid":{"rendered":"http:\/\/elinformanteperu.com\/?p=70002"},"modified":"2020-04-30T20:21:10","modified_gmt":"2020-05-01T01:21:10","slug":"lionsgate-live-llega-este-viernes-con-la-la-land-ciudad-de-suenos-gratis","status":"publish","type":"post","link":"https:\/\/elinformanteperu.com\/index.php\/2020\/04\/30\/lionsgate-live-llega-este-viernes-con-la-la-land-ciudad-de-suenos-gratis\/","title":{"rendered":"Lionsgate Live llega este viernes con &#8216;La La Land: ciudad de sue\u00f1os&#8217;, gratis"},"content":{"rendered":"<p><strong><span style=\"color: #000000;\">Se podr\u00e1 disfrutar de esta hermosa pel\u00edcula a trav\u00e9s del canal oficial de Lionsgate en Youtube, totalmente gratis.<\/span><\/strong><\/p>\n<p><span style=\"color: #000000;\"><strong>Lima, 30 Abril 2020, (El Informante Per\u00fa).-<\/strong> Lionsgate Live! Una Noche de Pel\u00edcula es una iniciativa del estudio Lionsgate para rendir un homenaje a la experiencia comunitaria de ver pel\u00edculas en cines, durante la transmisi\u00f3n los usuarios podr\u00e1n donar a Will Rogers Motion Picture Pioneers Foundation, que es una organizaci\u00f3n que est\u00e1 ayudando a los empleados de cines que se han visto afectados con la crisis del coronavirus.<\/span><\/p>\n<p><span style=\"color: #000000;\">\u201cNo hay nada que reemplace la magia de ver una pel\u00edcula junto con sus compa\u00f1eros espectadores en un cine en una pantalla grande, pero esta es una oportunidad para que Estados Unidos se una para recrear la experiencia\u201d, dijo Joe Drake, presidente de Lionsgate Motion Picture.\u00a0<\/span><\/p>\n<p><span style=\"color: #000000;\">John Fithian, presidente y director ejecutivo de la Asociaci\u00f3n Nacional de Propietarios de Cines, agreg\u00f3: \u201cA lo largo de los 125 a\u00f1os de historia del cine, esta es la primera vez que se cierran los cines en todo el pa\u00eds. Ya sea en la Depresi\u00f3n, las guerras, desastres o calamidades locales, las salas de cine siempre han sido un lugar de reuni\u00f3n. All\u00ed, el p\u00fablico puede juntarse a re\u00edr y conmoverse, reaccionar como uno solo, dejar atr\u00e1s sus problemas u olvidarse de su dura semana de trabajo. Simplemente perderse en las historias asombrosas en la pantalla grande. Hasta que podamos reunirnos nuevamente en los teatros, estamos agradecidos con Lionsgate por honrar la experiencia cinematogr\u00e1fica. Y estamos encantados de unirnos a ellos, no solo para ver un cl\u00e1sico gratis, sino para permitir que los fan\u00e1ticos y celebridades compartan sus propios recuerdos de las pel\u00edculas. Nos encanta que tanta gente hable sobre lo que hace que ir al cine sea tan \u00fanico y memorable \u201c.<\/span><\/p>\n<p><span style=\"color: #000000;\">La actriz que estar\u00e1 a cargo de presentar la pel\u00edcula es Jamie Lee Curtis, actriz que particip\u00f3 en la pel\u00edcula &#8216;Entre Navajas y Secretos&#8217; hace pocos meses.<\/span><\/p>\n<p><span style=\"color: #000000;\">En esta especial noche los usuarios tendr\u00e1n la oportunidad de interactuar en la transmisi\u00f3n en vivo, as\u00ed como tambi\u00e9n participar de trivias y desaf\u00edos con temas de pel\u00edculas<\/span><\/p>\n<p><span style=\"color: #000000;\">La transmisi\u00f3n en vivo de La La Land: Ciudad de Sue\u00f1os est\u00e1 prevista para este viernes primero de mayo a las 8 de la noche, hora Per\u00fa. <a href=\"https:\/\/www.youtube.com\/user\/LionsgateLIVE\"><strong>Acceder a canal oficial aqu\u00ed<\/strong><\/a>.<\/span><\/p>\n<p><iframe title=\"La La Land Ciudad de Sue\u00f1os- Trailer Oficial\" width=\"615\" height=\"346\" src=\"https:\/\/www.youtube.com\/embed\/Lcewx40qYV8?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Se podr\u00e1 disfrutar de esta hermosa pel\u00edcula a trav\u00e9s del canal oficial de Lionsgate en Youtube, totalmente gratis. Lima, 30 Abril 2020, (El Informante Per\u00fa).- Lionsgate Live! Una Noche de Pel\u00edcula es una iniciativa del estudio Lionsgate para rendir un homenaje a la experiencia comunitaria de ver pel\u00edculas en cines, durante la transmisi\u00f3n los usuarios [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":68628,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"rop_custom_images_group":[],"rop_custom_messages_group":[],"rop_publish_now":"initial","rop_publish_now_accounts":[],"rop_publish_now_history":[],"rop_publish_now_status":"pending","footnotes":""},"categories":[7],"tags":[1807,539,5560],"class_list":["post-70002","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-butaca","tag-bf-distribution","tag-la-la-land","tag-lionsgate"],"_links":{"self":[{"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/posts\/70002","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/comments?post=70002"}],"version-history":[{"count":1,"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/posts\/70002\/revisions"}],"predecessor-version":[{"id":70003,"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/posts\/70002\/revisions\/70003"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/media\/68628"}],"wp:attachment":[{"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/media?parent=70002"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/categories?post=70002"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/tags?post=70002"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}