{"id":69873,"date":"2020-04-29T19:50:11","date_gmt":"2020-04-30T00:50:11","guid":{"rendered":"http:\/\/elinformanteperu.com\/?p=69873"},"modified":"2020-04-29T20:49:04","modified_gmt":"2020-04-30T01:49:04","slug":"bus-de-la-seleccion-transporto-a-personal-medico-de-essalud-que-se-internara-en-la-villa-panamericana","status":"publish","type":"post","link":"https:\/\/elinformanteperu.com\/index.php\/2020\/04\/29\/bus-de-la-seleccion-transporto-a-personal-medico-de-essalud-que-se-internara-en-la-villa-panamericana\/","title":{"rendered":"Bus de la selecci\u00f3n transport\u00f3 a personal m\u00e9dico de EsSalud que se internar\u00e1 en la Villa Panamericana"},"content":{"rendered":"<p><strong><span style=\"color: #000000;\">FPF y Derco pusieron a disposici\u00f3n el Bus de la selecci\u00f3n como medio de transporte para el sector de salud durante el periodo de emergencia.<\/span><\/strong><\/p>\n<p><span style=\"color: #000000;\"><strong>Lima, 29 Abril 2020, (El Informante Per\u00fa).-<\/strong> Un equipo de m\u00e9dicos y personal asistencial de EsSalud, se reuni\u00f3 en la sede central de la instituci\u00f3n, ubicada en Jes\u00fas Mar\u00eda, para ser trasladados en el Bus de la selecci\u00f3n peruana a la Villa Panamericana, donde permanecer\u00e1n aislados por un mes y brindar\u00e1n atenci\u00f3n a pacientes con COVID-19.<\/span><\/p>\n<p><span style=\"color: #000000;\">Con gran vocaci\u00f3n y compromiso, el personal m\u00e9dico abord\u00f3 el Bus de la selecci\u00f3n, que fue puesto a disposici\u00f3n por la Federaci\u00f3n Peruana de F\u00fatbol y Derco durante todo el periodo de emergencia nacional, para poder iniciar sus labores y velar por la salud y bienestar de los ciudadanos.<\/span><\/p>\n<p><img fetchpriority=\"high\" decoding=\"async\" class=\"aligncenter size-full wp-image-69875\" src=\"http:\/\/elinformanteperu.com\/wp-content\/uploads\/2020\/04\/bus-seleccion-medicos1.jpg\" alt=\"\" width=\"763\" height=\"509\" srcset=\"https:\/\/elinformanteperu.com\/wp-content\/uploads\/2020\/04\/bus-seleccion-medicos1.jpg 763w, https:\/\/elinformanteperu.com\/wp-content\/uploads\/2020\/04\/bus-seleccion-medicos1-300x200.jpg 300w\" sizes=\"(max-width: 763px) 100vw, 763px\" \/><span style=\"color: #000000;\">Los 31 m\u00e9dicos, t\u00e9cnicos y enfermeras se suman a las m\u00e1s de 500 personas que actualmente est\u00e1n laborando en la Villa Panamericana, atendiendo a los pacientes con COVID-19.<\/span><\/p>\n<p><span style=\"color: #000000;\">Cabe se\u00f1alar que el personal de salud atender\u00e1 por 15 d\u00edas en jornadas de 12 horas en la Villa Panamericana, para luego realizar cuarentena por dos semanas. Ellos se realizar\u00e1n pruebas de descarte antes de poder regresar a sus domicilios por una semana y luego reincorporarse nuevamente en sus actividades.<\/span><\/p>\n<p><span style=\"color: #000000;\">La Federaci\u00f3n Peruana de F\u00fatbol y Derco Per\u00fa continuar\u00e1n apoyando con el Bus de la selecci\u00f3n a EsSalud, instituci\u00f3n peruana de seguridad social en salud a quien se le ha asignado el Bus de la selecci\u00f3n.<\/span><\/p>\n<p><img decoding=\"async\" class=\"aligncenter size-full wp-image-69876\" src=\"http:\/\/elinformanteperu.com\/wp-content\/uploads\/2020\/04\/bus-seleccion-medicos2.jpg\" alt=\"\" width=\"760\" height=\"504\" srcset=\"https:\/\/elinformanteperu.com\/wp-content\/uploads\/2020\/04\/bus-seleccion-medicos2.jpg 760w, https:\/\/elinformanteperu.com\/wp-content\/uploads\/2020\/04\/bus-seleccion-medicos2-300x199.jpg 300w\" sizes=\"(max-width: 760px) 100vw, 760px\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>FPF y Derco pusieron a disposici\u00f3n el Bus de la selecci\u00f3n como medio de transporte para el sector de salud durante el periodo de emergencia. Lima, 29 Abril 2020, (El Informante Per\u00fa).- Un equipo de m\u00e9dicos y personal asistencial de EsSalud, se reuni\u00f3 en la sede central de la instituci\u00f3n, ubicada en Jes\u00fas Mar\u00eda, para [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":69874,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"rop_custom_images_group":[],"rop_custom_messages_group":[],"rop_publish_now":"initial","rop_publish_now_accounts":[],"rop_publish_now_history":[],"rop_publish_now_status":"pending","footnotes":""},"categories":[10,8,20],"tags":[5554,451,204],"class_list":["post-69873","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualidad-municipal","category-disciplinas-deportivas","category-eventos","tag-derco","tag-essalud","tag-federacion-peruana-de-futbol"],"_links":{"self":[{"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/posts\/69873","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/comments?post=69873"}],"version-history":[{"count":1,"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/posts\/69873\/revisions"}],"predecessor-version":[{"id":69877,"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/posts\/69873\/revisions\/69877"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/media\/69874"}],"wp:attachment":[{"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/media?parent=69873"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/categories?post=69873"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/tags?post=69873"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}