{"id":69855,"date":"2020-04-29T17:07:48","date_gmt":"2020-04-29T22:07:48","guid":{"rendered":"http:\/\/elinformanteperu.com\/?p=69855"},"modified":"2020-04-29T17:07:48","modified_gmt":"2020-04-29T22:07:48","slug":"amen-raul-romero-maricarmen-marin-y-mas-de-50-artistas-se-unen-en-sentido-tema","status":"publish","type":"post","link":"https:\/\/elinformanteperu.com\/index.php\/2020\/04\/29\/amen-raul-romero-maricarmen-marin-y-mas-de-50-artistas-se-unen-en-sentido-tema\/","title":{"rendered":"Amen, Ra\u00fal Romero, Maricarmen Mar\u00edn y m\u00e1s de 50 artistas se unen en sentido tema"},"content":{"rendered":"<p><strong><span style=\"color: #000000;\">M\u00fasicos, cantantes, actores, modelos, deportistas, m\u00e9dicos y personajes de televisi\u00f3n, se unieron para crear el video de \u201cNo hay virus m\u00e1s fuerte que el amor\u201d.<\/span><\/strong><\/p>\n<p><span style=\"color: #000000;\"><strong>Lima, 29 Abril 2020, (ANDINA).-<\/strong> M\u00e1s de 50 personalidades, entre m\u00fasicos, cantantes, actores, modelos, deportistas, m\u00e9dicos y personajes de televisi\u00f3n, se unieron para crear el video de \u201cNo hay virus m\u00e1s fuerte que el amor\u201d.<\/span><\/p>\n<p><span style=\"color: #000000;\">Esta canci\u00f3n fue compuesta por Marcello Motta (Amen) y Gianina Picatoste (La Fulana), en medio de una cuarentena que ha paralizado todas las actividades en nuestro pa\u00eds debido a la pandemia del Coronavirus.<\/span><\/p>\n<p><span style=\"color: #000000;\">\u201cLa canci\u00f3n surgi\u00f3 por un sentimiento impulsado por lo que estamos viviendo. Escrib\u00ed la letra y Marcello hizo la m\u00fasica, y as\u00ed naci\u00f3, en nuestra casa y en medio de nuestro n\u00facleo familiar. Luego la compartimos en nuestras redes sociales y recibimos una buena respuesta del p\u00fablico. Sentimos que tiene un mensaje muy positivo en medio de tantas malas noticias, as\u00ed que llamamos a nuestros amigos artistas y armamos un video\u201d, comenta Gianina.<\/span><\/p>\n<p><span style=\"color: #000000;\">Al llamado de Picatoste y Motta acudieron estrellas como Alex y Chela Lora (El Tri de M\u00e9xico), Quique Neyra (exvocalista de Gondwana, de Chile), el argentino Luciano Napolitano (hijo del legendario guitarrista Pappo), Ra\u00fal Romero, Carlos \u00c1lvarez, Anna Carina Copello, Maricarmen Mar\u00edn, Deyvis Orosco, Jonathan Maicelo, Emilia Drago, Diego Lombardi, Maju Mantilla, Fiorella Flores, Thal\u00eda Estabridis, Tracy Freundt, Jimena Lindo, entre otros.<\/span><\/p>\n<p><span style=\"color: #000000;\">En el video, realizado por Jea Motta, tambi\u00e9n aparecen importantes figuras de la m\u00fasica peruana, como la formaci\u00f3n completa de Amen, Henry Ueunten, Natan Chara, Manuel Ch\u00e1vez \u201cel pulpo\u201d y \u201cMaluki\u201d Santa Cruz; Pocho Prieto y Cucho Galarza de Rio; Manolo Barrios y Toto Leverone de Mar de Copas; Jhovan Tomasevich de Zen, Luis Buckley de We The Lion, Pipe Villar\u00e1n, Ricardo Wiesse (La Mente), Pepe Gonzales (Aliados), Mariano Palacios (Laguna Pai), Nicole Pillman y Coqui de Tramontana.<\/span><\/p>\n<p><span style=\"color: #000000;\">\u201cLos m\u00fasicos y artistas fuimos de los primeros en dejar de trabajar y seremos de los \u00faltimos en volver, pero no hemos perdido la esperanza y no nos quedaremos sentados, as\u00ed como nadie debe hacerlo\u201d, comenta Marcello Motta, l\u00edder de Amen y coautor de la canci\u00f3n junto a Gianina Picatoste, quien adem\u00e1s de su esposa es la cantante de la banda La Fulana.<\/span><\/p>\n<p><span style=\"color: #000000;\">Salim Vera, To\u00f1o Jauregui, Manolo Hidalgo y Jeffry Fischman, integrantes originales de Libido, tambi\u00e9n son parte de este clip. Y aunque no grabaron juntos, resulta curioso verlos en un mismo video, algo que no pasaba desde hace 17 a\u00f1os. Julio Andrade, Marco Romero, Willy Terry, Carlos Ardiles, Ruth Karina, Mauricio Mesones, Pedro Loli, Koky Bonilla, Sandra Muente, Clara Yolks, Daniel Morales, Javier Arias, Jair Muro, \u00c1lvaro Canchari, tambi\u00e9n participan.<\/span><\/p>\n<p><span style=\"color: #000000;\">Otros personajes que tambi\u00e9n son parte del video de \u201cNo hay virus m\u00e1s fuerte que el amor\u201d, ya disponible en YouTube, son Ren\u00e1n D\u00edaz, Kike Tataje, Eduardo \u201cchino\u201d Toguchi, Sandro Ventura, Jes\u00fas Alzamora, Mar\u00eda Paz Gonz\u00e1les Vig\u00edl, Guillermo Casta\u00f1eda, Shantall Onetto, Christian Sotomayor, Alicia Retto, Jea Motta, Jos\u00e9 Vera, los doctores Ricardo Tamayo, Gustavo Rivara y Carolina Chang, y los ni\u00f1os Florencia, Lucas, Rafaella y Ninal\u00eda.<\/span><\/p>\n<p><iframe title=\"&quot;No Hay Virus M\u00e1s Fuerte Que El Amor&quot; - Marcello Motta feat. Gianina Picatoste (Y amigos)\" width=\"615\" height=\"346\" src=\"https:\/\/www.youtube.com\/embed\/7RZpVPAkUVs?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/p>\n","protected":false},"excerpt":{"rendered":"<p>M\u00fasicos, cantantes, actores, modelos, deportistas, m\u00e9dicos y personajes de televisi\u00f3n, se unieron para crear el video de \u201cNo hay virus m\u00e1s fuerte que el amor\u201d. Lima, 29 Abril 2020, (ANDINA).- M\u00e1s de 50 personalidades, entre m\u00fasicos, cantantes, actores, modelos, deportistas, m\u00e9dicos y personajes de televisi\u00f3n, se unieron para crear el video de \u201cNo hay virus [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":69856,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"rop_custom_images_group":[],"rop_custom_messages_group":[],"rop_publish_now":"initial","rop_publish_now_accounts":[],"rop_publish_now_history":[],"rop_publish_now_status":"pending","footnotes":""},"categories":[69],"tags":[5236,5364,81],"class_list":["post-69855","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-musica","tag-coronavirus","tag-covid-19","tag-peru"],"_links":{"self":[{"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/posts\/69855","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/comments?post=69855"}],"version-history":[{"count":1,"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/posts\/69855\/revisions"}],"predecessor-version":[{"id":69857,"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/posts\/69855\/revisions\/69857"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/media\/69856"}],"wp:attachment":[{"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/media?parent=69855"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/categories?post=69855"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/tags?post=69855"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}