{"id":64505,"date":"2020-02-06T23:43:50","date_gmt":"2020-02-07T04:43:50","guid":{"rendered":"http:\/\/elinformanteperu.com\/?p=64505"},"modified":"2020-02-06T23:43:50","modified_gmt":"2020-02-07T04:43:50","slug":"exponerte-al-sol-sin-proteccion-es-un-riesgo-para-desarrollar-cancer-de-piel","status":"publish","type":"post","link":"https:\/\/elinformanteperu.com\/index.php\/2020\/02\/06\/exponerte-al-sol-sin-proteccion-es-un-riesgo-para-desarrollar-cancer-de-piel\/","title":{"rendered":"Exponerte al sol sin protecci\u00f3n es un riesgo para desarrollar c\u00e1ncer de piel"},"content":{"rendered":"<p><span style=\"color: #000000;\"><strong>El 15% de casos de c\u00e1ncer de piel proviene de lesiones o lunares ya existentes. La sobreexposici\u00f3n solar, especialmente cuando se producen quemaduras visibles, podr\u00eda generar consecuencias negativas.<\/strong><\/span><\/p>\n<p><span style=\"color: #000000;\"><strong>Lima, 06 Febrero 2020, (El Informante Per\u00fa).-<\/strong> La sobreexposici\u00f3n solar, especialmente cuando se producen quemaduras visibles, podr\u00eda generar en el tiempo consecuencias negativas para nuestra salud, como es el caso de los lunares (lesiones pigmentadas) que podr\u00edan degenerar en c\u00e1ncer de piel, explic\u00f3 el doctor, Mauricio Le\u00f3n Rivera, director m\u00e9dico del Centro Detector del C\u00e1ncer y cirujano onc\u00f3logo de la Cl\u00ednica Ricardo Palma.<\/span><\/p>\n<p><span style=\"color: #000000;\">El especialista mencion\u00f3 que el 15% de casos de c\u00e1ncer de piel proviene de lesiones o lunares que degeneraron por la radiaci\u00f3n ultravioleta de sol (UV- B).<\/span><\/p>\n<p><span style=\"color: #000000;\">\u201cEn la actualidad los cuidados deben aumentar porque el \u201cagujero\u201d o densidad de la capa de ozono deja pasar cada vez m\u00e1s rayos ultravioletas al planeta, que son los responsables del aumento en la incidencia de c\u00e1ncer de piel en todo el mundo, sobretodo en pa\u00edses ecuatoriales como el Per\u00fa\u201d, a\u00f1adi\u00f3.<\/span><\/p>\n<p><span style=\"color: #000000;\">El diagn\u00f3stico del c\u00e1ncer de piel se basa en la b\u00fasqueda de signos sospechosos, los par\u00e1metros que utilizamos se resumen en la regla del A, B, C, D, E que son las iniciales de Asimetr\u00eda, Borde, Color, Di\u00e1metro y Evoluci\u00f3n. Si un lunar presenta bordes irregulares, es asim\u00e9trico, no tiene color homog\u00e9neo, mide m\u00e1s de 6 mm de tama\u00f1o o cambia en el tiempo, debemos descartar siempre un c\u00e1ncer acudiendo al especialista para su evaluaci\u00f3n.<\/span><\/p>\n<p><span style=\"color: #000000;\">El doctor Mauricio Le\u00f3n recomend\u00f3 usar ropa de algod\u00f3n holgada y si es de color oscuro mejor, sombreros de ala ancha, gafas de sol con protecci\u00f3n ultravioleta (UV), aplicaci\u00f3n de bloqueador con un m\u00ednimo Factor de Protecci\u00f3n Solar (FPS) de 35 aplic\u00e1ndolo media hora antes de la exposici\u00f3n al sol y renov\u00e1ndolo cada dos horas o luego del ba\u00f1o o de hacer ejercicio. Adem\u00e1s de evitar siempre la exposici\u00f3n solar en beb\u00e9s menores de un a\u00f1o.<\/span><\/p>\n<p><span style=\"color: #000000;\">Cabe mencionar, que el 6 de febrero se conmemora el D\u00eda del Lunar, efem\u00e9ride impulsada por el Ministerio de Salud (Minsa), con el prop\u00f3sito de brindar educaci\u00f3n sobre el c\u00e1ncer de piel y c\u00f3mo prevenirlo.<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>El 15% de casos de c\u00e1ncer de piel proviene de lesiones o lunares ya existentes. La sobreexposici\u00f3n solar, especialmente cuando se producen quemaduras visibles, podr\u00eda generar consecuencias negativas. Lima, 06 Febrero 2020, (El Informante Per\u00fa).- La sobreexposici\u00f3n solar, especialmente cuando se producen quemaduras visibles, podr\u00eda generar en el tiempo consecuencias negativas para nuestra salud, como [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":64506,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"rop_custom_images_group":[],"rop_custom_messages_group":[],"rop_publish_now":"initial","rop_publish_now_accounts":[],"rop_publish_now_history":[],"rop_publish_now_status":"pending","footnotes":""},"categories":[10,21],"tags":[395,394,431],"class_list":["post-64505","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualidad-municipal","category-orientacion","tag-clinica-ricardo-palma","tag-mauricio-leon-rivera","tag-minsa"],"_links":{"self":[{"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/posts\/64505","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/comments?post=64505"}],"version-history":[{"count":1,"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/posts\/64505\/revisions"}],"predecessor-version":[{"id":64507,"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/posts\/64505\/revisions\/64507"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/media\/64506"}],"wp:attachment":[{"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/media?parent=64505"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/categories?post=64505"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/tags?post=64505"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}