{"id":58463,"date":"2019-10-08T20:52:42","date_gmt":"2019-10-09T01:52:42","guid":{"rendered":"http:\/\/elinformanteperu.com\/?p=58463"},"modified":"2019-10-08T20:52:42","modified_gmt":"2019-10-09T01:52:42","slug":"u-cristal-las-entradas-ya-salieron-a-la-venta","status":"publish","type":"post","link":"https:\/\/elinformanteperu.com\/index.php\/2019\/10\/08\/u-cristal-las-entradas-ya-salieron-a-la-venta\/","title":{"rendered":"\u00abU\u00bb-Cristal: las entradas ya salieron a la venta"},"content":{"rendered":"<p><strong><span style=\"color: #000000;\">El partido entre Universitario y Sporting Cristal se juega el s\u00e1bado 12 de octubre, en el estadio Monumental de Ate, y la dirigencia \u00abcrema\u00bb ya puso a la venta las entradas.<\/span><\/strong><\/p>\n<p><span style=\"color: #000000;\"><strong>Lima, 08 Octubre 2019, (ANDINA).-<\/strong> El partido entre Universitario y Sporting Cristal se juega el s\u00e1bado 12 de octubre, en el estadio Monumental de Ate, y la dirigencia \u00abcrema\u00bb ya puso a la venta las entradas del cotejo m\u00e1s atractivo de la jornada 11 del Torneo Clausura de la Liga 1.<\/span><\/p>\n<p><span style=\"color: #000000;\">Las entradas se venden desde hoy a las 8:00 horas, a trav\u00e9s de la p\u00e1gina web: www.joinnus.com. El club crema inform\u00f3 que los asientos no ser\u00e1n numerados.<\/span><\/p>\n<p><span style=\"color: #000000;\">La tribuna sur, que es familiar, tendr\u00e1 el costo de S\/ 20 (2 adultos y 2 ni\u00f1os) y S\/ 15 (2 adultos y 1 ni\u00f1o), mientras que norte estar\u00e1 S\/ 20. Oriente tendr\u00e1 el costo de 45 soles y occidente 70 soles.<\/span><\/p>\n<p><span style=\"color: #000000;\">Vale recordar que a este duelo solo podr\u00e1n asistir los hinchas de Universitario.<\/span><\/p>\n<p><img fetchpriority=\"high\" decoding=\"async\" class=\"aligncenter size-full wp-image-58465\" src=\"http:\/\/elinformanteperu.com\/wp-content\/uploads\/2019\/10\/u-cristal-boleteria.jpg\" alt=\"\" width=\"481\" height=\"486\" srcset=\"https:\/\/elinformanteperu.com\/wp-content\/uploads\/2019\/10\/u-cristal-boleteria.jpg 481w, https:\/\/elinformanteperu.com\/wp-content\/uploads\/2019\/10\/u-cristal-boleteria-297x300.jpg 297w, https:\/\/elinformanteperu.com\/wp-content\/uploads\/2019\/10\/u-cristal-boleteria-128x128.jpg 128w, https:\/\/elinformanteperu.com\/wp-content\/uploads\/2019\/10\/u-cristal-boleteria-32x32.jpg 32w, https:\/\/elinformanteperu.com\/wp-content\/uploads\/2019\/10\/u-cristal-boleteria-60x60.jpg 60w, https:\/\/elinformanteperu.com\/wp-content\/uploads\/2019\/10\/u-cristal-boleteria-50x50.jpg 50w\" sizes=\"(max-width: 481px) 100vw, 481px\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>El partido entre Universitario y Sporting Cristal se juega el s\u00e1bado 12 de octubre, en el estadio Monumental de Ate, y la dirigencia \u00abcrema\u00bb ya puso a la venta las entradas. Lima, 08 Octubre 2019, (ANDINA).- El partido entre Universitario y Sporting Cristal se juega el s\u00e1bado 12 de octubre, en el estadio Monumental de [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":58464,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"rop_custom_images_group":[],"rop_custom_messages_group":[],"rop_publish_now":"initial","rop_publish_now_accounts":[],"rop_publish_now_history":[],"rop_publish_now_status":"pending","footnotes":""},"categories":[8],"tags":[4619,200,144],"class_list":["post-58463","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-disciplinas-deportivas","tag-clausura-2019","tag-sporting-cristal","tag-universitario-de-deportes"],"_links":{"self":[{"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/posts\/58463","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/comments?post=58463"}],"version-history":[{"count":1,"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/posts\/58463\/revisions"}],"predecessor-version":[{"id":58466,"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/posts\/58463\/revisions\/58466"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/media\/58464"}],"wp:attachment":[{"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/media?parent=58463"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/categories?post=58463"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/tags?post=58463"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}