{"id":58439,"date":"2019-10-08T01:04:27","date_gmt":"2019-10-08T06:04:27","guid":{"rendered":"http:\/\/elinformanteperu.com\/?p=58439"},"modified":"2019-10-08T01:04:27","modified_gmt":"2019-10-08T06:04:27","slug":"poder-judicial-rechaza-desacumular-delitos-contra-imputados-por-caso-metro-de-lima","status":"publish","type":"post","link":"https:\/\/elinformanteperu.com\/index.php\/2019\/10\/08\/poder-judicial-rechaza-desacumular-delitos-contra-imputados-por-caso-metro-de-lima\/","title":{"rendered":"Poder Judicial rechaza desacumular delitos contra imputados por caso Metro de Lima"},"content":{"rendered":"<p><strong><span style=\"color: #000000;\">La Primera Sala Penal rechaz\u00f3 el pedido del Ministerio P\u00fablico para desacumular imputaciones contra Jorge Cuba Hidalgo, J\u00e9ssica Tejada y otros investigados por el caso Metro de Lima.<\/span><\/strong><\/p>\n<p><span style=\"color: #000000;\"><strong>Lima, 07 Octubre 2019, (ANDINA).-<\/strong> La Primera Sala Penal de Apelaciones Nacional Especializada en Crimen Organizado rechaz\u00f3 el pedido del Ministerio P\u00fablico para desacumular imputaciones contra Jorge Cuba Hidalgo, J\u00e9ssica Tejada Guzm\u00e1n, Santiago Chau Novoa, Mariella Huerta Minaya y otros investigados por el caso Metro de Lima.<\/span><\/p>\n<p><span style=\"color: #000000;\">La medida se extiende en los extremos referidos a los terceros civilmente responsables Constructora Norberto Odebrecht S. A. (matriz Brasil), Constructora Norberto Odebrecht (matriz Per\u00fa) y Gra\u00f1a y Montero S.A.<\/span><\/p>\n<p><span style=\"color: #000000;\">En su resoluci\u00f3n la Sala precisa que la desacumulaci\u00f3n de imputaciones es excepcional, y tiene como postulados la simplificaci\u00f3n del proceso, de acuerdo con el art\u00edculo 51 del C\u00f3digo Procesal Penal.<\/span><\/p>\n<p><span style=\"color: #000000;\">En cambio, se\u00f1ala, la acumulaci\u00f3n resulta obligatoria en caso varias personas obren como autores o part\u00edcipes del mismo hecho punible debido a que se busca preservar la econom\u00eda y celeridad procesal a fin de evitar posibles fallos contradictorios.<\/span><\/p>\n<p><span style=\"color: #000000;\">De esta forma, la Sala declar\u00f3 infundado el requerimiento de desacumulaci\u00f3n de imputaciones formulado por el Ministerio P\u00fablico con motivo de la investigaci\u00f3n por la presunta comisi\u00f3n de los delitos de lavados de activos y otros en agravio del Estado en el caso Metro de Lima.<\/span><\/p>\n<p><span style=\"color: #000000;\">La Primera Sala Penal de Apelaciones Nacional Especializada en Crimen Organizado est\u00e1 conformada por los jueces Edita Condor\u00ed Fernandez, Sonia Torre Mu\u00f1oz y R\u00f3mulo Carcausto Calla.<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La Primera Sala Penal rechaz\u00f3 el pedido del Ministerio P\u00fablico para desacumular imputaciones contra Jorge Cuba Hidalgo, J\u00e9ssica Tejada y otros investigados por el caso Metro de Lima. Lima, 07 Octubre 2019, (ANDINA).- La Primera Sala Penal de Apelaciones Nacional Especializada en Crimen Organizado rechaz\u00f3 el pedido del Ministerio P\u00fablico para desacumular imputaciones contra Jorge [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":58440,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"rop_custom_images_group":[],"rop_custom_messages_group":[],"rop_publish_now":"initial","rop_publish_now_accounts":[],"rop_publish_now_history":[],"rop_publish_now_status":"pending","footnotes":""},"categories":[5],"tags":[1025,916,2587,163],"class_list":["post-58439","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualidad-informativa","tag-jessica-tejada","tag-jorge-cuba-hidalgo","tag-metro-de-lima","tag-poder-judicial"],"_links":{"self":[{"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/posts\/58439","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/comments?post=58439"}],"version-history":[{"count":1,"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/posts\/58439\/revisions"}],"predecessor-version":[{"id":58441,"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/posts\/58439\/revisions\/58441"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/media\/58440"}],"wp:attachment":[{"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/media?parent=58439"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/categories?post=58439"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/tags?post=58439"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}