{"id":58436,"date":"2019-10-08T01:00:07","date_gmt":"2019-10-08T06:00:07","guid":{"rendered":"http:\/\/elinformanteperu.com\/?p=58436"},"modified":"2019-10-08T01:11:37","modified_gmt":"2019-10-08T06:11:37","slug":"mas-de-24-millones-de-peruanos-votaran-en-elecciones-2020","status":"publish","type":"post","link":"https:\/\/elinformanteperu.com\/index.php\/2019\/10\/08\/mas-de-24-millones-de-peruanos-votaran-en-elecciones-2020\/","title":{"rendered":"M\u00e1s de 24 millones de peruanos votar\u00e1n en elecciones 2020"},"content":{"rendered":"<p><strong><span style=\"color: #000000;\">Un total de 24 millones 812,087 ciudadanos peruanos se encuentran h\u00e1biles para sufragar en las pr\u00f3ximas elecciones parlamentarias.<\/span><\/strong><\/p>\n<p><span style=\"color: #000000;\"><strong>Lima, 07 Octubre 2019, (ANDINA).-<\/strong> Un total de 24 millones 812,087 ciudadanos peruanos se encuentran h\u00e1biles para sufragar en las pr\u00f3ximas elecciones parlamentarias, de acuerdo a la Lista del Padr\u00f3n Inicial entregada hoy por el Registro Nacional de Identificaci\u00f3n y Estado Civil (Reniec) al Jurado Nacional de Elecciones (JNE).<\/span><\/p>\n<p><span style=\"color: #000000;\">De dicha cifra, 23 millones 839,839 residen en territorio nacional y 972,248 declararon vivir en el extranjero, indic\u00f3 Reniec.<\/span><\/p>\n<p><span style=\"color: #000000;\">El padr\u00f3n inicial tambi\u00e9n considera a los 166,755 j\u00f3venes que cumplen 18 a\u00f1os entre la fecha de cierre del padr\u00f3n (30 de setiembre de 2019) y el d\u00eda de las elecciones (26 de enero de 2020).<\/span><\/p>\n<p><span style=\"color: #000000;\">El n\u00famero de electores podr\u00eda cambiar, debido a que el padr\u00f3n inicial es una versi\u00f3n preliminar que debe ser depurada y fiscalizada \u2013por el Reniec y el JNE, respectivamente\u2013 antes de utilizarse como padr\u00f3n electoral.<\/span><\/p>\n<p><span style=\"color: #000000;\">Una de las formas de depurar el padr\u00f3n inicial pasa por permitir la veedur\u00eda ciudadana: ser\u00e1 publicado del lunes 14 al viernes 18 de octubre para que las personas puedan verificar si sus datos aparecen correctamente en las listas de un distrito y detectar a quienes no residen ah\u00ed o ya han fallecido.<\/span><\/p>\n<p><span style=\"color: #000000;\">Es posible comunicar al Reniec cualquier error detectado, generando una alerta, formulando un reclamo, una tacha o una solicitud de eliminaci\u00f3n, inform\u00f3 dicha instituci\u00f3n.<\/span><\/p>\n<p><span style=\"color: #000000;\">Para evitar inconvenientes, Reniec recomend\u00f3 mantener vigentes los documentos nacionales de Identidad (DNI) y recoger todos los solicitados.<\/span><\/p>\n<p><span style=\"color: #000000;\">Actualmente hay 711,405 DNI que no han sido recogidos de las agencias del organismo registral y el 30% de ellos han sido tramitados hace m\u00e1s de un a\u00f1o.<\/span><\/p>\n<p><span style=\"color: #000000;\">Asimismo, son 55,055 los DNI amarillos (entregados a los menores de 17 a\u00f1os) que no han sido cambiados por DNI azules (entregados a partir de los 17 a\u00f1os). El cambio se debe realizar al cumplir 17 a\u00f1os, pues el DNI azul es un requisito para inscribirse en el Registro Militar.<\/span><\/p>\n<p><iframe title=\"Reniec: Electores aumentan en 2% para elecciones congresales\" width=\"615\" height=\"346\" src=\"https:\/\/www.youtube.com\/embed\/jiLHyn5x9IQ?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Un total de 24 millones 812,087 ciudadanos peruanos se encuentran h\u00e1biles para sufragar en las pr\u00f3ximas elecciones parlamentarias. Lima, 07 Octubre 2019, (ANDINA).- Un total de 24 millones 812,087 ciudadanos peruanos se encuentran h\u00e1biles para sufragar en las pr\u00f3ximas elecciones parlamentarias, de acuerdo a la Lista del Padr\u00f3n Inicial entregada hoy por el Registro Nacional [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":58437,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"rop_custom_images_group":[],"rop_custom_messages_group":[],"rop_publish_now":"initial","rop_publish_now_accounts":[],"rop_publish_now_history":[],"rop_publish_now_status":"pending","footnotes":""},"categories":[5],"tags":[4898,184,185,150,146],"class_list":["post-58436","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualidad-informativa","tag-elecciones-parlamentarias-2020","tag-jne","tag-jurado-nacional-de-elecciones","tag-onpe","tag-reniec"],"_links":{"self":[{"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/posts\/58436","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/comments?post=58436"}],"version-history":[{"count":2,"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/posts\/58436\/revisions"}],"predecessor-version":[{"id":58448,"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/posts\/58436\/revisions\/58448"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/media\/58437"}],"wp:attachment":[{"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/media?parent=58436"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/categories?post=58436"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/tags?post=58436"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}