{"id":5832,"date":"2017-02-07T22:55:20","date_gmt":"2017-02-08T03:55:20","guid":{"rendered":"http:\/\/elinformanteperu.com\/?p=5832"},"modified":"2017-02-07T22:55:20","modified_gmt":"2017-02-08T03:55:20","slug":"roban-joyas-de-la-gala-de-los-premios-goya-en-espana","status":"publish","type":"post","link":"https:\/\/elinformanteperu.com\/index.php\/2017\/02\/07\/roban-joyas-de-la-gala-de-los-premios-goya-en-espana\/","title":{"rendered":"Roban joyas de la gala de los premios Goya en Espa\u00f1a"},"content":{"rendered":"<p><strong>La Academia de Cine de Espa\u00f1a denunci\u00f3 el robo de un conjunto de joyas valoradas en 30 mil euros del hotel donde el pasado s\u00e1bado se celebr\u00f3 la gala de los Goya.<\/strong><\/p>\n<p><strong>Madrid, 07 Febrero 2017, (PL).-<\/strong> La Academia de Cine de Espa\u00f1a denunci\u00f3 el robo de un conjunto de joyas valoradas en 30 mil euros del hotel donde el pasado s\u00e1bado se celebr\u00f3 la gala de los premios Goya, inform\u00f3 la polic\u00eda.<\/p>\n<p>Las alhajas sustra\u00eddas -cuatro pares de gemelos, una sortija y un juego de pendientes- son de una conocida marca que las puso a disposici\u00f3n de los participantes en la ceremonia anual de los Goya, considerados los Oscar del cine espa\u00f1ol.<\/p>\n<p>Seg\u00fan la Polic\u00eda Nacional, estos valiosos objetos fueron robados en una de las habitaciones del hotel Marriott Auditorium de Madrid, que fue reservada por los organizadores de la importante cita cinematogr\u00e1fica.<\/p>\n<p>Sin embargo, las joyas no se guardaron bajo especiales medidas de seguridad ni dentro de cajas fuertes, y el n\u00famero de personas que pasaron por el cuarto entre el s\u00e1bado y el lunes, momento en que se descubri\u00f3 su falta, fue &#8216;incontable&#8217;, indic\u00f3 la fuente.<\/p>\n<p>La denuncia recoge que los hechos ocurrieron entre las 10 de la noche del s\u00e1bado y las 10 de la ma\u00f1ana de ayer, cuando se detect\u00f3 el hurto.<\/p>\n<p>Los investigadores indagan si el robo se produjo durante la premiaci\u00f3n, que se extendi\u00f3 hasta la madrugada del domingo, o despu\u00e9s de la misma.<\/p>\n<p>Seguida por millones de espectadores por televisi\u00f3n, la principal fiesta del cine espa\u00f1ol consagr\u00f3 este a\u00f1o, en su 31 edici\u00f3n, el thriller Tarde para la ira, como mejor pel\u00edcula de 2016, y al drama fant\u00e1stico Un monstruo viene a verme, que se llev\u00f3 nueve estatuillas.<\/p>\n<p><img fetchpriority=\"high\" decoding=\"async\" class=\"size-full wp-image-5834 aligncenter\" src=\"http:\/\/elinformanteperu.com\/wp-content\/uploads\/2017\/02\/goya-2017-ganadores.jpeg\" alt=\"\" width=\"612\" height=\"340\" srcset=\"https:\/\/elinformanteperu.com\/wp-content\/uploads\/2017\/02\/goya-2017-ganadores.jpeg 612w, https:\/\/elinformanteperu.com\/wp-content\/uploads\/2017\/02\/goya-2017-ganadores-300x167.jpeg 300w, https:\/\/elinformanteperu.com\/wp-content\/uploads\/2017\/02\/goya-2017-ganadores-128x71.jpeg 128w, https:\/\/elinformanteperu.com\/wp-content\/uploads\/2017\/02\/goya-2017-ganadores-32x18.jpeg 32w\" sizes=\"(max-width: 612px) 100vw, 612px\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La Academia de Cine de Espa\u00f1a denunci\u00f3 el robo de un conjunto de joyas valoradas en 30 mil euros del hotel donde el pasado s\u00e1bado se celebr\u00f3 la gala de los Goya. Madrid, 07 Febrero 2017, (PL).- La Academia de Cine de Espa\u00f1a denunci\u00f3 el robo de un conjunto de joyas valoradas en 30 mil [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":5833,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"rop_custom_images_group":[],"rop_custom_messages_group":[],"rop_publish_now":"initial","rop_publish_now_accounts":[],"rop_publish_now_history":[],"rop_publish_now_status":"pending","footnotes":""},"categories":[7],"tags":[987],"class_list":["post-5832","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-butaca","tag-goya-2017"],"_links":{"self":[{"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/posts\/5832","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/comments?post=5832"}],"version-history":[{"count":1,"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/posts\/5832\/revisions"}],"predecessor-version":[{"id":5835,"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/posts\/5832\/revisions\/5835"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/media\/5833"}],"wp:attachment":[{"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/media?parent=5832"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/categories?post=5832"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/tags?post=5832"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}