{"id":5552,"date":"2017-02-04T12:28:53","date_gmt":"2017-02-04T17:28:53","guid":{"rendered":"http:\/\/elinformanteperu.com\/?p=5552"},"modified":"2017-02-04T12:28:53","modified_gmt":"2017-02-04T17:28:53","slug":"toledo-retornara-al-pais-cuando-sea-requerido-afirma-dirigente-de-pp","status":"publish","type":"post","link":"https:\/\/elinformanteperu.com\/index.php\/2017\/02\/04\/toledo-retornara-al-pais-cuando-sea-requerido-afirma-dirigente-de-pp\/","title":{"rendered":"Toledo retornar\u00e1 al pa\u00eds cuando sea requerido, afirma dirigente de PP"},"content":{"rendered":"<p><strong>El expresidente Alejandro Toledo no teme volver a Lima y retornar\u00e1 cuando sea requerido por el Congreso o las autoridades judiciales.<\/strong><\/p>\n<p><strong>Lima, 03 Febrero 2017, (ANDINA).-<\/strong> El expresidente Alejandro Toledo no teme volver a Lima y retornar\u00e1 cuando sea requerido por el Congreso o las autoridades judiciales que investigan el pago de coimas a exfuncionarios peruanos por la empresa Odebrecht, sostuvo el dirigente de Per\u00fa Posible (PP), Jos\u00e9 Le\u00f3n.<\/p>\n<p>En di\u00e1logo con la Agencia Andina, precis\u00f3 que Toledo se encuentra cumpliendo actividades acad\u00e9micas en el exterior, por ello, agreg\u00f3, no puede regresar al Per\u00fa en estos momentos, sin embargo, reiter\u00f3 la disposici\u00f3n del exgobernante de colaborar con la justicia.<\/p>\n<p>\u201cToledo va y viene, siempre lo hace, \u00e9l no tiene temor de volver, al contrario, tiene toda la disposici\u00f3n de colaborar con la justicia, lo ha dicho siempre. Adem\u00e1s, si es requerido por el Congreso o por las autoridades que ven el caso, \u00e9l volver\u00e1 sin ning\u00fan problema\u201d, expres\u00f3.<\/p>\n<p>La Fiscal\u00eda solicitar\u00e1 en los pr\u00f3ximos d\u00edas una orden de arresto contra el expresidente Alejandro Toledo por el caso Odebrecht, seg\u00fan un art\u00edculo publicado hoy por el diario The Economist.<\/p>\n<p>\u00abUn fiscal est\u00e1 a punto de emitir una orden de arresto contra Alejandro Toledo, un expresidente que compr\u00f3 varios costosos inmuebles despu\u00e9s de dejar el cargo\u00bb, dijo la revista inglesa en una nota titulada El esc\u00e1ndalo de Odebrecht trae esperanza de reforma.<\/p>\n<p>Jos\u00e9 Le\u00f3n record\u00f3 que el l\u00edder del Per\u00fa Posible acudi\u00f3 a la comisi\u00f3n parlamentaria presidida por Juan Pari, que investig\u00f3 estos hechos, y brind\u00f3 toda la informaci\u00f3n de manera clara y transparente.<\/p>\n<p>En esa l\u00ednea, pidi\u00f3 respeto a la investidura presidencial de Toledo y acabar con las especulaciones sobre un posible pedido de detenci\u00f3n contra Toledo. \u201cNo hay fundamentos para ello\u201d, dijo.<\/p>\n<p>Lament\u00f3 que detr\u00e1s de las investigaciones del caso Odebrecht exista un \u201caprovechamiento pol\u00edtico\u201d con el objetivo de enlodar la honra y la imagen de Toledo.<\/p>\n<p>En su opini\u00f3n, existe la intensi\u00f3n de vincular a Toledo en este caso de corrupci\u00f3n para desviar la atenci\u00f3n, en beneficio de los verdaderos responsables.<\/p>\n<p>En ese sentido, invoc\u00f3 al Ministerio P\u00fablico actuar con celeridad y seriedad en la identificaci\u00f3n de los funcionarios involucrados en este caso.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El expresidente Alejandro Toledo no teme volver a Lima y retornar\u00e1 cuando sea requerido por el Congreso o las autoridades judiciales. Lima, 03 Febrero 2017, (ANDINA).- El expresidente Alejandro Toledo no teme volver a Lima y retornar\u00e1 cuando sea requerido por el Congreso o las autoridades judiciales que investigan el pago de coimas a exfuncionarios [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":5553,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"rop_custom_images_group":[],"rop_custom_messages_group":[],"rop_publish_now":"initial","rop_publish_now_accounts":[],"rop_publish_now_history":[],"rop_publish_now_status":"pending","footnotes":""},"categories":[5],"tags":[208,1021,1022],"class_list":["post-5552","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualidad-informativa","tag-alejandro-toledo","tag-jose-leon","tag-peru-posible"],"_links":{"self":[{"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/posts\/5552","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/comments?post=5552"}],"version-history":[{"count":1,"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/posts\/5552\/revisions"}],"predecessor-version":[{"id":5554,"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/posts\/5552\/revisions\/5554"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/media\/5553"}],"wp:attachment":[{"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/media?parent=5552"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/categories?post=5552"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/tags?post=5552"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}