{"id":55506,"date":"2019-08-20T20:51:57","date_gmt":"2019-08-21T01:51:57","guid":{"rendered":"http:\/\/elinformanteperu.com\/?p=55506"},"modified":"2019-08-20T20:51:57","modified_gmt":"2019-08-21T01:51:57","slug":"que-hacer-con-el-stock-que-sobra-de-las-campanas-importantes","status":"publish","type":"post","link":"https:\/\/elinformanteperu.com\/index.php\/2019\/08\/20\/que-hacer-con-el-stock-que-sobra-de-las-campanas-importantes\/","title":{"rendered":"\u00bfQu\u00e9 hacer con el stock que sobra de las campa\u00f1as importantes?"},"content":{"rendered":"<p><strong><span style=\"color: #000000;\">Sabemos que en el a\u00f1o hay varias campa\u00f1as importantes. Estas se dan cuando los clientes est\u00e1n en la posibilidad y, a la vez, dispuestos de gastar un poco m\u00e1s.<\/span><\/strong><\/p>\n<p><span style=\"color: #000000;\"><strong>Lima, 20 Agosto 2019, (El Informante Per\u00fa).-<\/strong> Sabemos que en el a\u00f1o hay varias campa\u00f1as importantes, como verano, escolar, Fiestas Patrias, Navidad, etc. Estas se dan cuando los clientes est\u00e1n en la posibilidad y, a la vez, dispuestos de gastar un poco m\u00e1s porque tienen ingresos extras. Y, algunas veces, al afrontar estos momentos los comerciantes no tienen claro cu\u00e1nto m\u00e1s deben pedir en stock, con lo que algunas veces el c\u00e1lculo falla y se quedan con un poco de mercader\u00eda.<\/span><\/p>\n<p><span style=\"color: #000000;\">\u00bfQu\u00e9 podemos hacer, entonces, para evitar el stock sobrante o para sacarlo r\u00e1pidamente? Conversamos con Edgar, comerciante de confecciones de la galer\u00eda \u201cSudamericano\u201d del centro de Lima, quien afirma que \u201csiempre es necesario que est\u00e9s preparado para satisfacer y abastecer a tus clientes\u201d, es decir, contar con stock para soportar la demanda extra de los d\u00edas festivos. Sin embargo, para minimizar el riesgo del sobrante, le dijo al Consultorio Financiero de Mibanco su experiencia y extrajimos los siguientes consejos:<\/span><\/p>\n<p><span style=\"color: #000000;\">Aprende de a\u00f1os anteriores: es importante tener como base c\u00f3mo te fue en la temporada pasada. Es decir, al momento de pedir la mercanc\u00eda para la campa\u00f1a actual, recuerda cu\u00e1nto pediste y qu\u00e9 productos tuvieron mayor \u00e9xito. As\u00ed, el margen de stock sobrante ser\u00e1 menor.<\/span><\/p>\n<p><span style=\"color: #000000;\">Atento a las tendencias: es importante que conozcas qu\u00e9 productos o modelos est\u00e1n de moda y as\u00ed, le dar\u00e1s a los clientes lo que est\u00e1n buscando. Ten en cuenta que hoy en d\u00eda las tendencias cambian muy r\u00e1pido.<\/span><\/p>\n<p><span style=\"color: #000000;\">Visibiliza los productos: si tienes productos espec\u00edficos para esta campa\u00f1a o hay algunos que no est\u00e1n teniendo mucha acogida, col\u00f3calos en un lugar de la tienda donde los clientes puedan verlos y tocarlos. De esta manera, ser\u00e1 m\u00e1s f\u00e1cil su venta.<\/span><\/p>\n<p><span style=\"color: #000000;\">Haz ofertas: si te quedaste con algunos productos con menor rotaci\u00f3n, baja el precio, siempre teniendo en cuenta que debes ganar algo de dinero.<\/span><\/p>\n<p><span style=\"color: #000000;\">Edgar comenta que ha aprendido a calcular bien la cantidad que debe pedir en campa\u00f1a por la experiencia que tiene como comerciante. Menciona que es mejor hacer los pedidos con algunos meses de anticipaci\u00f3n, para aprovechar los precios fuera de temporada, e incluso empezar a tantear con la nueva mercader\u00eda exhibiendo alguna muestra en los puestos, para vigilar c\u00f3mo marcha la demanda.<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Sabemos que en el a\u00f1o hay varias campa\u00f1as importantes. Estas se dan cuando los clientes est\u00e1n en la posibilidad y, a la vez, dispuestos de gastar un poco m\u00e1s. Lima, 20 Agosto 2019, (El Informante Per\u00fa).- Sabemos que en el a\u00f1o hay varias campa\u00f1as importantes, como verano, escolar, Fiestas Patrias, Navidad, etc. Estas se dan [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":44029,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"rop_custom_images_group":[],"rop_custom_messages_group":[],"rop_publish_now":"initial","rop_publish_now_accounts":[],"rop_publish_now_history":[],"rop_publish_now_status":"pending","footnotes":""},"categories":[10,21],"tags":[1104,640],"class_list":["post-55506","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualidad-municipal","category-orientacion","tag-mi-banco","tag-mypes"],"_links":{"self":[{"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/posts\/55506","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/comments?post=55506"}],"version-history":[{"count":1,"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/posts\/55506\/revisions"}],"predecessor-version":[{"id":55507,"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/posts\/55506\/revisions\/55507"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/media\/44029"}],"wp:attachment":[{"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/media?parent=55506"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/categories?post=55506"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/tags?post=55506"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}