{"id":5540,"date":"2017-02-04T12:14:06","date_gmt":"2017-02-04T17:14:06","guid":{"rendered":"http:\/\/elinformanteperu.com\/?p=5540"},"modified":"2017-02-04T12:14:06","modified_gmt":"2017-02-04T17:14:06","slug":"festival-de-sundance-termina-comprometido-politicamente","status":"publish","type":"post","link":"https:\/\/elinformanteperu.com\/index.php\/2017\/02\/04\/festival-de-sundance-termina-comprometido-politicamente\/","title":{"rendered":"Festival de Sundance termina comprometido pol\u00edticamente"},"content":{"rendered":"<p><strong>Aunque dedicado a la estimulaci\u00f3n del cine independiente, el festival de Sundance acentu\u00f3 su compromiso pol\u00edtico con la selecci\u00f3n de 120 t\u00edtulos de 32 pa\u00edses,<\/strong><\/p>\n<p><strong>Los \u00c1ngeles, 03 Febrero 2017, (PL).-<\/strong> Aunque dedicado a la estimulaci\u00f3n del cine independiente, el festival de Sundance acentu\u00f3 su compromiso pol\u00edtico con la selecci\u00f3n de 120 t\u00edtulos de 32 pa\u00edses, destacan hoy medios especializados.<\/p>\n<p>Con una cartelera que termin\u00f3 realmente la v\u00edspera y la presentaci\u00f3n de varios de los metrajes galardonados, la cita cinematogr\u00e1fica cumpli\u00f3 su cometido al margen de los grandes estudios hollywoodenses, al tiempo que remarc\u00f3 su posici\u00f3n hacia determinados t\u00f3picos de inter\u00e9s p\u00fablico.<\/p>\n<p>Adem\u00e1s de su programa, la ceremonia de premiaciones ha sido remarcada como un hito de esta edici\u00f3n, en atenci\u00f3n a las referencias directas acerca del decreto antiinmigraci\u00f3n del presidente Donald Trump contra siete pa\u00edses de mayor\u00eda musulmana.<\/p>\n<p>Tras saludar a los artistas de esas y otras naciones en igual condici\u00f3n que asistieron este a\u00f1o a Sundance, la directora ejecutiva, Keri Putnam, expres\u00f3 que el cierre fronterizo a artistas for\u00e1neos frena el flujo de ideas e inspiraci\u00f3n, vital para la comunidad global.<\/p>\n<p>El Instituto Sundance emiti\u00f3 un comunicado en el cual se reitera su postura a favor del libre intercambio de ideas, as\u00ed como la solidaridad con artistas del mundo y con todas aquellas personas que buscan refugiarse de la violencia y la persecuci\u00f3n.<\/p>\n<p>La cita f\u00edlmica, que habitualmente ocupa las dos \u00faltimas semanas de enero, entreg\u00f3 el Gran Premio del Jurado a la comedia negra estadounidense I don&#8217;t Feel at Home in This World Anymore, de Macon Blair.<\/p>\n<p>En tanto, el premio del p\u00fablico al mejor drama internacional fue para Sue\u00f1o en otro idioma, del mexicano Ernesto Contreras, qui\u00e9n interpret\u00f3 el premio como un reconocimiento a la diversidad, la inclusi\u00f3n y la aceptaci\u00f3n.<\/p>\n<p><img fetchpriority=\"high\" decoding=\"async\" class=\"size-full wp-image-5542 aligncenter\" src=\"http:\/\/elinformanteperu.com\/wp-content\/uploads\/2017\/02\/festival-sundance1.jpg\" alt=\"\" width=\"800\" height=\"449\" srcset=\"https:\/\/elinformanteperu.com\/wp-content\/uploads\/2017\/02\/festival-sundance1.jpg 800w, https:\/\/elinformanteperu.com\/wp-content\/uploads\/2017\/02\/festival-sundance1-300x168.jpg 300w, https:\/\/elinformanteperu.com\/wp-content\/uploads\/2017\/02\/festival-sundance1-768x431.jpg 768w, https:\/\/elinformanteperu.com\/wp-content\/uploads\/2017\/02\/festival-sundance1-128x72.jpg 128w, https:\/\/elinformanteperu.com\/wp-content\/uploads\/2017\/02\/festival-sundance1-32x18.jpg 32w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Aunque dedicado a la estimulaci\u00f3n del cine independiente, el festival de Sundance acentu\u00f3 su compromiso pol\u00edtico con la selecci\u00f3n de 120 t\u00edtulos de 32 pa\u00edses, Los \u00c1ngeles, 03 Febrero 2017, (PL).- Aunque dedicado a la estimulaci\u00f3n del cine independiente, el festival de Sundance acentu\u00f3 su compromiso pol\u00edtico con la selecci\u00f3n de 120 t\u00edtulos de 32 [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":5541,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"rop_custom_images_group":[],"rop_custom_messages_group":[],"rop_publish_now":"initial","rop_publish_now_accounts":[],"rop_publish_now_history":[],"rop_publish_now_status":"pending","footnotes":""},"categories":[7],"tags":[937],"class_list":["post-5540","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-butaca","tag-sundance-film-festival-2017"],"_links":{"self":[{"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/posts\/5540","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/comments?post=5540"}],"version-history":[{"count":1,"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/posts\/5540\/revisions"}],"predecessor-version":[{"id":5543,"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/posts\/5540\/revisions\/5543"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/media\/5541"}],"wp:attachment":[{"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/media?parent=5540"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/categories?post=5540"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/tags?post=5540"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}