{"id":5534,"date":"2017-02-03T00:54:11","date_gmt":"2017-02-03T05:54:11","guid":{"rendered":"http:\/\/elinformanteperu.com\/?p=5534"},"modified":"2017-02-03T00:54:11","modified_gmt":"2017-02-03T05:54:11","slug":"ministro-tamayo-tenemos-el-compromiso-de-proteger-intereses-del-estado","status":"publish","type":"post","link":"https:\/\/elinformanteperu.com\/index.php\/2017\/02\/03\/ministro-tamayo-tenemos-el-compromiso-de-proteger-intereses-del-estado\/","title":{"rendered":"Ministro Tamayo: tenemos el compromiso de proteger intereses del Estado"},"content":{"rendered":"<p><strong>El ministro de Energ\u00eda y Minas, Gonzalo Tamayo Flores, dijo que tiene el compromiso de proteger y cautelar los intereses del Estado en el proyecto Gasoducto del Sur.<\/strong><\/p>\n<p><strong>Lima, 02 Febrero 2017, (ANDINA).-<\/strong> El ministro de Energ\u00eda y Minas, Gonzalo Tamayo Flores, dijo que tiene el compromiso de proteger y cautelar los intereses del Estado en el proyecto Gasoducto del Sur (GSP), y ante la cancelaci\u00f3n del mismo se cobr\u00f3 la carta fianza.<\/p>\n<p>\u201cMi compromiso como ministro es proteger y cautelar los intereses del Estado en este proyecto. Por eso ante cancelaci\u00f3n del mismo hemos concretado en solo tres d\u00edas el cobro de la carta fianza m\u00e1s grande de la historia del pa\u00eds, ascendente a 262.5 millones de d\u00f3lares\u201d, sostuvo durante su presentaci\u00f3n ante la comisi\u00f3n que investiga el caso Lava Jato en el Congreso de la Rep\u00fablica.<\/p>\n<p>Indic\u00f3 que la garant\u00eda de fiel cumplimiento original ascend\u00eda a 350 millones de d\u00f3lares y fue reducida por el Gobierno anterior, el 15 de julio del 2016, porque el contrato permit\u00eda al concesionario solicitar la reducci\u00f3n cada vez que se haya ejecutado avances del 25 % de las obras.<\/p>\n<p>\u201cSabemos que con la cancelaci\u00f3n de este contrato afectamos intereses econ\u00f3micos enormes. Nuestro Gobierno se mantendr\u00e1 firme en su posici\u00f3n de luchar contra la corrupci\u00f3n, no nos vamos a dejar amedrentar\u201d, se\u00f1al\u00f3 Tamayo en el Congreso.<\/p>\n<p>Como acci\u00f3n inmediata a la cancelaci\u00f3n del contrato, se promulg\u00f3 el Decreto de Urgencia 0001-2017, para preservar el valor de los bienes del GSP y se le encarga al Organismo Supervisor de la Inversi\u00f3n en Energ\u00eda y Minas (Osinergmin), la contrataci\u00f3n de un administrador de los bienes del proyecto del GSP hasta que sea transferido al sector privado a trav\u00e9s de una nueva licitaci\u00f3n.<\/p>\n<p>Ante este nuevo escenario, el Ministerio de Energ\u00eda y Minas (MEM) viene ejecutando medidas para garantizar la masificaci\u00f3n del gas natural en el sur del pa\u00eds, evaluando nuevas opciones que no perjudiquen al consumidor con cargos en su recibo de luz.<\/p>\n<p>\u201cHemos reorganizado Proinversi\u00f3n y le hemos encargado la constituci\u00f3n de un comit\u00e9 especial que llevar\u00e1 a cabo el nuevo proceso de licitaci\u00f3n del GSP de manera transparente y aut\u00f3noma\u201d, asever\u00f3 Tamayo en el Congreso, donde dio a conocer los antecedentes sobre la adjudicaci\u00f3n del proyecto GSP, la situaci\u00f3n actual, las acciones que el sector viene ejecutando y los avances para llevar gas al sur del pa\u00eds.<\/p>\n<p>En otro momento de su exposici\u00f3n, el titular del MEM precis\u00f3 que, como es p\u00fablico, cuenta con una experiencia profesional de 27 a\u00f1os en el campo de las consultor\u00edas independientes en temas de infraestructura y que ha trabajado en una empresa consultora con m\u00e1s de 30 a\u00f1os en el mercado que brinda servicios especializados a un amplio n\u00famero de clientes.<\/p>\n<p>\u201cNunca he prestado servicios para Enag\u00e1s; y como parte de mi trabajo he realizado estudios de mercado para Gra\u00f1a y Montero, pero ninguno relacionado al GSP. Hoy, mi compromiso como ministro, es garantizar que todos los proyectos Minero-Energ\u00e9ticos se ejecuten en el marco de la transparencia, pero sobretodo en beneficio de los peruanos y no de intereses privados\u201d, finaliz\u00f3.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El ministro de Energ\u00eda y Minas, Gonzalo Tamayo Flores, dijo que tiene el compromiso de proteger y cautelar los intereses del Estado en el proyecto Gasoducto del Sur. Lima, 02 Febrero 2017, (ANDINA).- El ministro de Energ\u00eda y Minas, Gonzalo Tamayo Flores, dijo que tiene el compromiso de proteger y cautelar los intereses del Estado [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":5535,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"rop_custom_images_group":[],"rop_custom_messages_group":[],"rop_publish_now":"initial","rop_publish_now_accounts":[],"rop_publish_now_history":[],"rop_publish_now_status":"pending","footnotes":""},"categories":[5],"tags":[801,321,823,322],"class_list":["post-5534","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualidad-informativa","tag-gasoducto-del-sur","tag-gonzalo-tamayo","tag-mem","tag-ministerio-de-energia-y-minas"],"_links":{"self":[{"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/posts\/5534","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/comments?post=5534"}],"version-history":[{"count":1,"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/posts\/5534\/revisions"}],"predecessor-version":[{"id":5536,"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/posts\/5534\/revisions\/5536"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/media\/5535"}],"wp:attachment":[{"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/media?parent=5534"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/categories?post=5534"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/tags?post=5534"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}