{"id":54441,"date":"2019-08-04T23:05:17","date_gmt":"2019-08-05T04:05:17","guid":{"rendered":"http:\/\/elinformanteperu.com\/?p=54441"},"modified":"2019-08-04T23:05:17","modified_gmt":"2019-08-05T04:05:17","slug":"lima-2019-lucca-mesinas-logro-otra-medalla-de-oro-para-peru-en-surf","status":"publish","type":"post","link":"https:\/\/elinformanteperu.com\/index.php\/2019\/08\/04\/lima-2019-lucca-mesinas-logro-otra-medalla-de-oro-para-peru-en-surf\/","title":{"rendered":"Lima 2019: Lucca Mesinas logr\u00f3 otra medalla de oro para Per\u00fa en surf"},"content":{"rendered":"<p><strong><span style=\"color: #000000;\">Lucca Mesinas fue otro de los atletas peruanos que se ba\u00f1\u00f3 de oro en los Juegos Panamericanos Lima 2019. El tablista nacional logr\u00f3 imponerse en la final del Surf Open.<\/span><\/strong><\/p>\n<p><span style=\"color: #000000;\"><strong>Lima, 04 Agosto 2019, (ANDINA).-<\/strong> Lucca Mesinas fue otro de los atletas peruanos que se ba\u00f1\u00f3 de oro en los Juegos Panamericanos Lima 2019. El tablista nacional logr\u00f3 imponerse en la final del Surf Open al argentino Leandro Usuna y puso a celebrar a todo el p\u00fablico que se dio cita en el Complejo Deportivo de Punta Rocas.<\/span><\/p>\n<p><span style=\"color: #000000;\">El peruano se coron\u00f3 como el mejor en su disciplina al conseguir un puntaje de 14.00, mientras que su rival solo alcanz\u00f3 un 13.77. El triunfo no solo le dio una medalla de oro, sino que adem\u00e1s consigui\u00f3 un cupo para los pr\u00f3ximos Juegos Ol\u00edmpicos Tokio 2020.<\/span><\/p>\n<p><span style=\"color: #000000;\">\u00abEstoy s\u00faper feliz de estar aqu\u00ed, es incre\u00edble tener a tanta gente apoy\u00e1ndome. Es un campeonato que va a a quedar para toda mi vida\u00bb, declar\u00f3 Lucca Mesinas completamente emocionado.<\/span><\/p>\n<p><span style=\"color: #000000;\">Se trata de la s\u00e9ptima medalla de oro para nuestro pa\u00eds en Lima 2019. En total, Per\u00fa suma 23 preseas en el medallero general y volvi\u00f3 a colocarse en la octava posici\u00f3n en la tabla.<\/span><\/p>\n<p><span style=\"color: #000000;\">En esta misma jornada, &#8216;Piccolo&#8217; Clemente y Daniella Rosas tambi\u00e9n consiguieron otras dos presas de oro en el deporte de las olas, mientras que Maria Fernanda Reyes, Tamil Martino y Vania Torres lograron en total tres medallas de plata.<\/span><\/p>\n<p><img fetchpriority=\"high\" decoding=\"async\" class=\"aligncenter size-full wp-image-51727\" src=\"http:\/\/elinformanteperu.com\/wp-content\/uploads\/2019\/06\/panamericanos-lima-2019-mu\u00f1eco.jpg\" alt=\"\" width=\"1800\" height=\"1200\" srcset=\"https:\/\/elinformanteperu.com\/wp-content\/uploads\/2019\/06\/panamericanos-lima-2019-mu\u00f1eco.jpg 1800w, https:\/\/elinformanteperu.com\/wp-content\/uploads\/2019\/06\/panamericanos-lima-2019-mu\u00f1eco-300x200.jpg 300w, https:\/\/elinformanteperu.com\/wp-content\/uploads\/2019\/06\/panamericanos-lima-2019-mu\u00f1eco-768x512.jpg 768w, https:\/\/elinformanteperu.com\/wp-content\/uploads\/2019\/06\/panamericanos-lima-2019-mu\u00f1eco-1024x683.jpg 1024w, https:\/\/elinformanteperu.com\/wp-content\/uploads\/2019\/06\/panamericanos-lima-2019-mu\u00f1eco-128x85.jpg 128w, https:\/\/elinformanteperu.com\/wp-content\/uploads\/2019\/06\/panamericanos-lima-2019-mu\u00f1eco-32x21.jpg 32w\" sizes=\"(max-width: 1800px) 100vw, 1800px\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Lucca Mesinas fue otro de los atletas peruanos que se ba\u00f1\u00f3 de oro en los Juegos Panamericanos Lima 2019. El tablista nacional logr\u00f3 imponerse en la final del Surf Open. Lima, 04 Agosto 2019, (ANDINA).- Lucca Mesinas fue otro de los atletas peruanos que se ba\u00f1\u00f3 de oro en los Juegos Panamericanos Lima 2019. El [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":54442,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"rop_custom_images_group":[],"rop_custom_messages_group":[],"rop_publish_now":"initial","rop_publish_now_accounts":[],"rop_publish_now_history":[],"rop_publish_now_status":"pending","footnotes":""},"categories":[8],"tags":[404,191,4718],"class_list":["post-54441","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-disciplinas-deportivas","tag-juegos-panamericanos-lima-2019","tag-lima-2019","tag-lucca-mesinas"],"_links":{"self":[{"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/posts\/54441","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/comments?post=54441"}],"version-history":[{"count":1,"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/posts\/54441\/revisions"}],"predecessor-version":[{"id":54443,"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/posts\/54441\/revisions\/54443"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/media\/54442"}],"wp:attachment":[{"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/media?parent=54441"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/categories?post=54441"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/tags?post=54441"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}