{"id":5036,"date":"2017-01-25T22:13:29","date_gmt":"2017-01-26T03:13:29","guid":{"rendered":"http:\/\/elinformanteperu.com\/?p=5036"},"modified":"2017-01-25T22:13:29","modified_gmt":"2017-01-26T03:13:29","slug":"resident-evil-capitulo-final-se-estrena-esta-semana","status":"publish","type":"post","link":"https:\/\/elinformanteperu.com\/index.php\/2017\/01\/25\/resident-evil-capitulo-final-se-estrena-esta-semana\/","title":{"rendered":"\u00abResident Evil: Cap\u00edtulo Final\u00bb se estrena esta semana"},"content":{"rendered":"<p><strong> Este jueves 26 llegar\u00e1 a nuestros cines la sexta y \u00faltima entrega de la serie de pel\u00edculas de terror y ciencia ficci\u00f3n, Resident Evil.<\/strong><\/p>\n<p><strong>Lima, 25 Enero 2017, (El Informante Per\u00fa).-<\/strong> Este 2017 llegar\u00e1 a nuestros cines la sexta y \u00faltima entrega de la serie de pel\u00edculas de terror y ciencia ficci\u00f3n, Resident Evil, luego de 15 a\u00f1os. \u201cResident Evil: Cap\u00edtulo Final\u201d vuelve a traer a Milla Jovovich en el papel que la llev\u00f3 a la fama. El estreno en nuestro pa\u00eds est\u00e1 programado para el jueves 26 de enero, cabe destacar que la pel\u00edcula reci\u00e9n se estrenar\u00e1 este viernes en Estados Unidos.<\/p>\n<p><img fetchpriority=\"high\" decoding=\"async\" class=\"size-full wp-image-5038 aligncenter\" src=\"http:\/\/elinformanteperu.com\/wp-content\/uploads\/2017\/01\/Resident-Evil1.jpg\" alt=\"\" width=\"1088\" height=\"725\" srcset=\"https:\/\/elinformanteperu.com\/wp-content\/uploads\/2017\/01\/Resident-Evil1.jpg 1088w, https:\/\/elinformanteperu.com\/wp-content\/uploads\/2017\/01\/Resident-Evil1-300x200.jpg 300w, https:\/\/elinformanteperu.com\/wp-content\/uploads\/2017\/01\/Resident-Evil1-768x512.jpg 768w, https:\/\/elinformanteperu.com\/wp-content\/uploads\/2017\/01\/Resident-Evil1-1024x682.jpg 1024w, https:\/\/elinformanteperu.com\/wp-content\/uploads\/2017\/01\/Resident-Evil1-128x85.jpg 128w, https:\/\/elinformanteperu.com\/wp-content\/uploads\/2017\/01\/Resident-Evil1-32x21.jpg 32w\" sizes=\"(max-width: 1088px) 100vw, 1088px\" \/><\/p>\n<p>Recogiendo inmediatamente despu\u00e9s de los acontecimientos de Resident Evil: Retribution, Alice (Milla Jovovich) es la \u00fanica sobreviviente de lo que estaba destinado a ser la \u00faltima resistencia de la humanidad contra los no-muertos. Ahora, ella tiene que volver a donde comenz\u00f3 toda la pesadilla: La Colmena en Raccoon City, donde la Corporaci\u00f3n Umbrella est\u00e1 reuniendo sus fuerzas para un ataque final contra los supervivientes que quedan del apocalipsis.<\/p>\n<p>\u201cResiden Evil: Cap\u00edtulo Final\u201d es dirigida por Paul W.S. Anderson y protagonizada de nuevo por Milla Jovovich, adem\u00e1s completan el reparto los actores Shawn Roberts, Ali Larter, Iain Glen, William Levy y Ruby Rose.<\/p>\n<p><img decoding=\"async\" class=\"size-full wp-image-5039 aligncenter\" src=\"http:\/\/elinformanteperu.com\/wp-content\/uploads\/2017\/01\/Resident-Evil2.jpg\" alt=\"\" width=\"734\" height=\"1088\" srcset=\"https:\/\/elinformanteperu.com\/wp-content\/uploads\/2017\/01\/Resident-Evil2.jpg 734w, https:\/\/elinformanteperu.com\/wp-content\/uploads\/2017\/01\/Resident-Evil2-202x300.jpg 202w, https:\/\/elinformanteperu.com\/wp-content\/uploads\/2017\/01\/Resident-Evil2-691x1024.jpg 691w, https:\/\/elinformanteperu.com\/wp-content\/uploads\/2017\/01\/Resident-Evil2-86x128.jpg 86w, https:\/\/elinformanteperu.com\/wp-content\/uploads\/2017\/01\/Resident-Evil2-22x32.jpg 22w\" sizes=\"(max-width: 734px) 100vw, 734px\" \/><\/p>\n<p><iframe src=\"https:\/\/www.youtube-nocookie.com\/embed\/i1bqf-9-eco?rel=0&amp;controls=0&amp;showinfo=0\" width=\"560\" height=\"315\" frameborder=\"0\" allowfullscreen=\"allowfullscreen\"><\/iframe><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Este jueves 26 llegar\u00e1 a nuestros cines la sexta y \u00faltima entrega de la serie de pel\u00edculas de terror y ciencia ficci\u00f3n, Resident Evil. Lima, 25 Enero 2017, (El Informante Per\u00fa).- Este 2017 llegar\u00e1 a nuestros cines la sexta y \u00faltima entrega de la serie de pel\u00edculas de terror y ciencia ficci\u00f3n, Resident Evil, luego [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":5037,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"rop_custom_images_group":[],"rop_custom_messages_group":[],"rop_publish_now":"initial","rop_publish_now_accounts":[],"rop_publish_now_history":[],"rop_publish_now_status":"pending","footnotes":""},"categories":[7],"tags":[947,946],"class_list":["post-5036","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-butaca","tag-milla-jovovich","tag-resident-evil-capitulo-final"],"_links":{"self":[{"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/posts\/5036","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/comments?post=5036"}],"version-history":[{"count":1,"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/posts\/5036\/revisions"}],"predecessor-version":[{"id":5040,"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/posts\/5036\/revisions\/5040"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/media\/5037"}],"wp:attachment":[{"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/media?parent=5036"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/categories?post=5036"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/tags?post=5036"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}