{"id":5006,"date":"2017-01-25T00:05:00","date_gmt":"2017-01-25T05:05:00","guid":{"rendered":"http:\/\/elinformanteperu.com\/?p=5006"},"modified":"2017-01-25T00:05:00","modified_gmt":"2017-01-25T05:05:00","slug":"publican-primera-imagen-de-benedict-cumberbatch-como-thomas-edison","status":"publish","type":"post","link":"https:\/\/elinformanteperu.com\/index.php\/2017\/01\/25\/publican-primera-imagen-de-benedict-cumberbatch-como-thomas-edison\/","title":{"rendered":"Publican primera imagen de Benedict Cumberbatch como Thomas Edison"},"content":{"rendered":"<p><strong>Las redes sociales exhiben la primera imagen oficial del actor brit\u00e1nico Benedict Cumberbatch durante el rodaje de The Current War.<\/strong><\/p>\n<p><strong>Los \u00c1ngeles, 24 Enero 2017, (PL).-<\/strong> Las redes sociales exhiben la primera imagen oficial del actor brit\u00e1nico Benedict Cumberbatch durante el rodaje de The Current War, una pel\u00edcula en la cual encarna al genio estadounidense Thomas Edison.<\/p>\n<p>El largometraje dirigido por Alfonso G\u00f3mez-Rej\u00f3n se enfoca en los \u00faltimos a\u00f1os de la d\u00e9cada de 1880, cuando se desarroll\u00f3 una rivalidad entre Edison y el ingeniero George Westinghouse en Estados Unidos por el prop\u00f3sito de construir un sistema de electricidad comercializable y sostenible.<\/p>\n<p>Michael Shannon interpretar\u00e1 a Westinghouse, mientras Nicholas Hoult ser\u00e1 el tambi\u00e9n famoso ingeniero Nikola Tesla, quien mantuvo con Edison una gran disputa tras haber trabajado juntos, porque defend\u00edan sistemas de corrientes distintos.<\/p>\n<p>Otros actores en el reparto son Katherine Waterston, Tom Holland, Matthew Macfadyen y Tuppence Middleton.<\/p>\n<p>No ser\u00e1 la primera vez que Cumberbatch interprete a un genio, pues en 2014 se meti\u00f3 en la piel del matem\u00e1tico y cient\u00edfico pionero de la computaci\u00f3n Alan Turing en la pel\u00edcula The Imitation Game y por este trabajo estuvo nominado a los Globos de Oro y al Oscar.<\/p>\n<p>Tampoco debe perderse de vista que el actor accedi\u00f3 a la fama gracias a su interpretaci\u00f3n del f\u00edsico te\u00f3rico, astrof\u00edsico, cosm\u00f3logo y divulgador cient\u00edfico brit\u00e1nico Stephen Hawking en la pel\u00edcula Hawking (2004).<\/p>\n<p><img fetchpriority=\"high\" decoding=\"async\" class=\"size-full wp-image-5008 aligncenter\" src=\"http:\/\/elinformanteperu.com\/wp-content\/uploads\/2017\/01\/Benedict-Cumberbatch1.jpg\" alt=\"\" width=\"620\" height=\"406\" srcset=\"https:\/\/elinformanteperu.com\/wp-content\/uploads\/2017\/01\/Benedict-Cumberbatch1.jpg 620w, https:\/\/elinformanteperu.com\/wp-content\/uploads\/2017\/01\/Benedict-Cumberbatch1-300x196.jpg 300w, https:\/\/elinformanteperu.com\/wp-content\/uploads\/2017\/01\/Benedict-Cumberbatch1-128x84.jpg 128w, https:\/\/elinformanteperu.com\/wp-content\/uploads\/2017\/01\/Benedict-Cumberbatch1-32x21.jpg 32w\" sizes=\"(max-width: 620px) 100vw, 620px\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Las redes sociales exhiben la primera imagen oficial del actor brit\u00e1nico Benedict Cumberbatch durante el rodaje de The Current War. Los \u00c1ngeles, 24 Enero 2017, (PL).- Las redes sociales exhiben la primera imagen oficial del actor brit\u00e1nico Benedict Cumberbatch durante el rodaje de The Current War, una pel\u00edcula en la cual encarna al genio estadounidense [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":5007,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"rop_custom_images_group":[],"rop_custom_messages_group":[],"rop_publish_now":"initial","rop_publish_now_accounts":[],"rop_publish_now_history":[],"rop_publish_now_status":"pending","footnotes":""},"categories":[7],"tags":[943,944],"class_list":["post-5006","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-butaca","tag-benedict-cumberbatch","tag-the-current-war"],"_links":{"self":[{"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/posts\/5006","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/comments?post=5006"}],"version-history":[{"count":1,"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/posts\/5006\/revisions"}],"predecessor-version":[{"id":5009,"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/posts\/5006\/revisions\/5009"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/media\/5007"}],"wp:attachment":[{"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/media?parent=5006"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/categories?post=5006"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/tags?post=5006"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}