{"id":4929,"date":"2017-01-23T23:19:00","date_gmt":"2017-01-24T04:19:00","guid":{"rendered":"http:\/\/elinformanteperu.com\/?p=4929"},"modified":"2017-01-23T23:19:00","modified_gmt":"2017-01-24T04:19:00","slug":"grupo-rio-lanza-tema-con-musica-de-televidente","status":"publish","type":"post","link":"https:\/\/elinformanteperu.com\/index.php\/2017\/01\/23\/grupo-rio-lanza-tema-con-musica-de-televidente\/","title":{"rendered":"Grupo R\u00edo lanza tema con m\u00fasica de \u00abTelevidente\u00bb"},"content":{"rendered":"<p><strong>El emblem\u00e1tico grupo \u00abR\u00edo\u00bb utiliz\u00f3 la m\u00fasica del tema \u00abTelevidente\u00bb para lanzar una nueva versi\u00f3n con una letra inspirada en los emprendedores titulada \u00abIndependiente\u00bb.<\/strong><\/p>\n<p><strong>Lima, 23 Enero 2017, (ANDINA).-<\/strong> El emblem\u00e1tico grupo \u00abR\u00edo\u00bb utiliz\u00f3 la m\u00fasica del tema \u00abTelevidente\u00bb para lanzar una nueva versi\u00f3n con una letra inspirada en los emprendedores titulada \u00abIndependiente\u00bb.<\/p>\n<p>As\u00ed en su cuenta oficial, la agrupaci\u00f3n comparti\u00f3 el videoclip donde destacan escenas de la vida laboral de un independiente.<\/p>\n<p>El grupo presenta este trabajo diciendo \u00abAs\u00ed comenzamos el 2017 con buena vibra\u00bb.<\/p>\n<p>El video, trabajado en formato digital, nos muestra a Chachi, Pocho y Cucho acerc\u00e1ndose a una rockola para programar justamente su tema que le cantaba a quienes en los 80 pasaban horas frente a la pantalla chica.<\/p>\n<p>Sin embargo, lejos de aparecer su popular canci\u00f3n aparece esta nueva.<\/p>\n<p>Mira y escucha aqu\u00ed su nuevo tema \u00abIndependiente\u00bb.<\/p>\n<p><iframe src=\"https:\/\/www.youtube-nocookie.com\/embed\/BwHKz8Tne9Y?rel=0&amp;controls=0&amp;showinfo=0\" width=\"560\" height=\"315\" frameborder=\"0\" allowfullscreen=\"allowfullscreen\"><\/iframe><\/p>\n<p>Y esta fue la canci\u00f3n que la inspir\u00f3.<\/p>\n<p><iframe src=\"https:\/\/www.youtube-nocookie.com\/embed\/kVIGKfACJsI?rel=0&amp;controls=0&amp;showinfo=0\" width=\"560\" height=\"315\" frameborder=\"0\" allowfullscreen=\"allowfullscreen\"><\/iframe><\/p>\n","protected":false},"excerpt":{"rendered":"<p>El emblem\u00e1tico grupo \u00abR\u00edo\u00bb utiliz\u00f3 la m\u00fasica del tema \u00abTelevidente\u00bb para lanzar una nueva versi\u00f3n con una letra inspirada en los emprendedores titulada \u00abIndependiente\u00bb. Lima, 23 Enero 2017, (ANDINA).- El emblem\u00e1tico grupo \u00abR\u00edo\u00bb utiliz\u00f3 la m\u00fasica del tema \u00abTelevidente\u00bb para lanzar una nueva versi\u00f3n con una letra inspirada en los emprendedores titulada \u00abIndependiente\u00bb. As\u00ed en [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":4930,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"rop_custom_images_group":[],"rop_custom_messages_group":[],"rop_publish_now":"initial","rop_publish_now_accounts":[],"rop_publish_now_history":[],"rop_publish_now_status":"pending","footnotes":""},"categories":[69],"tags":[929],"class_list":["post-4929","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-musica","tag-grupo-rio"],"_links":{"self":[{"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/posts\/4929","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/comments?post=4929"}],"version-history":[{"count":1,"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/posts\/4929\/revisions"}],"predecessor-version":[{"id":4931,"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/posts\/4929\/revisions\/4931"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/media\/4930"}],"wp:attachment":[{"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/media?parent=4929"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/categories?post=4929"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/tags?post=4929"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}