{"id":44947,"date":"2019-03-01T23:19:23","date_gmt":"2019-03-02T04:19:23","guid":{"rendered":"http:\/\/elinformanteperu.com\/?p=44947"},"modified":"2019-03-01T23:19:23","modified_gmt":"2019-03-02T04:19:23","slug":"conmebol-rechaza-propuesta-de-us-soccer-de-una-copa-continental-en-2020","status":"publish","type":"post","link":"https:\/\/elinformanteperu.com\/index.php\/2019\/03\/01\/conmebol-rechaza-propuesta-de-us-soccer-de-una-copa-continental-en-2020\/","title":{"rendered":"Conmebol rechaza propuesta de US Soccer de una copa continental en 2020"},"content":{"rendered":"<p><strong><span style=\"color: #000000;\">La Conmebol rechaz\u00f3 la propuesta de la US Soccer de celebrar en ese pa\u00eds un torneo continental de selecciones en 2020 al advertir que se superpone con la Copa Am\u00e9rica del pr\u00f3ximo a\u00f1o.<\/span><\/strong><\/p>\n<p><span style=\"color: #000000;\"><strong>Asunci\u00f3n, 01 de Marzo 2019, (ANDINA).-<\/strong> La Conmebol rechaz\u00f3 la propuesta de la US Soccer de celebrar en ese pa\u00eds un torneo continental de selecciones en 2020 al advertir que se superpone con la Copa Am\u00e9rica del pr\u00f3ximo a\u00f1o y carece de la aprobaci\u00f3n de la FIFA, dijo el presidente de la entidad, Alejandro Dom\u00ednguez, en una carta a la Federaci\u00f3n estadounidense.<\/span><\/p>\n<p><span style=\"color: #000000;\">\u00abLa no existencia de aprobaci\u00f3n y calendarizaci\u00f3n por parte de la FIFA de una Continental Cup-2020 Edition, condici\u00f3n sine qua non para que la misma se pueda llevar a cabo (&#8230;) resulta imposible a la Conmebol y sus Asociaciones Miembro aceptar su invitaci\u00f3n\u00bb, advirti\u00f3 Dom\u00ednguez en la carta dirigida a Carlos Cordeiro, presidente de la US Soccer, y a la que tuvo acceso la AFP.<\/span><\/p>\n<p><span style=\"color: #000000;\">Seg\u00fan el New York Times, la US Soccer propuso a la Conmebol la realizaci\u00f3n en 2020 de una copa continental con 16 selecciones, 10 de la Conmebol y seis de la Concacaf, un torneo similar a la Copa Am\u00e9rica Centenario que se disput\u00f3 en Estados Unidos en 2016 para conmemorar los 100 a\u00f1os de la Confederaci\u00f3n Sudamericana.<\/span><\/p>\n<p><img fetchpriority=\"high\" decoding=\"async\" class=\"aligncenter size-full wp-image-17918\" src=\"http:\/\/elinformanteperu.com\/wp-content\/uploads\/2017\/11\/FIFA-LOCAL.jpg\" alt=\"\" width=\"1800\" height=\"1198\" srcset=\"https:\/\/elinformanteperu.com\/wp-content\/uploads\/2017\/11\/FIFA-LOCAL.jpg 1800w, https:\/\/elinformanteperu.com\/wp-content\/uploads\/2017\/11\/FIFA-LOCAL-300x200.jpg 300w, https:\/\/elinformanteperu.com\/wp-content\/uploads\/2017\/11\/FIFA-LOCAL-768x511.jpg 768w, https:\/\/elinformanteperu.com\/wp-content\/uploads\/2017\/11\/FIFA-LOCAL-1024x682.jpg 1024w, https:\/\/elinformanteperu.com\/wp-content\/uploads\/2017\/11\/FIFA-LOCAL-128x85.jpg 128w, https:\/\/elinformanteperu.com\/wp-content\/uploads\/2017\/11\/FIFA-LOCAL-32x21.jpg 32w\" sizes=\"(max-width: 1800px) 100vw, 1800px\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La Conmebol rechaz\u00f3 la propuesta de la US Soccer de celebrar en ese pa\u00eds un torneo continental de selecciones en 2020 al advertir que se superpone con la Copa Am\u00e9rica del pr\u00f3ximo a\u00f1o. Asunci\u00f3n, 01 de Marzo 2019, (ANDINA).- La Conmebol rechaz\u00f3 la propuesta de la US Soccer de celebrar en ese pa\u00eds un torneo [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":44949,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"rop_custom_images_group":[],"rop_custom_messages_group":[],"rop_publish_now":"initial","rop_publish_now_accounts":[],"rop_publish_now_history":[],"rop_publish_now_status":"pending","footnotes":""},"categories":[8],"tags":[2694,268],"class_list":["post-44947","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-disciplinas-deportivas","tag-conmebol","tag-fifa"],"_links":{"self":[{"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/posts\/44947","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/comments?post=44947"}],"version-history":[{"count":1,"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/posts\/44947\/revisions"}],"predecessor-version":[{"id":44950,"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/posts\/44947\/revisions\/44950"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/media\/44949"}],"wp:attachment":[{"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/media?parent=44947"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/categories?post=44947"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/tags?post=44947"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}