{"id":34863,"date":"2018-10-14T21:23:54","date_gmt":"2018-10-15T02:23:54","guid":{"rendered":"http:\/\/elinformanteperu.com\/?p=34863"},"modified":"2018-10-14T21:23:54","modified_gmt":"2018-10-15T02:23:54","slug":"gareca-era-necesario-salir-rapido-de-dos-derrotas-seguidas","status":"publish","type":"post","link":"https:\/\/elinformanteperu.com\/index.php\/2018\/10\/14\/gareca-era-necesario-salir-rapido-de-dos-derrotas-seguidas\/","title":{"rendered":"Gareca: era necesario salir r\u00e1pido de dos derrotas seguidas"},"content":{"rendered":"<p><strong><span style=\"color: #000000;\">El entrenador, Ricardo Gareca, afirm\u00f3 que era necesario salir r\u00e1pido de dos derrotas seguidas, al comentar la alegr\u00eda que le produjo el 3 &#8211; 0 ante Chile.<\/span><\/strong><\/p>\n<p><span style=\"color: #000000;\"><strong>Miami, 12 de Octubre 2018, (ANDINA).-<\/strong> El entrenador de la selecci\u00f3n peruana, Ricardo Gareca, afirm\u00f3 que era necesario salir r\u00e1pido de dos derrotas seguidas, al comentar la alegr\u00eda que le produjo el buen trabajo de los jugadores en la goleada de 3 &#8211; 0 ante Chile.<\/span><\/p>\n<p><span style=\"color: #000000;\">En conferencia de prensa, precis\u00f3 que el encuentro fue muy disputado, digno de un partido cl\u00e1sico \u00abque se viven intensamente\u00bb, ante una selecci\u00f3n sure\u00f1a que complic\u00f3 en varios momentos.<\/span><\/p>\n<p><span style=\"color: #000000;\">\u00abSiento que es necesario recuperarse despu\u00e9s de dos derrotas, es importante salir r\u00e1pido de ellas, el equipo hoy jug\u00f3 un partido importante y le damos la importancia que se merece y lograr una victoria luego de dos ca\u00eddas es importante para todos\u00bb, afirm\u00f3.<\/span><\/p>\n<p><span style=\"color: #000000;\">Asimismo, precis\u00f3 que ante Holanda y Alemania la selecci\u00f3n se adelant\u00f3 en el marcador, pero no pudo sostener el partido, algo que se corrigi\u00f3 en la victoria ante Chile.<\/span><\/p>\n<p><span style=\"color: #000000;\">Sobre el encuentro, Gareca refiri\u00f3 que \u00abno fue chato\u00bb para Per\u00fa porque enfrentaron a una selecci\u00f3n chilena que es muy fuerte, pero que se capitalizaron todas las oportunidades de gol.<\/span><\/p>\n<p><span style=\"color: #000000;\">\u00abAhora, lo que nos queda es recuperarnos porque se viene un partido importante ante Estados Unidos\u00bb, manifest\u00f3.<\/span><\/p>\n<p><strong><span style=\"color: #000000;\">Hinchada<\/span><\/strong><\/p>\n<p><span style=\"color: #000000;\">En otro momento, destac\u00f3 la hinchada peruana que estuvo presente en el Hard Rock Stadium de Miami y que, incluso sac\u00f3 lustre de su premio como la mejor por la FIFA, respetando la entonaci\u00f3n del himno chileno.<\/span><\/p>\n<p><span style=\"color: #000000;\">\u00abRecibir este premio despu\u00e9s de un Mundial no es poca cosa, la alegr\u00eda que le ponen al partido es muy bueno, quiero felicitar a la gente por el respeto al himno chileno, hay que destacarlo, nos gratifica en ese aspecto\u00bb, sostuvo.<\/span><\/p>\n<p><span style=\"color: #000000;\">En ese sentido, explic\u00f3 que la victoria fue para todos los hinchas peruanos, que, en todos los lugares que viajan, fuera y dentro del pa\u00eds, siempre \u00abson una multitud\u00bb.<\/span><\/p>\n<p><span style=\"color: #000000;\">\u00abLa selecci\u00f3n siempre busca darle todo a ellos, si ellos son felices, nosotros estamos m\u00e1s contentos\u00bb, a\u00f1adi\u00f3.<\/span><\/p>\n<p><img fetchpriority=\"high\" decoding=\"async\" class=\"aligncenter size-full wp-image-29486\" src=\"http:\/\/elinformanteperu.com\/wp-content\/uploads\/2018\/06\/gareca3.jpg\" alt=\"\" width=\"1800\" height=\"1168\" srcset=\"https:\/\/elinformanteperu.com\/wp-content\/uploads\/2018\/06\/gareca3.jpg 1800w, https:\/\/elinformanteperu.com\/wp-content\/uploads\/2018\/06\/gareca3-300x195.jpg 300w, https:\/\/elinformanteperu.com\/wp-content\/uploads\/2018\/06\/gareca3-768x498.jpg 768w, https:\/\/elinformanteperu.com\/wp-content\/uploads\/2018\/06\/gareca3-1024x664.jpg 1024w, https:\/\/elinformanteperu.com\/wp-content\/uploads\/2018\/06\/gareca3-128x83.jpg 128w, https:\/\/elinformanteperu.com\/wp-content\/uploads\/2018\/06\/gareca3-32x21.jpg 32w\" sizes=\"(max-width: 1800px) 100vw, 1800px\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>El entrenador, Ricardo Gareca, afirm\u00f3 que era necesario salir r\u00e1pido de dos derrotas seguidas, al comentar la alegr\u00eda que le produjo el 3 &#8211; 0 ante Chile. Miami, 12 de Octubre 2018, (ANDINA).- El entrenador de la selecci\u00f3n peruana, Ricardo Gareca, afirm\u00f3 que era necesario salir r\u00e1pido de dos derrotas seguidas, al comentar la alegr\u00eda [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":34865,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"rop_custom_images_group":[],"rop_custom_messages_group":[],"rop_publish_now":"initial","rop_publish_now_accounts":[],"rop_publish_now_history":[],"rop_publish_now_status":"pending","footnotes":""},"categories":[8],"tags":[173,92,137],"class_list":["post-34863","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-disciplinas-deportivas","tag-chile","tag-ricardo-gareca","tag-seleccion-peruana"],"_links":{"self":[{"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/posts\/34863","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/comments?post=34863"}],"version-history":[{"count":1,"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/posts\/34863\/revisions"}],"predecessor-version":[{"id":34866,"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/posts\/34863\/revisions\/34866"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/media\/34865"}],"wp:attachment":[{"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/media?parent=34863"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/categories?post=34863"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/tags?post=34863"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}