{"id":3477,"date":"2016-12-31T00:29:35","date_gmt":"2016-12-31T05:29:35","guid":{"rendered":"http:\/\/elinformanteperu.com\/?p=3477"},"modified":"2016-12-31T00:29:35","modified_gmt":"2016-12-31T05:29:35","slug":"51-conciertos-vivio-lima-en-el-2016","status":"publish","type":"post","link":"https:\/\/elinformanteperu.com\/index.php\/2016\/12\/31\/51-conciertos-vivio-lima-en-el-2016\/","title":{"rendered":"51 conciertos vivi\u00f3 Lima en el 2016"},"content":{"rendered":"<p><strong>Cerca de 51 puestas musicales vivi\u00f3 Lima en diversos escenarios trayendo a nuestro pa\u00eds figuras como Coldplay, Rolling Stones o Guns N\u2019 Roses, entre otros.<\/strong><\/p>\n<p><strong>Lima, 30 Diciembre 2016, (ANDINA).-<\/strong> Cerca de 51 puestas musicales vivi\u00f3 Lima en diversos escenarios trayendo a nuestro pa\u00eds figuras como Coldplay, Rolling Stones o Guns N\u2019 Roses solo por mencionar a algunos.<\/p>\n<p>Si bien es cierto no solo las figuras del rock pisaron suelo peruano, exponentes de otros g\u00e9neros tambi\u00e9n lograron mostrar su arte en conciertos masivos como Willie Col\u00f3n y El Gran Combo, quienes estelarizaron un cartel salsero al lado de otros exponentes.<\/p>\n<p>El grupo que m\u00e1s asistencia llev\u00f3, seg\u00fan informa Apdayc, fue Coldplay. Ellos nos visitaron el pasado abril y lograron convocar a 48 mil 623 asistentes en el Estadio Nacional.<\/p>\n<p>La visita de la banda liderada por Chris Martin trajo a la actriz Gwyneth Paltrow con su hijo Moses, quien recibi\u00f3 su cumplea\u00f1os sobre el escenario con un homenaje que le hizo su popular padre.<\/p>\n<p>El segundo lugar en asistencia lo tuvo Guns N\u2019 Roses. Esta presencia gener\u00f3 gran expectativa ya que tra\u00edda a nuestro pa\u00eds a Axl Rose y Slash, este \u00faltimo nos hab\u00eda visitado hac\u00eda relativamente poco, sin embargo su reconciliaci\u00f3n musical logr\u00f3 llevar al recinto que los recibi\u00f3 a 47 mil 340 personas.<\/p>\n<p>Otros que capturaron la atenci\u00f3n de la prensa fueron The Rolling Stones. La agrupaci\u00f3n brit\u00e1nica captur\u00f3 con cada paso que dieron en nuestro pa\u00eds a los peruanos y esta visita llev\u00f3 a su concierto a 46 mil 136 personas en el Monumental.<\/p>\n<p>Aunque se realiz\u00f3 casi cerrando el a\u00f1o el Festival Vivo X el Rock congreg\u00f3 en su cartel a numerosas figuras queridas por los peruanos y as\u00ed su asistencia se tradujo en 44 mil 855 personas en el Estadio Nacional.<\/p>\n<p>Grupos como Man\u00e1 tambi\u00e9n tuvieron buena recepci\u00f3n, apenas 835 menos espectadores que Vivo X el Rock.<\/p>\n<p>Tambi\u00e9n nos visitaron figuras como Alejandro Sanz, quien junto a Rub\u00e9n Blades y Eddie Palmieri protagonizaron una puesta m\u00e1gica en Lima en el marco de un festival al igual que Iggy Pop en Ciudad Rock.<\/p>\n<p>Otras bandas como la inglesa Foals sorprendieron con su llegada, al igual que Laura Marling, Esperanza Spalding.<\/p>\n<p>El g\u00e9nero del amor tuvo a Sin Bandera y para quienes disfrutan de las estrellas de la m\u00fasica brasile\u00f1a lleg\u00f3 Caetano Veloso y Gilberto Gil.<\/p>\n<p>Una de las ausencias pese a que se anunci\u00f3 con insistencia fue Eros Ramazzoti, quien suspendi\u00f3 su show en Lima.<br \/>\nTambi\u00e9n nos visitaron New Order, Chris Cornell, Travis, Aerosmith, Slipknot, entre otros.<\/p>\n<p>Tambi\u00e9n Buika, Nacho Vegas, Los Violadores y m\u00e1s.<\/p>\n<p><iframe src=\"https:\/\/www.youtube-nocookie.com\/embed\/QtXby3twMmI?rel=0&amp;controls=0&amp;showinfo=0\" width=\"560\" height=\"315\" frameborder=\"0\" allowfullscreen=\"allowfullscreen\"><\/iframe><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Cerca de 51 puestas musicales vivi\u00f3 Lima en diversos escenarios trayendo a nuestro pa\u00eds figuras como Coldplay, Rolling Stones o Guns N\u2019 Roses, entre otros. Lima, 30 Diciembre 2016, (ANDINA).- Cerca de 51 puestas musicales vivi\u00f3 Lima en diversos escenarios trayendo a nuestro pa\u00eds figuras como Coldplay, Rolling Stones o Guns N\u2019 Roses solo por [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":3478,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"rop_custom_images_group":[],"rop_custom_messages_group":[],"rop_publish_now":"initial","rop_publish_now_accounts":[],"rop_publish_now_history":[],"rop_publish_now_status":"pending","footnotes":""},"categories":[69],"tags":[687],"class_list":["post-3477","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-musica","tag-apdayc"],"_links":{"self":[{"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/posts\/3477","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/comments?post=3477"}],"version-history":[{"count":1,"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/posts\/3477\/revisions"}],"predecessor-version":[{"id":3479,"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/posts\/3477\/revisions\/3479"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/media\/3478"}],"wp:attachment":[{"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/media?parent=3477"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/categories?post=3477"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/tags?post=3477"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}