{"id":3305,"date":"2016-12-28T00:59:25","date_gmt":"2016-12-28T05:59:25","guid":{"rendered":"http:\/\/elinformanteperu.com\/?p=3305"},"modified":"2016-12-28T00:59:25","modified_gmt":"2016-12-28T05:59:25","slug":"familia-de-george-michael-rechaza-sospechas-sobre-su-muerte","status":"publish","type":"post","link":"https:\/\/elinformanteperu.com\/index.php\/2016\/12\/28\/familia-de-george-michael-rechaza-sospechas-sobre-su-muerte\/","title":{"rendered":"Familia de George Michael rechaza sospechas sobre su muerte"},"content":{"rendered":"<p><strong>La familia del cantante y compositor brit\u00e1nico George Michael rechaz\u00f3 la existencia de circunstancias sospechosas alrededor de su fallecimiento.<\/strong><\/p>\n<p><strong>Londres, 27 Diciembre 2016, (PL).-<\/strong> La familia del cantante y compositor brit\u00e1nico George Michael rechaz\u00f3 la existencia de circunstancias sospechosas alrededor de su fallecimiento el pasado 25 de diciembre.<\/p>\n<p>Tras negar cualquier evento dudoso en un comunicado p\u00fablico, la familia agradeci\u00f3 a todos los que han elegido celebrar la vida y legado del artista pues consider\u00f3 esto como lo correcto en el actual momento desolador.<\/p>\n<p>La noticia de la muerte de Michael a los 53 a\u00f1os de edad fue recibida con desconcierto en todo el planeta, y no pocos conjeturan sobre una causa relacionada con la adicci\u00f3n a la marihuana y el consumo excesivo de alcohol, que incluso lo llevaron a prisi\u00f3n alguna vez y le ocasionaron accidentes.<\/p>\n<p>Pero la polic\u00eda brit\u00e1nica niega hasta este instante cualquier hecho sospechoso y el agente del compositor, productor y cantante, Michael Lippman, dijo a la publicaci\u00f3n estadounidense Billboard que se trat\u00f3 de un fallo card\u00edaco.<\/p>\n<p>Georgios Kyriacos Panayiotou, nombre real Michael, fue una de las estrellas m\u00e1s reconocidas del pop de las d\u00e9cadas de 1980 y 1990, con una exitosa carrera primero junto a la banda Wham! y luego en solitario.<\/p>\n<p>Dos premios Grammy y colaboraciones con Elton John, la banda Queen y otras celebridades acrecentaron su fama y la venta de discos por encima de los 100 millones.<\/p>\n<p>Al parecer, una legi\u00f3n de admiradores considera una muerte repentina por infarto como un evento demasiado com\u00fan para alguien tan singular, y contin\u00faa reclamando ex\u00e1menes m\u00e1s exhaustivos, as\u00ed como la publicaci\u00f3n de sus resultados.<\/p>\n<p><img fetchpriority=\"high\" decoding=\"async\" class=\"size-full wp-image-3280 alignnone\" src=\"http:\/\/elinformanteperu.com\/wp-content\/uploads\/2016\/12\/george-michael1.jpeg\" alt=\"\" width=\"858\" height=\"540\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La familia del cantante y compositor brit\u00e1nico George Michael rechaz\u00f3 la existencia de circunstancias sospechosas alrededor de su fallecimiento. Londres, 27 Diciembre 2016, (PL).- La familia del cantante y compositor brit\u00e1nico George Michael rechaz\u00f3 la existencia de circunstancias sospechosas alrededor de su fallecimiento el pasado 25 de diciembre. Tras negar cualquier evento dudoso en un [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":3306,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"rop_custom_images_group":[],"rop_custom_messages_group":[],"rop_publish_now":"initial","rop_publish_now_accounts":[],"rop_publish_now_history":[],"rop_publish_now_status":"pending","footnotes":""},"categories":[69],"tags":[649],"class_list":["post-3305","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-musica","tag-george-michael"],"_links":{"self":[{"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/posts\/3305","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/comments?post=3305"}],"version-history":[{"count":1,"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/posts\/3305\/revisions"}],"predecessor-version":[{"id":3307,"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/posts\/3305\/revisions\/3307"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/media\/3306"}],"wp:attachment":[{"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/media?parent=3305"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/categories?post=3305"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/tags?post=3305"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}