{"id":2904,"date":"2016-12-19T21:28:59","date_gmt":"2016-12-20T02:28:59","guid":{"rendered":"http:\/\/elinformanteperu.com\/?p=2904"},"modified":"2016-12-19T21:28:59","modified_gmt":"2016-12-20T02:28:59","slug":"luis-aguiar-promete-sacrificio-respeto-y-humildad-para-lograr-el-titulo","status":"publish","type":"post","link":"https:\/\/elinformanteperu.com\/index.php\/2016\/12\/19\/luis-aguiar-promete-sacrificio-respeto-y-humildad-para-lograr-el-titulo\/","title":{"rendered":"Luis Aguiar promete \u00abSacrificio, respeto  y humildad para lograr el t\u00edtulo\u00bb"},"content":{"rendered":"<p><strong>El nuevo volante de Alianza Lima, el uruguayo Luis Bernardo Aguiar, ha prometido \u201csacrificio, respeto y humildad\u00bb para lograr juntos el t\u00edtulo nacional 2017.<\/strong><\/p>\n<p><strong>Lima, 19 Diciembre 2016, (El Informante Per\u00fa).-<\/strong> El nuevo volante de Alianza Lima, el uruguayo Luis Bernardo Aguiar, ha prometido \u201csacrificio, respeto y humildad\u00bb para lograr juntos el t\u00edtulo nacional 2017.<\/p>\n<p>Aguiar que ha militado en el Pe\u00f1arol, ha garantizado, en declaraciones a Alianza Lima Noticias, que va a \u00abdejarlo todo en la cancha\u00bb.<\/p>\n<p>\u201cDesde ya prometo sacrifico, mucha humildad hacia mis compa\u00f1eros y mucho respeto hacia el club para lograr lo que tanto ans\u00edan que es ser campeones. Estoy ansioso de llegar al Per\u00fa\u201d, dijo el mediocampista.<\/p>\n<p>Aguiar Burgos que se encuentra en Montevideo, ha indicado que est\u00e1 \u00abmuy contento y feliz\u201d de llegar a una gran instituci\u00f3n como Alianza Lima. Se\u00f1al\u00f3 que su intenci\u00f3n es estar a la altura y tratar de ayudar al equipo a lograr los objetivos trazados.<\/p>\n<p>El futbolista uruguayo dijo que Alianza Lima como club grande aspira a lograr t\u00edtulos y con el apoyo de todos se podr\u00e1 conseguir.<\/p>\n<p>\u201cSolo prometo sacrifico y respeto por esa camiseta grande como es la de Alianza Lima\u201d, reiter\u00f3.<\/p>\n<p>Aguiar, de 31 a\u00f1os ha militado en clubes como: Sporting de Lisboa, Sporting braga, Dinamo de Mosc\u00fa, San Lorenzo (Argentina) y Vitoria (Brasil).<\/p>\n<p><iframe src=\"https:\/\/www.youtube-nocookie.com\/embed\/ZBVCw8WzcmU?rel=0&amp;controls=0&amp;showinfo=0\" width=\"560\" height=\"315\" frameborder=\"0\" allowfullscreen=\"allowfullscreen\"><\/iframe><\/p>\n","protected":false},"excerpt":{"rendered":"<p>El nuevo volante de Alianza Lima, el uruguayo Luis Bernardo Aguiar, ha prometido \u201csacrificio, respeto y humildad\u00bb para lograr juntos el t\u00edtulo nacional 2017. Lima, 19 Diciembre 2016, (El Informante Per\u00fa).- El nuevo volante de Alianza Lima, el uruguayo Luis Bernardo Aguiar, ha prometido \u201csacrificio, respeto y humildad\u00bb para lograr juntos el t\u00edtulo nacional 2017. [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":2905,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"rop_custom_images_group":[],"rop_custom_messages_group":[],"rop_publish_now":"initial","rop_publish_now_accounts":[],"rop_publish_now_history":[],"rop_publish_now_status":"pending","footnotes":""},"categories":[8],"tags":[91,575],"class_list":["post-2904","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-disciplinas-deportivas","tag-alianza-lima","tag-luis-aguiar"],"_links":{"self":[{"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/posts\/2904","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/comments?post=2904"}],"version-history":[{"count":1,"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/posts\/2904\/revisions"}],"predecessor-version":[{"id":2906,"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/posts\/2904\/revisions\/2906"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/media\/2905"}],"wp:attachment":[{"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/media?parent=2904"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/categories?post=2904"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/tags?post=2904"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}