{"id":25885,"date":"2018-04-29T11:40:57","date_gmt":"2018-04-29T16:40:57","guid":{"rendered":"http:\/\/elinformanteperu.com\/?p=25885"},"modified":"2018-04-30T00:18:37","modified_gmt":"2018-04-30T05:18:37","slug":"48-trabajadores-al-dia-tienen-un-accidente-durante-su-jornada-laboral","status":"publish","type":"post","link":"https:\/\/elinformanteperu.com\/index.php\/2018\/04\/29\/48-trabajadores-al-dia-tienen-un-accidente-durante-su-jornada-laboral\/","title":{"rendered":"48 trabajadores al d\u00eda tienen un accidente durante su jornada laboral"},"content":{"rendered":"<p><span style=\"color: #000000;\"><strong>Del total de accidentes, 297 atenciones fueron amputaciones traum\u00e1ticas con p\u00e9rdida parcial o total de la parte afectada.\u00a0<\/strong><\/span><\/p>\n<p><span style=\"color: #000000;\"><strong>Lima, 29 de Abril 2018, &#8211; (El Informante Per\u00fa).-<\/strong> Un promedio de 48 accidentes de trabajo por d\u00eda, lo que equivale a decir a dos accidentes por hora, registra la cartera del Seguro Complementario de Trabajo de Riesgo (SCTR) Salud de RIMAC Seguros.<\/span><\/p>\n<p><span style=\"color: #000000;\">El informe detalla que los sectores econ\u00f3micos que presentaron mayor frecuencia de accidentes fueron Industrias Manufactureras (28.46%).<\/span><\/p>\n<p><span style=\"color: #000000;\">Le siguen, Comercio (10.50%) y Construcci\u00f3n (10.23%), indican las estad\u00edsticas del 2017, en cuyo a\u00f1o RIMAC atendi\u00f3 un total de 17,446 accidentes laborales.<\/span><\/p>\n<p><span style=\"color: #000000;\">Los afectados son mayoritariamente varones (87.48%); sin embargo, la incidencia de casos en mujeres se est\u00e1 incrementando progresivamente conforme se integran en actividades de riesgo.<\/span><\/p>\n<p><span style=\"color: #000000;\">La mayor parte de estos accidentes se atendieron en Lima y Callao que agruparon el 78.90% de los casos, mientras que 21.09% fueron atendidos en el resto del pa\u00eds.<\/span><\/p>\n<p><span style=\"color: #000000;\"><strong>Amputaciones traum\u00e1ticas<\/strong><\/span><\/p>\n<p><span style=\"color: #000000;\">Los accidentes no siempre terminan en la recuperaci\u00f3n total del trabajador. En algunas ocasiones pueden dejar secuelas que determinan una incapacidad permanente y sus consecuencias para la persona, la familia y la sociedad. Las lesiones traum\u00e1ticas que terminan en alg\u00fan tipo de amputaci\u00f3n son un ejemplo de este tipo de situaci\u00f3n.<\/span><\/p>\n<p><span style=\"color: #000000;\">Del total de accidentes registrados el 2017, 297 fueron amputaciones traum\u00e1ticas. El 92.25% de estos casos afecto a varones y el 7.7% a mujeres.<\/span><\/p>\n<p><span style=\"color: #000000;\">Los casos de amputaci\u00f3n m\u00e1s frecuentes ocurrieron en extremidad superior con 244 casos (82.15%) y extremidad inferior en 53 casos (17.85%).<\/span><\/p>\n<p><span style=\"color: #000000;\">En tanto, 6 (2.46%) de los casos de amputaci\u00f3n de extremidad superior ocurrieron por encima de la mu\u00f1eca y los 238 (97.54%) casos restantes afectaron manos y\/o dedos.<\/span><\/p>\n<p><span style=\"color: #000000;\">En el caso de amputaci\u00f3n de extremidad inferior, se tuvieron 52 casos (98.11%), que afectaron pies y\/o dedos.<\/span><\/p>\n<p><span style=\"color: #000000;\">El 50.81% de los accidentes ocurri\u00f3 en menores de 35 a\u00f1os, lo cual da cuenta del alto impacto que esto tiene para la sociedad por la potencial p\u00e9rdida de a\u00f1os de vida productiva perdidos por incapacidad.<\/span><\/p>\n<p><span style=\"color: #000000;\">En este punto es evidente la importancia de un seguro de riesgos laborales, que garantice la oportuna y adecuada atenci\u00f3n m\u00e9dica del colaborador hasta su recuperaci\u00f3n completa o la debida compensaci\u00f3n econ\u00f3mica en caso extremo de una incapacidad permanente o fallecimiento secundaria al accidente de trabajo o enfermedad profesional. Esta protecci\u00f3n de naturaleza social est\u00e1 dise\u00f1ada para evitar el desamparo de la familia y asegurar la sostenibilidad de la empresa.<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Del total de accidentes, 297 atenciones fueron amputaciones traum\u00e1ticas con p\u00e9rdida parcial o total de la parte afectada.\u00a0 Lima, 29 de Abril 2018, &#8211; (El Informante Per\u00fa).- Un promedio de 48 accidentes de trabajo por d\u00eda, lo que equivale a decir a dos accidentes por hora, registra la cartera del Seguro Complementario de Trabajo de [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":25887,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"rop_custom_images_group":[],"rop_custom_messages_group":[],"rop_publish_now":"initial","rop_publish_now_accounts":[],"rop_publish_now_history":[],"rop_publish_now_status":"pending","footnotes":""},"categories":[10],"tags":[533],"class_list":["post-25885","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualidad-municipal","tag-rimac-seguros"],"_links":{"self":[{"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/posts\/25885","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/comments?post=25885"}],"version-history":[{"count":2,"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/posts\/25885\/revisions"}],"predecessor-version":[{"id":26006,"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/posts\/25885\/revisions\/26006"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/media\/25887"}],"wp:attachment":[{"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/media?parent=25885"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/categories?post=25885"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/tags?post=25885"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}