{"id":20434,"date":"2017-12-28T20:28:05","date_gmt":"2017-12-29T01:28:05","guid":{"rendered":"http:\/\/elinformanteperu.com\/?p=20434"},"modified":"2017-12-28T20:28:05","modified_gmt":"2017-12-29T01:28:05","slug":"dinamarca-tiene-la-mejor-progresion-del-ano-en-la-clasificacion-mundial-fifa","status":"publish","type":"post","link":"https:\/\/elinformanteperu.com\/index.php\/2017\/12\/28\/dinamarca-tiene-la-mejor-progresion-del-ano-en-la-clasificacion-mundial-fifa\/","title":{"rendered":"Dinamarca tiene la mejor progresi\u00f3n del a\u00f1o en la Clasificaci\u00f3n Mundial FIFA"},"content":{"rendered":"<p><strong><span style=\"color: #000000;\">La selecci\u00f3n de Dinamarca, que jugar\u00e1 contra Per\u00fa en el Mundial Rusia 2018, se ha mantenido imbatida durante todo el a\u00f1o y se ha convertido en el equipo con la mejor progresi\u00f3n del a\u00f1o.<\/span><\/strong><\/p>\n<p><span style=\"color: #000000;\"><strong>Lima, 28 Diciembre 2017, (ANDINA).-<\/strong> La selecci\u00f3n de Dinamarca, que jugar\u00e1 contra Per\u00fa en el Mundial Rusia 2018, se ha mantenido imbatida durante todo el a\u00f1o y se ha convertido en el equipo con la mejor progresi\u00f3n del a\u00f1o en la Clasificaci\u00f3n Mundial FIFA.<\/span><\/p>\n<p><span style=\"color: #000000;\">El portal FIFA resalt\u00f3 que los daneses lograron incrementar 456 puntos a su rendimiento, lo cual lo ha llevado a terminar el 2017 en la 12\u00aa posici\u00f3n de la clasificaci\u00f3n mundial. Su ubicaci\u00f3n era el puesto 46\u00ba al final del a\u00f1o 2016.<\/span><\/p>\n<p><span style=\"color: #000000;\">Un jugador clave para el excelente a\u00f1o que ha disfrutado Dinamarca es Christian Eriksen. El creador de juego del Tottenham Hotspur registr\u00f3 11 goles a lo largo de la campa\u00f1a de clasificaci\u00f3n, incluido los decisivos tres goles contra la Rep\u00fablica de Irlanda que le permiti\u00f3 sellar su pase al Mundial Rusia 2018.<\/span><\/p>\n<p><span style=\"color: #000000;\">Otro hombre fundamental ha sido el entrenador noruego Age Hareide, quien se hizo cargo de la selecci\u00f3n de Dinamarca el 2016.<\/span><\/p>\n<p><strong><span style=\"color: #000000;\">Factor determinante<\/span><\/strong><\/p>\n<p><span style=\"color: #000000;\">\u00abLa habilidad del exseleccionador nacional de Noruega para sacar lo mejor de Eriksen y lograr al mismo tiempo que su equipo fuera mejor que la suma de sus partes se consideran los factores determinantes de la clasificaci\u00f3n de Dinamarca para Rusia 2018\u00bb, se\u00f1ala el portal FIFA.<\/span><\/p>\n<p><span style=\"color: #000000;\">\u00abEn nuestro caso, creo que se trata de la capacidad de jugar con diferentes planteamientos. Tenemos presencia f\u00edsica en la delantera, pero tambi\u00e9n jugadores de gran habilidad t\u00e9cnica. Los extraordinarios recursos de Christian Eriksen nos han proporcionado el plus que necesit\u00e1bamos en estos aspectos\u00bb, manifest\u00f3, por su parte, Age Hareide.<\/span><\/p>\n<p><span style=\"color: #000000;\">La Selecci\u00f3n Peruana debutar\u00e1 ante Dinamarca por la primera fecha del Grupo C del Mundial Rusia 2018, el s\u00e1bado 16 de junio en el Estadio Mordovia Saransk.<\/span><\/p>\n<p><span style=\"color: #000000;\">Dicho grupo tambi\u00e9n es integrador por Francia y Australia.<\/span><\/p>\n<p><span style=\"color: #000000;\"><img fetchpriority=\"high\" decoding=\"async\" class=\"aligncenter size-full wp-image-20436\" src=\"http:\/\/elinformanteperu.com\/wp-content\/uploads\/2017\/12\/Dinamarca-Age-Hareide.jpg\" alt=\"\" width=\"500\" height=\"337\" srcset=\"https:\/\/elinformanteperu.com\/wp-content\/uploads\/2017\/12\/Dinamarca-Age-Hareide.jpg 500w, https:\/\/elinformanteperu.com\/wp-content\/uploads\/2017\/12\/Dinamarca-Age-Hareide-300x202.jpg 300w, https:\/\/elinformanteperu.com\/wp-content\/uploads\/2017\/12\/Dinamarca-Age-Hareide-128x86.jpg 128w, https:\/\/elinformanteperu.com\/wp-content\/uploads\/2017\/12\/Dinamarca-Age-Hareide-32x22.jpg 32w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/><\/span><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La selecci\u00f3n de Dinamarca, que jugar\u00e1 contra Per\u00fa en el Mundial Rusia 2018, se ha mantenido imbatida durante todo el a\u00f1o y se ha convertido en el equipo con la mejor progresi\u00f3n del a\u00f1o. Lima, 28 Diciembre 2017, (ANDINA).- La selecci\u00f3n de Dinamarca, que jugar\u00e1 contra Per\u00fa en el Mundial Rusia 2018, se ha mantenido [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":20435,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"rop_custom_images_group":[],"rop_custom_messages_group":[],"rop_publish_now":"initial","rop_publish_now_accounts":[],"rop_publish_now_history":[],"rop_publish_now_status":"pending","footnotes":""},"categories":[8],"tags":[140,2427,268],"class_list":["post-20434","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-disciplinas-deportivas","tag-copa-del-mundo-fifa","tag-dinamarca","tag-fifa"],"_links":{"self":[{"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/posts\/20434","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/comments?post=20434"}],"version-history":[{"count":1,"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/posts\/20434\/revisions"}],"predecessor-version":[{"id":20437,"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/posts\/20434\/revisions\/20437"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/media\/20435"}],"wp:attachment":[{"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/media?parent=20434"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/categories?post=20434"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/tags?post=20434"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}