{"id":20135,"date":"2017-12-24T09:55:18","date_gmt":"2017-12-24T14:55:18","guid":{"rendered":"http:\/\/elinformanteperu.com\/?p=20135"},"modified":"2017-12-24T09:55:18","modified_gmt":"2017-12-24T14:55:18","slug":"disfruta-la-navidad-en-familia-en-los-clubes-zonales-y-parques-metropolitanos-de-lima","status":"publish","type":"post","link":"https:\/\/elinformanteperu.com\/index.php\/2017\/12\/24\/disfruta-la-navidad-en-familia-en-los-clubes-zonales-y-parques-metropolitanos-de-lima\/","title":{"rendered":"Disfruta la Navidad en familia en los clubes zonales y parques metropolitanos de Lima"},"content":{"rendered":"<p><strong><span style=\"color: #000000;\">Este fin de semana disfruta de las diferentes actividades que se realizar\u00e1n para toda la familia en los 10 clubes zonales y 9 parques metropolitanos de Lima.<\/span><\/strong><\/p>\n<p><span style=\"color: #000000;\"><strong>Lima, 24 Diciembre 2017, (ANDINA).-<\/strong> Este fin de semana de Navidad no te quedes en casa y disfruta de las diferentes actividades que se realizar\u00e1n para toda la familia en los 10 clubes zonales y 9 parques metropolitanos de Lima, hoy domingo 24 y ma\u00f1ana lunes 25 de diciembre, inform\u00f3 la municipalidad capitalina.<\/span><\/p>\n<p><span style=\"color: #000000;\">Precis\u00f3 que las instalaciones administradas por el Servicio de Parques (Serpar) abrir\u00e1n al p\u00fablico desde las 8.00 am. hasta las 6.00 pm.<\/span><\/p>\n<p><span style=\"color: #000000;\">Los asistentes podr\u00e1n entretenerse en las amplias \u00e1reas verdes, campos deportivos, juegos infantiles, restaurantes y otros atractivos.<\/span><\/p>\n<p><span style=\"color: #000000;\">De igual manera, podr\u00e1n recrearse con paseos a caballo, cuatrimotos, bicicletas y visitar las munigranjas que poseen los 10 clubes zonales y 9 parques metropolitanos que administra Serpar.<\/span><\/p>\n<p><span style=\"color: #000000;\">Los clubes zonales y parques metropolitanos de Serpar cuentan con m\u00e1s de 400 hect\u00e1reas de \u00e1reas verdes, que est\u00e1n disponibles para que el p\u00fablico las disfrute los 365 d\u00edas del a\u00f1o.<\/span><\/p>\n<p><span style=\"color: #000000;\">De esta manera, la Municipalidad de Lima sigue consolidando su compromiso de llevar cultura y entretenimiento sano en los clubes y parques de nuestra capital.<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Este fin de semana disfruta de las diferentes actividades que se realizar\u00e1n para toda la familia en los 10 clubes zonales y 9 parques metropolitanos de Lima. Lima, 24 Diciembre 2017, (ANDINA).- Este fin de semana de Navidad no te quedes en casa y disfruta de las diferentes actividades que se realizar\u00e1n para toda la [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":20136,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"rop_custom_images_group":[],"rop_custom_messages_group":[],"rop_publish_now":"initial","rop_publish_now_accounts":[],"rop_publish_now_history":[],"rop_publish_now_status":"pending","footnotes":""},"categories":[10],"tags":[122,568],"class_list":["post-20135","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualidad-municipal","tag-municipalidad-de-lima","tag-serpar"],"_links":{"self":[{"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/posts\/20135","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/comments?post=20135"}],"version-history":[{"count":1,"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/posts\/20135\/revisions"}],"predecessor-version":[{"id":20137,"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/posts\/20135\/revisions\/20137"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/media\/20136"}],"wp:attachment":[{"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/media?parent=20135"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/categories?post=20135"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/tags?post=20135"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}