{"id":17335,"date":"2017-10-22T12:32:25","date_gmt":"2017-10-22T17:32:25","guid":{"rendered":"http:\/\/elinformanteperu.com\/?p=17335"},"modified":"2017-10-22T12:32:25","modified_gmt":"2017-10-22T17:32:25","slug":"bcp-ofrece-a-sus-clientes-permitirles-escoger-disenos-de-personajes-en-sus-tarjetas-de-credito-y-debito","status":"publish","type":"post","link":"https:\/\/elinformanteperu.com\/index.php\/2017\/10\/22\/bcp-ofrece-a-sus-clientes-permitirles-escoger-disenos-de-personajes-en-sus-tarjetas-de-credito-y-debito\/","title":{"rendered":"BCP ofrece a sus clientes permitirles escoger dise\u00f1os de personajes en sus tarjetas de cr\u00e9dito y d\u00e9bito"},"content":{"rendered":"<p><span style=\"color: #000000;\"><strong>Estrategia del BCP permite que clientes sientan al banco m\u00e1s cercano e incrementa el uso del dinero pl\u00e1stico. A la fecha, 7% del total de tarjetas de cr\u00e9dito tienen dise\u00f1os de personajes.\u00a0<\/strong><\/span><\/p>\n<p><span style=\"color: #000000;\"><strong>Lima, 22 Octubre 2017, (El Informante Per\u00fa).-<\/strong> A fin de seguir construyendo una experiencia WOW para sus clientes, el BCP present\u00f3 los nuevos dise\u00f1os de Plastic Choice, servicio que permite personalizar los pl\u00e1sticos de las tarjetas de cr\u00e9dito y d\u00e9bito con personajes ic\u00f3nicos solicitados por el p\u00fablico. Jose Antonio Mu\u00f1iz, gerente de \u00c1rea de Medios de Pago y Financiamiento al Consumo del BCP, explic\u00f3 que los nuevos dise\u00f1os tienen como motivo a los personajes de Transformers, serie entra\u00f1able muy popular de las d\u00e9cada del 80 y 90, que fue llevada al cine a\u00f1os m\u00e1s tarde.<\/span><\/p>\n<p><span style=\"color: #000000;\">Estos dise\u00f1os se suman al portafolio de Plastic Choice, integrado por Hello Kitty, Superman, Batman, Los Simpson y Looney Tunes. De esa manera, el BCP cuenta con 16 dise\u00f1os para tarjeta de cr\u00e9dito y 11 para tarjetas de d\u00e9bito.<\/span><\/p>\n<p><span style=\"color: #000000;\">\u201cPlastic Choice muestra el lado innovador y divertido del BCP. El cliente valora que se le d\u00e9 la posibilidad de personalizar su tarjeta con dise\u00f1os de personajes que los han acompa\u00f1ado durante toda la vida. Plastic Choice ha generado una relaci\u00f3n mucho m\u00e1s cercana y de fidelidad entre las tarjetas y los clientes\u201d, se\u00f1al\u00f3.<\/span><\/p>\n<p><span style=\"color: #000000;\">Mu\u00f1iz detall\u00f3 que la respuesta del p\u00fablico ha sido muy favorable, a tal punto que en menos de cuatro a\u00f1os se ha conseguido que el 7% del total de tarjetas de cr\u00e9dito tengan dise\u00f1o de Plastic Choice. Explic\u00f3 que el uso de la tarjeta de cr\u00e9dito con dise\u00f1o se incrementa notablemente, pues la facturaci\u00f3n promedio de este tipo de tarjeta es mayor en un 53% que en el promedio de tarjetas sin dise\u00f1o.<\/span><\/p>\n<p><span style=\"color: #000000;\">Asimismo, en los \u00faltimos dos a\u00f1os se ha conseguido que se hayan emitido m\u00e1s de 70 mil tarjetas de d\u00e9bito con dise\u00f1os de Plastic Choice, las cuales representan el 2% del total y han motivado un uso promedio 23% mayor que el resto de pl\u00e1sticos, que no tienen dise\u00f1o.<\/span><\/p>\n<p><span style=\"color: #000000;\">El gerente de \u00c1rea de Medios de Pago y Financiamiento al Consumo del BCP se\u00f1al\u00f3 que los clientes participan en la selecci\u00f3n de los motivos para Plastic Choice y est\u00e1n interactuando permanentemente para generar m\u00e1s valor en la relaci\u00f3n que tienen los clientes con sus tarjetas.<\/span><\/p>\n<div id=\"attachment_17336\" style=\"width: 1603px\" class=\"wp-caption aligncenter\"><img fetchpriority=\"high\" decoding=\"async\" aria-describedby=\"caption-attachment-17336\" class=\"size-full wp-image-17336\" src=\"http:\/\/elinformanteperu.com\/wp-content\/uploads\/2017\/10\/BCP-Jose-Antonio-Muniz.jpg\" alt=\"\" width=\"1593\" height=\"1062\" srcset=\"https:\/\/elinformanteperu.com\/wp-content\/uploads\/2017\/10\/BCP-Jose-Antonio-Muniz.jpg 1593w, https:\/\/elinformanteperu.com\/wp-content\/uploads\/2017\/10\/BCP-Jose-Antonio-Muniz-300x200.jpg 300w, https:\/\/elinformanteperu.com\/wp-content\/uploads\/2017\/10\/BCP-Jose-Antonio-Muniz-768x512.jpg 768w, https:\/\/elinformanteperu.com\/wp-content\/uploads\/2017\/10\/BCP-Jose-Antonio-Muniz-1024x683.jpg 1024w, https:\/\/elinformanteperu.com\/wp-content\/uploads\/2017\/10\/BCP-Jose-Antonio-Muniz-128x85.jpg 128w, https:\/\/elinformanteperu.com\/wp-content\/uploads\/2017\/10\/BCP-Jose-Antonio-Muniz-32x21.jpg 32w\" sizes=\"(max-width: 1593px) 100vw, 1593px\" \/><p id=\"caption-attachment-17336\" class=\"wp-caption-text\"><strong>Jose Antonio Mu\u00f1iz, gerente de \u00c1rea de Medios de Pago y Financiamiento al Consumo del BCP.<\/strong><\/p><\/div>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Estrategia del BCP permite que clientes sientan al banco m\u00e1s cercano e incrementa el uso del dinero pl\u00e1stico. A la fecha, 7% del total de tarjetas de cr\u00e9dito tienen dise\u00f1os de personajes.\u00a0 Lima, 22 Octubre 2017, (El Informante Per\u00fa).- A fin de seguir construyendo una experiencia WOW para sus clientes, el BCP present\u00f3 los nuevos [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":17337,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"rop_custom_images_group":[],"rop_custom_messages_group":[],"rop_publish_now":"initial","rop_publish_now_accounts":[],"rop_publish_now_history":[],"rop_publish_now_status":"pending","footnotes":""},"categories":[10],"tags":[254],"class_list":["post-17335","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualidad-municipal","tag-bcp"],"_links":{"self":[{"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/posts\/17335","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/comments?post=17335"}],"version-history":[{"count":1,"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/posts\/17335\/revisions"}],"predecessor-version":[{"id":17338,"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/posts\/17335\/revisions\/17338"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/media\/17337"}],"wp:attachment":[{"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/media?parent=17335"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/categories?post=17335"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/tags?post=17335"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}