{"id":16905,"date":"2017-10-15T10:39:45","date_gmt":"2017-10-15T15:39:45","guid":{"rendered":"http:\/\/elinformanteperu.com\/?p=16905"},"modified":"2017-10-15T10:39:45","modified_gmt":"2017-10-15T15:39:45","slug":"seleccion-peruana-confirman-fechas-del-repechaje-contra-nueva-zelanda","status":"publish","type":"post","link":"https:\/\/elinformanteperu.com\/index.php\/2017\/10\/15\/seleccion-peruana-confirman-fechas-del-repechaje-contra-nueva-zelanda\/","title":{"rendered":"Selecci\u00f3n peruana: Confirman fechas del repechaje contra Nueva Zelanda"},"content":{"rendered":"<p><strong><span style=\"color: #000000;\">La Federaci\u00f3n Peruana de F\u00fatbol (FPF) anunci\u00f3 las fechas en que se jugar\u00e1n los partidos de repechaje contra la selecci\u00f3n de Nueva Zelanda con miras al Mundial de Rusia 2018.<\/span><\/strong><\/p>\n<p><span style=\"color: #000000;\"><strong>Lima, 14 Octubre 2017, (ANDINA).-<\/strong> La Federaci\u00f3n Peruana de F\u00fatbol (FPF) anunci\u00f3 las fechas en que se jugar\u00e1n los partidos de repechaje contra la selecci\u00f3n de Nueva Zelanda con miras al Mundial de Rusia 2018.<\/span><\/p>\n<p><span style=\"color: #000000;\">Mediante un comunicado precis\u00f3 que la confirmaci\u00f3n de las fechas provino del Bureau del Consejo de la Federaci\u00f3n Internacional de de F\u00fatbol Asociado (FIFA).<\/span><\/p>\n<p><span style=\"color: #000000;\">Los partidos se jugar\u00e1n de la siguiente manera:<\/span><\/p>\n<p><span style=\"color: #000000;\">El 11 de noviembre en el Estadio Westpac, en Wellington, a las 16:15 horas de Nueva Zelanda (22:15 horas del 10 de noviembre en Per\u00fa).<\/span><\/p>\n<p><span style=\"color: #000000;\">El 15 de noviembre en el Estadio Nacional de Lima, a las 21:15 horas.<\/span><\/p>\n<p><span style=\"color: #000000;\">La FPF indic\u00f3 que la FIFA examin\u00f3 los diferentes elementos decisivos en juego alrededor de los partidos, como las distancias, duraci\u00f3n de vuelos y zonas horarias.<\/span><\/p>\n<p><img fetchpriority=\"high\" decoding=\"async\" class=\"aligncenter size-full wp-image-9486\" src=\"http:\/\/elinformanteperu.com\/wp-content\/uploads\/2017\/05\/seleccion20.jpg\" alt=\"\" width=\"1800\" height=\"1213\" srcset=\"https:\/\/elinformanteperu.com\/wp-content\/uploads\/2017\/05\/seleccion20.jpg 1800w, https:\/\/elinformanteperu.com\/wp-content\/uploads\/2017\/05\/seleccion20-300x202.jpg 300w, https:\/\/elinformanteperu.com\/wp-content\/uploads\/2017\/05\/seleccion20-768x518.jpg 768w, https:\/\/elinformanteperu.com\/wp-content\/uploads\/2017\/05\/seleccion20-1024x690.jpg 1024w, https:\/\/elinformanteperu.com\/wp-content\/uploads\/2017\/05\/seleccion20-128x86.jpg 128w, https:\/\/elinformanteperu.com\/wp-content\/uploads\/2017\/05\/seleccion20-32x22.jpg 32w\" sizes=\"(max-width: 1800px) 100vw, 1800px\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La Federaci\u00f3n Peruana de F\u00fatbol (FPF) anunci\u00f3 las fechas en que se jugar\u00e1n los partidos de repechaje contra la selecci\u00f3n de Nueva Zelanda con miras al Mundial de Rusia 2018. Lima, 14 Octubre 2017, (ANDINA).- La Federaci\u00f3n Peruana de F\u00fatbol (FPF) anunci\u00f3 las fechas en que se jugar\u00e1n los partidos de repechaje contra la selecci\u00f3n [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":16906,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"rop_custom_images_group":[],"rop_custom_messages_group":[],"rop_publish_now":"initial","rop_publish_now_accounts":[],"rop_publish_now_history":[],"rop_publish_now_status":"pending","footnotes":""},"categories":[8],"tags":[175,205,2249,137],"class_list":["post-16905","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-disciplinas-deportivas","tag-eliminatorias","tag-fpf","tag-repechaje-peru-nueva-zelanda","tag-seleccion-peruana"],"_links":{"self":[{"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/posts\/16905","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/comments?post=16905"}],"version-history":[{"count":1,"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/posts\/16905\/revisions"}],"predecessor-version":[{"id":16907,"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/posts\/16905\/revisions\/16907"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/media\/16906"}],"wp:attachment":[{"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/media?parent=16905"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/categories?post=16905"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/tags?post=16905"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}