{"id":141456,"date":"2025-08-08T01:58:13","date_gmt":"2025-08-08T06:58:13","guid":{"rendered":"https:\/\/elinformanteperu.com\/?p=141456"},"modified":"2025-08-08T01:58:13","modified_gmt":"2025-08-08T06:58:13","slug":"sjl-fuga-de-gas-cerca-al-malecon-checa-moviliza-a-bomberos-y-alarma-a-vecinos","status":"publish","type":"post","link":"https:\/\/elinformanteperu.com\/index.php\/2025\/08\/08\/sjl-fuga-de-gas-cerca-al-malecon-checa-moviliza-a-bomberos-y-alarma-a-vecinos\/","title":{"rendered":"SJL: fuga de gas cerca al Malec\u00f3n Checa moviliza a bomberos y alarma a vecinos"},"content":{"rendered":"<p><span style=\"color: #000000;\"><strong>Lima, 07 Agosto 2025, (ANDINA).-<\/strong> Una peligrosa fuga de gas se registr\u00f3 la tarde de hoy jueves 7 de agosto en el Malec\u00f3n Miguel Checa, en el distrito de San Juan de Lurigancho, generando alarma entre vecinos y obligando al cierre de v\u00edas en la zona.<\/span><\/p>\n<p><span style=\"color: #000000;\">El hecho fue reportado a las 17.32 horas por el Cuerpo General de Bomberos como un incidente por materiales peligrosos debido a la presencia de GLP u otros gases inflamables.<\/span><\/p>\n<p><span style=\"color: #000000;\">Seg\u00fan informaci\u00f3n de canal N, la fuga se origin\u00f3 en una tuber\u00eda ubicada cerca del cauce del r\u00edo R\u00edmac, a la altura del Puente Las Lomas, en el l\u00edmite con el distrito de El Agustino.<\/span><\/p>\n<p><span style=\"color: #000000;\">La fuerza con la que sal\u00eda el gas fue captada por los vecinos y personas que circulaban por el puente Las Lomas.<\/span><\/p>\n<p><span style=\"color: #000000;\">Al lugar acudieron cinco unidades de bomberos, agentes de la Polic\u00eda Nacional y personal de la Municipalidad de Lima para atender la emergencia.<\/span><\/p>\n<p><span style=\"color: #000000;\">Como medida preventiva, las autoridades cerraron el tr\u00e1nsito vehicular en el Malec\u00f3n Checa, quedando habilitada solo la avenida Chim\u00fa para el desplazamiento hacia Campoy y otras zonas de San Juan de Lurigancho.<\/span><\/p>\n<p><span style=\"color: #000000;\">Hasta el momento, se desconoce a qu\u00e9 empresa pertenece la tuber\u00eda da\u00f1ada ni las causas que originaron la fuga.<\/span><\/p>\n<p><span style=\"color: #000000;\">El escape de gas persiste, por lo que las autoridades han pedido a la poblaci\u00f3n evitar acercarse al \u00e1rea afectada mientras contin\u00faan las labores de seguridad.<\/span><\/p>\n<p><a href=\"https:\/\/elinformanteperu.com\/wp-content\/uploads\/2025\/02\/MML-escaleras-SJL3.jpg\"><img fetchpriority=\"high\" decoding=\"async\" class=\"size-large wp-image-135218 aligncenter\" src=\"https:\/\/elinformanteperu.com\/wp-content\/uploads\/2025\/02\/MML-escaleras-SJL3-1024x767.jpg\" alt=\"\" width=\"615\" height=\"461\" srcset=\"https:\/\/elinformanteperu.com\/wp-content\/uploads\/2025\/02\/MML-escaleras-SJL3-1024x767.jpg 1024w, https:\/\/elinformanteperu.com\/wp-content\/uploads\/2025\/02\/MML-escaleras-SJL3-300x225.jpg 300w, https:\/\/elinformanteperu.com\/wp-content\/uploads\/2025\/02\/MML-escaleras-SJL3-768x575.jpg 768w, https:\/\/elinformanteperu.com\/wp-content\/uploads\/2025\/02\/MML-escaleras-SJL3-1536x1150.jpg 1536w, https:\/\/elinformanteperu.com\/wp-content\/uploads\/2025\/02\/MML-escaleras-SJL3.jpg 1600w\" sizes=\"(max-width: 615px) 100vw, 615px\" \/><\/a><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Lima, 07 Agosto 2025, (ANDINA).- Una peligrosa fuga de gas se registr\u00f3 la tarde de hoy jueves 7 de agosto en el Malec\u00f3n Miguel Checa, en el distrito de San Juan de Lurigancho, generando alarma entre vecinos y obligando al cierre de v\u00edas en la zona. El hecho fue reportado a las 17.32 horas por [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":141457,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"rop_custom_images_group":[],"rop_custom_messages_group":[],"rop_publish_now":"initial","rop_publish_now_accounts":[],"rop_publish_now_history":[],"rop_publish_now_status":"pending","footnotes":""},"categories":[10],"tags":[335],"class_list":["post-141456","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualidad-municipal","tag-san-juan-de-lurigancho"],"_links":{"self":[{"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/posts\/141456","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/comments?post=141456"}],"version-history":[{"count":1,"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/posts\/141456\/revisions"}],"predecessor-version":[{"id":141458,"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/posts\/141456\/revisions\/141458"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/media\/141457"}],"wp:attachment":[{"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/media?parent=141456"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/categories?post=141456"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/tags?post=141456"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}