{"id":138998,"date":"2025-07-07T01:23:47","date_gmt":"2025-07-07T06:23:47","guid":{"rendered":"https:\/\/elinformanteperu.com\/?p=138998"},"modified":"2025-07-07T01:23:47","modified_gmt":"2025-07-07T06:23:47","slug":"universitario-derroto-1-0-al-garcilaso-y-esta-a-un-paso-de-ganar-el-apertura","status":"publish","type":"post","link":"https:\/\/elinformanteperu.com\/index.php\/2025\/07\/07\/universitario-derroto-1-0-al-garcilaso-y-esta-a-un-paso-de-ganar-el-apertura\/","title":{"rendered":"Universitario derrot\u00f3 (1-0) al Garcilaso y est\u00e1 a un paso de ganar el Apertura"},"content":{"rendered":"<p><strong><span style=\"color: #000000;\">Los cremas recuperaron la punta y ahora suman 38 puntos por lo que ganando en la \u00faltima fecha se coronar\u00e1n<\/span><\/strong><\/p>\n<p><span style=\"color: #000000;\"><strong>Cusco, 06 Julio 2025, (ANDINA).-<\/strong> Universitario de Deportes se puso a tiro de coronarse en el Torneo Apertura al ganar 1-0 a Deportivo Garcilaso en el Cusco, resultado que le permite recuperar la punta, por lo que le basta un triunfo ante Los Chancas CYC, en la \u00faltima fecha, para quedarse con el primer certamen del a\u00f1o.<\/span><\/p>\n<p><span style=\"color: #000000;\">Con gol de su capit\u00e1n Aldo Corzo, en el minuto 54, el conjunto crema sali\u00f3 un triunfazo del estadio Inca Garcilaso de la Vega, que le permite recuperar el liderato del Torneo Apertura, cuando falta una fecha para su culminaci\u00f3n.<\/span><\/p>\n<p><span style=\"color: #000000;\">El partido fue luchado de principio a fin con pocas posibilidades de gol para ambas escuadras. El conjunto merengue volvi\u00f3 a sobresalir la defensa liderada por el paraguayo William Riveros.<\/span><\/p>\n<p><span style=\"color: #000000;\">Las pocas veces que llegaron los cusque\u00f1os al arco de los lime\u00f1os, siempre estuvo bien cuadrado el arquero Sebasti\u00e1n Britos, quien fue figura.<\/span><\/p>\n<p><a href=\"https:\/\/elinformanteperu.com\/wp-content\/uploads\/2025\/07\/U-vs-Garcilaso-Apertura-25-1.jpg\"><img fetchpriority=\"high\" decoding=\"async\" class=\"size-large wp-image-139000 aligncenter\" src=\"https:\/\/elinformanteperu.com\/wp-content\/uploads\/2025\/07\/U-vs-Garcilaso-Apertura-25-1-1024x683.jpg\" alt=\"\" width=\"615\" height=\"410\" srcset=\"https:\/\/elinformanteperu.com\/wp-content\/uploads\/2025\/07\/U-vs-Garcilaso-Apertura-25-1-1024x683.jpg 1024w, https:\/\/elinformanteperu.com\/wp-content\/uploads\/2025\/07\/U-vs-Garcilaso-Apertura-25-1-300x200.jpg 300w, https:\/\/elinformanteperu.com\/wp-content\/uploads\/2025\/07\/U-vs-Garcilaso-Apertura-25-1-768x512.jpg 768w, https:\/\/elinformanteperu.com\/wp-content\/uploads\/2025\/07\/U-vs-Garcilaso-Apertura-25-1-1536x1024.jpg 1536w, https:\/\/elinformanteperu.com\/wp-content\/uploads\/2025\/07\/U-vs-Garcilaso-Apertura-25-1.jpg 1800w\" sizes=\"(max-width: 615px) 100vw, 615px\" \/><\/a><span style=\"color: #000000;\">En el segundo tiempo, Universitario volvi\u00f3 a tener el control de juego, pero en esta ocasi\u00f3n encontr\u00f3 el camino de la celebraci\u00f3n en el minuto 54, cuando Aldo Corzo apareci\u00f3 con un cabezazo para terminar en gol el buen centro que recibi\u00f3 desde la zona izquierda.<\/span><\/p>\n<p><span style=\"color: #000000;\">En el minuto 84, la &#8216;U&#8217; se qued\u00f3 con un jugador menos tras la expulsi\u00f3n de Jairo V\u00e9lez por una agresi\u00f3n. Esto hizo de que Deportivo Garcilaso tenga m\u00e1s espacios para generar peligro en los \u00faltimo minutos.<\/span><\/p>\n<p><span style=\"color: #000000;\">Con este resultado, Universitario sum\u00f3 38 unidades y desplaz\u00f3 a Alianza Lima, que pas\u00f3 al segundo puesto, con 36. Todo est\u00e1 para que el conjunto crema se consagre como ganador del Apertura porque se puso a un triunfo de coronarse.<\/span><\/p>\n<p><span style=\"color: #000000;\">En la \u00faltima jornada, la escuadra crema recibir\u00e1, el s\u00e1bado 12 de julio, en el estadio Monumental de Ate a Los Chancas CYC.<\/span><\/p>\n<p><span style=\"color: #000000;\">De ganar se consagrar\u00eda como vencedor del primer certamen. Tambi\u00e9n le sirve un empate debido a que cuenta con una amplia diferencia de goles con respecto a su m\u00e1s cercano perseguidor, el conjunto \u00edntimo.<\/span><\/p>\n<p><iframe title=\"ALDO CORZO ACERCA A LA &#039;U&#039; AL T\u00cdTULO DEL TORNEO APERTURA | Resumen Garcilaso 0-1 Universitario\" width=\"615\" height=\"346\" src=\"https:\/\/www.youtube.com\/embed\/3UnEzgtwkK4?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Los cremas recuperaron la punta y ahora suman 38 puntos por lo que ganando en la \u00faltima fecha se coronar\u00e1n Cusco, 06 Julio 2025, (ANDINA).- Universitario de Deportes se puso a tiro de coronarse en el Torneo Apertura al ganar 1-0 a Deportivo Garcilaso en el Cusco, resultado que le permite recuperar la punta, por [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":138999,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"rop_custom_images_group":[],"rop_custom_messages_group":[],"rop_publish_now":"initial","rop_publish_now_accounts":[],"rop_publish_now_history":[],"rop_publish_now_status":"pending","footnotes":""},"categories":[8,5745],"tags":[8224,7458,144],"class_list":["post-138998","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-disciplinas-deportivas","category-lo-ultimo","tag-apertura-de-la-liga-1-2025","tag-deportivo-garcilaso","tag-universitario-de-deportes"],"_links":{"self":[{"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/posts\/138998","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/comments?post=138998"}],"version-history":[{"count":1,"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/posts\/138998\/revisions"}],"predecessor-version":[{"id":139001,"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/posts\/138998\/revisions\/139001"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/media\/138999"}],"wp:attachment":[{"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/media?parent=138998"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/categories?post=138998"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/tags?post=138998"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}