{"id":12688,"date":"2017-07-07T23:24:07","date_gmt":"2017-07-08T04:24:07","guid":{"rendered":"http:\/\/elinformanteperu.com\/?p=12688"},"modified":"2017-07-07T23:24:07","modified_gmt":"2017-07-08T04:24:07","slug":"fiscales-y-peritos-policiales-continuaron-buscando-evidencias-en-galeria-nicolini","status":"publish","type":"post","link":"https:\/\/elinformanteperu.com\/index.php\/2017\/07\/07\/fiscales-y-peritos-policiales-continuaron-buscando-evidencias-en-galeria-nicolini\/","title":{"rendered":"Fiscales y peritos policiales continuaron buscando evidencias en galer\u00eda Nicolini"},"content":{"rendered":"<p><strong><span style=\"color: #000000;\">Representantes del Ministerio P\u00fablico y peritos de la Direcci\u00f3n Policial de Seguridad del Estado ingresaron a la siniestrada galer\u00eda Nicolini para seguir buscando evidencias.<\/span><\/strong><\/p>\n<p><span style=\"color: #000000;\"><strong>Lima, 07 Julio 2017, (ANDINA).-<\/strong> Representantes del Ministerio P\u00fablico y peritos de la Direcci\u00f3n Policial de Seguridad del Estado ingresaron a la siniestrada galer\u00eda Nicolini para seguir buscando evidencias que ayuden a determinar las causas del incendio y las posibles responsabilidades.<\/span><\/p>\n<p><span style=\"color: #000000;\">Al respecto, la fiscal a cargo de las investigaciones, Mar\u00eda Hinostroza Centa, dijo que solo se inspeccionan aquellos ambientes de la galer\u00eda que cuentan con luz natural.<\/span><\/p>\n<p><span style=\"color: #000000;\">\u201cHay otros ambientes que est\u00e1n muy oscuros y no se pueden examinar, por eso hoy solo vamos a trabajar en los almacenes con luz natural\u201d, explic\u00f3.<\/span><\/p>\n<p><span style=\"color: #000000;\">Sostuvo que la diligencia que se desarrolla es para determinar si existen m\u00e1s restos humanos en la galer\u00eda.<\/span><\/p>\n<p><span style=\"color: #000000;\">Junto a un grupo de ingenieros estructuralistas, Hinostroza agreg\u00f3 que durante la diligencia tambi\u00e9n se analizar\u00e1n las condiciones estructurales del edificio, luego de los da\u00f1os sufridos por el incendio.<\/span><\/p>\n<p><span style=\"color: #000000;\">Seg\u00fan inform\u00f3 el Ministerio P\u00fablico en su cuenta de Twitter, la magistrada realiz\u00f3 en la v\u00edspera una diligencia en el edificio afectado por el incendio, a fin de evaluar las condiciones del inmueble.<\/span><\/p>\n<p><span style=\"color: #000000;\">En las diligencias tambi\u00e9n participan integrantes del Cuerpo General de Bomberos Voluntarios y personal del Instituto de Medicina Legal del Ministerio P\u00fablico.<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Representantes del Ministerio P\u00fablico y peritos de la Direcci\u00f3n Policial de Seguridad del Estado ingresaron a la siniestrada galer\u00eda Nicolini para seguir buscando evidencias. Lima, 07 Julio 2017, (ANDINA).- Representantes del Ministerio P\u00fablico y peritos de la Direcci\u00f3n Policial de Seguridad del Estado ingresaron a la siniestrada galer\u00eda Nicolini para seguir buscando evidencias que ayuden [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":12689,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"rop_custom_images_group":[],"rop_custom_messages_group":[],"rop_publish_now":"initial","rop_publish_now_accounts":[],"rop_publish_now_history":[],"rop_publish_now_status":"pending","footnotes":""},"categories":[10],"tags":[1785,1540],"class_list":["post-12688","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualidad-municipal","tag-incendios","tag-las-malvinas"],"_links":{"self":[{"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/posts\/12688","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/comments?post=12688"}],"version-history":[{"count":1,"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/posts\/12688\/revisions"}],"predecessor-version":[{"id":12690,"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/posts\/12688\/revisions\/12690"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/media\/12689"}],"wp:attachment":[{"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/media?parent=12688"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/categories?post=12688"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/tags?post=12688"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}