{"id":125772,"date":"2024-10-10T01:14:03","date_gmt":"2024-10-10T06:14:03","guid":{"rendered":"https:\/\/elinformanteperu.com\/?p=125772"},"modified":"2024-10-10T01:14:03","modified_gmt":"2024-10-10T06:14:03","slug":"jefe-del-gabinete-senala-que-transportistas-formales-no-se-sumaran-a-paralizacion","status":"publish","type":"post","link":"https:\/\/elinformanteperu.com\/index.php\/2024\/10\/10\/jefe-del-gabinete-senala-que-transportistas-formales-no-se-sumaran-a-paralizacion\/","title":{"rendered":"Jefe del Gabinete se\u00f1ala que transportistas formales no se sumar\u00e1n a paralizaci\u00f3n"},"content":{"rendered":"<p><strong><span style=\"color: #000000;\">Anuncia la promulgaci\u00f3n de la ley que restituye la capacidad de conducir la investigaci\u00f3n a la polic\u00eda<\/span><\/strong><\/p>\n<p><span style=\"color: #000000;\"><strong>Lima, 09 Octubre 2024, (ANDINA).-<\/strong> El presidente del Consejo de Ministros, Gustavo Adrianz\u00e9n, indic\u00f3 que los gremios de transporte formal, que son la mayor\u00eda, no se sumar\u00e1n al paro anunciado para ma\u00f1ana por un sector de transportistas e invoc\u00f3 a la responsabilidad durante la medida de fuerza.<\/span><\/p>\n<p><span style=\"color: #000000;\">\u201cEl Per\u00fa no se detiene, debemos seguir trabajando, no le podemos hacer el juego a los desestabilizadores del gobierno que pretenden socavar el estado de derecho y la democracia\u201d, refiri\u00f3 tras la sesi\u00f3n del Consejo de Ministros.<\/span><\/p>\n<p><span style=\"color: #000000;\">Sostuvo que ma\u00f1ana operar\u00e1n con normalidad la L\u00ednea 1 y 2 del Metro de Lima; el Metropolitano en todas sus rutas y los alimentadores, as\u00ed como las unidades de las empresa de transporte formal que son la mayor\u00eda.<\/span><\/p>\n<p><span style=\"color: #000000;\">El transporte formal, seg\u00fan dijo, representa el 85% del total del transporte en Lima y Callao. Han pedido que la polic\u00eda y las Fuerzas Armadas garanticen la seguridad de sus unidades, sus rutas y de los pasajeros.<\/span><\/p>\n<p><span style=\"color: #000000;\">\u201cHay una minor\u00eda que, ajena a las demandas del transporte, levanta banderas pol\u00edticas; se han aupado gremios con prop\u00f3sitos inaceptables, quieren provocar caos, desgobierno, traer la inestabilidad\u201d, asever\u00f3.<\/span><\/p>\n<p><strong><span style=\"color: #000000;\">Acuerdos cumplidos<\/span><\/strong><\/p>\n<p><span style=\"color: #000000;\">Adrianz\u00e9n sostuvo que los compromisos asumidos en el di\u00e1logo con los transportistas que paralizaron la semana pasada, se han ido cumpliendo, como la creaci\u00f3n del grupo Gores de la polic\u00eda, la Central 111 para denunciar extorsiones, el envi\u00f3 al Congreso del proyecto sobre terrorismo urbano y se ha coordinado con el Ministerio P\u00fablico fiscal\u00edas especiales para ver casos de extorsi\u00f3n.<\/span><\/p>\n<p><span style=\"color: #000000;\">Dijo tambi\u00e9n que el Gobierno destin\u00f3 3 mil millones de soles para la construcci\u00f3n, ampliaci\u00f3n y mejoramiento de, penales. En ese marco, se ampliar\u00e1 dos pabellones en el penal de Challapalca, donde ser\u00e1n enviados los delincuentes implicados en sicariato, extorsi\u00f3n y terrorismo urbano.<\/span><\/p>\n<p><span style=\"color: #000000;\">En ese marco, el jefe del Gabinete felicit\u00f3 \u201cel talante democr\u00e1tico y la actitud consecuente\u201d de diversos gremios de transportistas formales que han decidido en forma responsable no acatar el paro, as\u00ed como de los bodegueros y las mypes.<\/span><\/p>\n<p><span style=\"color: #000000;\">Cuestion\u00f3 a quienes hacen un llamado a que el pa\u00eds paralice, en un momento en que los peruanos deben trabajar unidos para enfrentar la violencia, el sicariato, la extorsi\u00f3n y el terrorismo urbano.<\/span><\/p>\n<p><span style=\"color: #000000;\">\u201cInvocamos a la responsabilidad para que ma\u00f1ana, quienes decidan ir a protestar, lo hagan en forma pac\u00edfica y en un clima de paz y tranquilidad\u201d, asever\u00f3.<\/span><\/p>\n<p><span style=\"color: #000000;\">Precis\u00f3 que las Fuerzas Armadas y la polic\u00eda har\u00e1n prevalecer el orden y evitar\u00e1n el vandalismo en todos los distritos de Lima y Callao que se encuentran en estado de emergencia. Precis\u00f3 que las acciones preventivas se iniciar\u00e1n desde hoy.<\/span><\/p>\n<p><strong><span style=\"color: #000000;\">Promulgan ley<\/span><\/strong><\/p>\n<p><span style=\"color: #000000;\">El jefe del Gabinete Ministerial, finalmente, anunci\u00f3 que la presidenta Dina Boluarte promulg\u00f3 la ley que restituye la capacidad de conducir la investigaci\u00f3n a la Polic\u00eda Nacional, aprobada por el Congreso.<\/span><\/p>\n<p><span style=\"color: #000000;\">El jefe del Gabinete Ministerial, agreg\u00f3 que la norma fue promulgada por la mandataria y \u00abdeber\u00eda estar publicada el d\u00eda de ma\u00f1ana\u00bb.<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Anuncia la promulgaci\u00f3n de la ley que restituye la capacidad de conducir la investigaci\u00f3n a la polic\u00eda Lima, 09 Octubre 2024, (ANDINA).- El presidente del Consejo de Ministros, Gustavo Adrianz\u00e9n, indic\u00f3 que los gremios de transporte formal, que son la mayor\u00eda, no se sumar\u00e1n al paro anunciado para ma\u00f1ana por un sector de transportistas e [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":125773,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"rop_custom_images_group":[],"rop_custom_messages_group":[],"rop_publish_now":"initial","rop_publish_now_accounts":[],"rop_publish_now_history":[],"rop_publish_now_status":"pending","footnotes":""},"categories":[5],"tags":[7382,2004],"class_list":["post-125772","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualidad-informativa","tag-gustavo-adrianzen","tag-huelga"],"_links":{"self":[{"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/posts\/125772","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/comments?post=125772"}],"version-history":[{"count":1,"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/posts\/125772\/revisions"}],"predecessor-version":[{"id":125774,"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/posts\/125772\/revisions\/125774"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/media\/125773"}],"wp:attachment":[{"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/media?parent=125772"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/categories?post=125772"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/tags?post=125772"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}