{"id":119495,"date":"2024-03-25T23:56:51","date_gmt":"2024-03-26T04:56:51","guid":{"rendered":"https:\/\/elinformanteperu.com\/?p=119495"},"modified":"2024-03-25T23:56:51","modified_gmt":"2024-03-26T04:56:51","slug":"semana-santa-conoce-aqui-como-reconocer-un-taxi-autorizado-para-un-viaje-seguro","status":"publish","type":"post","link":"https:\/\/elinformanteperu.com\/index.php\/2024\/03\/25\/semana-santa-conoce-aqui-como-reconocer-un-taxi-autorizado-para-un-viaje-seguro\/","title":{"rendered":"Semana Santa: conoce aqu\u00ed c\u00f3mo reconocer un taxi autorizado para un viaje seguro"},"content":{"rendered":"<p><strong><span style=\"color: #000000;\">La ATU realiza jornadas de orientaci\u00f3n a los usuarios en paraderos y las zonas m\u00e1s concurridas<\/span><\/strong><\/p>\n<p><span style=\"color: #000000;\"><strong>Lima, 25 de Marzo 2024, (ANDINA).-<\/strong> En el marco de su campa\u00f1a \u201cMovil\u00edzate Seguro\u201d, y ante los feriados por Semana Santa, la Autoridad de Transporte Urbano para Lima y Callao (ATU) viene realizando jornadas de orientaci\u00f3n y concientizaci\u00f3n dirigida a los usuarios para que conozcan c\u00f3mo identificar un veh\u00edculo autorizado para brindar el servicio de taxi.<\/span><\/p>\n<p><span style=\"color: #000000;\">Es por ello que personal de la ATU recorre los principales paraderos y zonas de mayor demanda, como los centros comerciales, informado sobre las caracter\u00edsticas de la unidad, que se pueden distinguir a simple vista.<\/span><\/p>\n<p><span style=\"color: #000000;\">En ese sentido, mencion\u00f3 el casquete de taxi que va en la parte superior de la unidad (taxi independiente), las l\u00e1minas retrorreflectivas que van a ambos lados en la parte posterior del veh\u00edculo, las placas rotuladas, tener m\u00ednimo de cuatro puertas y un m\u00e1ximo de ocho asientos, placa con franja amarilla, entre otros.<\/span><\/p>\n<p><span style=\"color: #000000;\">Asimismo, el conductor debe contar con la cartilla informativa ubicada en la parte posterior de su asiento donde se consignan sus datos personales (nombre, DNI, foto), la modalidad del servicio de taxi (independiente o ejecutivo), la placa, color y marca del veh\u00edculo.<\/span><\/p>\n<p><span style=\"color: #000000;\">\u201cSabemos que en los feriados largos se incrementa el n\u00famero de personas que utilizan el servicio de taxi, por eso los invocamos a hacer uso de unidades formales para evitar ser v\u00edctimas de la delincuencia\u201d indic\u00f3 Jos\u00e9 Aguilar Re\u00e1tegui, presidente ejecutivo de la ATU.<\/span><\/p>\n<p><span style=\"color: #000000;\">Es importante mencionar que un taxi autorizado cuenta con revisi\u00f3n t\u00e9cnica complementaria y Seguro Obligatorio de Accidentes de Tr\u00e1nsito (SOAT) o el Certificado contra Accidentes de Tr\u00e1nsito (CAT). <\/span><\/p>\n<p><span style=\"color: #000000;\">Adem\u00e1s, los usuarios podr\u00e1n verificar la habilitaci\u00f3n vehicular ingresando a \u201c<strong><a href=\"https:\/\/sistemas.atu.gob.pe\/ConsultaVehiculo\">Consulta de Veh\u00edculos Autorizados<\/a><\/strong>\u201d (digitando la placa de rodaje) y la habilitaci\u00f3n del conductor ingresando al siguiente <a href=\"https:\/\/sistemas.atu.gob.pe\/ConsultaCredencial\/\"><strong>link<\/strong><\/a> (digitando el DNI del conductor)<\/span><\/p>\n<p><span style=\"color: #000000;\">A la fecha hay m\u00e1s de 83,000 veh\u00edculos habilitados para brindar el servicio de taxi en todas sus modalidades cumpliendo con todos los requisitos para un traslado seguro de los usuarios.<\/span><\/p>\n<p><span style=\"color: #000000;\">La ATU a trav\u00e9s de su campa\u00f1a \u201cMovil\u00edzate seguro\u201d busca tambi\u00e9n la formalizaci\u00f3n del servicio.<\/span><\/p>\n<p><span style=\"color: #000000;\">En ese sentido, para obtener la autorizaci\u00f3n, la Tarjeta \u00danica de Circulaci\u00f3n (TUC), la credencial del conductor y la cartilla informativa se debe ingresar a su <a href=\"https:\/\/sistemas.atu.gob.pe\/plataformavirtual\"><strong>plataforma virtual<\/strong><\/a> para que, en pocos minutos, se tramiten los documentos necesarios.<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La ATU realiza jornadas de orientaci\u00f3n a los usuarios en paraderos y las zonas m\u00e1s concurridas Lima, 25 de Marzo 2024, (ANDINA).- En el marco de su campa\u00f1a \u201cMovil\u00edzate Seguro\u201d, y ante los feriados por Semana Santa, la Autoridad de Transporte Urbano para Lima y Callao (ATU) viene realizando jornadas de orientaci\u00f3n y concientizaci\u00f3n dirigida [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":119496,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"rop_custom_images_group":[],"rop_custom_messages_group":[],"rop_publish_now":"initial","rop_publish_now_accounts":[],"rop_publish_now_history":[],"rop_publish_now_status":"pending","footnotes":""},"categories":[10],"tags":[5422],"class_list":["post-119495","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualidad-municipal","tag-atu"],"_links":{"self":[{"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/posts\/119495","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/comments?post=119495"}],"version-history":[{"count":1,"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/posts\/119495\/revisions"}],"predecessor-version":[{"id":119497,"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/posts\/119495\/revisions\/119497"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/media\/119496"}],"wp:attachment":[{"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/media?parent=119495"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/categories?post=119495"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/tags?post=119495"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}