{"id":118358,"date":"2023-10-21T20:41:52","date_gmt":"2023-10-22T01:41:52","guid":{"rendered":"https:\/\/elinformanteperu.com\/?p=118358"},"modified":"2023-10-21T20:42:05","modified_gmt":"2023-10-22T01:42:05","slug":"la-evolucion-de-loki-nueva-temporada-revela-aspectos-del-dios-de-las-mentiras","status":"publish","type":"post","link":"https:\/\/elinformanteperu.com\/index.php\/2023\/10\/21\/la-evolucion-de-loki-nueva-temporada-revela-aspectos-del-dios-de-las-mentiras\/","title":{"rendered":"La evoluci\u00f3n de Loki: Nueva temporada revela aspectos del Dios de las Mentiras"},"content":{"rendered":"<p><strong><span style=\"color: #000000;\">Ya se encuentra disponible \u201cA lo largo de los a\u00f1os\u201d, un nuevo contenido adicional en el que Kevin Feige, Kevin R. Wright y Tom Hiddleston reflexionan sobre el recorrido de Loki en el Universo Cinematogr\u00e1fico de Marvel<\/span><\/strong><\/p>\n<p><span style=\"color: #000000;\"><strong>Lima, 21 Octubre 2023, (El Informante Per\u00fa).-<\/strong> En la nueva temporada, se encuentra al Dios de las Mentiras (Tom Hiddleston) lidiando con nuevos peligros internos y externos que amenazan a la Autoridad de Variaci\u00f3n Temporal (AVT). Con una guerra en el horizonte, Loki se encuentra librando una batalla para salvar la AVT con Mobius (Owen Wilson), la Cazadora B-15 (Wunmi Mosaku), y junto a personajes nuevos y otros ya conocidos.<\/span><\/p>\n<p><span style=\"color: #000000;\">Estas amenazas traer\u00e1n momentos imperdibles de tensi\u00f3n y acci\u00f3n, pero sobre todo revelar\u00e1n aspectos de la personalidad de Loki que no se han visto hasta ahora. En este sentido, la nueva temporada de la serie es testigo de una aut\u00e9ntica evoluci\u00f3n de este ic\u00f3nico personaje de Marvel.<\/span><\/p>\n<p><span style=\"color: #000000;\">La segunda temporada de Loki de Marvel Studios ya se puede ver exclusivamente en Disney+ y estrena nuevos episodios todos los jueves a las 20:00 horas. \u201cA lo largo de los a\u00f1os\u201d, un nuevo contenido adicional que recorre el camino de Loki en el Universo Cinematogr\u00e1fico de Marvel (MCU por sus siglas en ingl\u00e9s), ya se encuentra disponible.<\/span><\/p>\n<p><strong><span style=\"color: #000000;\">Tom Hiddleston, el capit\u00e1n del \u00abBarco Loki\u00bb<\/span><\/strong><\/p>\n<p><a href=\"https:\/\/elinformanteperu.com\/wp-content\/uploads\/2023\/10\/loki-segunda-temporada1.png\"><img fetchpriority=\"high\" decoding=\"async\" class=\"size-full wp-image-118360 aligncenter\" src=\"https:\/\/elinformanteperu.com\/wp-content\/uploads\/2023\/10\/loki-segunda-temporada1.png\" alt=\"\" width=\"917\" height=\"611\" srcset=\"https:\/\/elinformanteperu.com\/wp-content\/uploads\/2023\/10\/loki-segunda-temporada1.png 917w, https:\/\/elinformanteperu.com\/wp-content\/uploads\/2023\/10\/loki-segunda-temporada1-300x200.png 300w, https:\/\/elinformanteperu.com\/wp-content\/uploads\/2023\/10\/loki-segunda-temporada1-768x512.png 768w\" sizes=\"(max-width: 917px) 100vw, 917px\" \/><\/a><span style=\"color: #000000;\">Dice Tom Hiddleston en este nuevo contenido: \u201cLo que me encant\u00f3 de interpretar a Loki es que abarca diferentes rangos. Puede ser divertido, c\u00f3mico, pero tambi\u00e9n vol\u00e1til y col\u00e9rico\u201d.<\/span><\/p>\n<p><span style=\"color: #000000;\">La evoluci\u00f3n de Loki cobra vida en parte por la impronta que le da Tom, quien lo viene interpretando desde su primera aparici\u00f3n en el MCU, all\u00e1 por 2011 en la pel\u00edcula THOR. Con m\u00e1s de una d\u00e9cada en la piel de Loki, Hiddleston sabe intuitivamente lo que tiene sentido para el personaje y c\u00f3mo actuar\u00eda en distintas situaciones. Su conocimiento, a su vez, result\u00f3 una gu\u00eda imprescindible para el resto del elenco, la producci\u00f3n y el equipo de directores.<\/span><\/p>\n<p><span style=\"color: #000000;\">\u201cNos encanta cuando encontramos la manera de que un personaje tenga un gran peso. Pero con Loki, vimos que ya desde el comienzo ten\u00eda un enorme trauma y una gran carga emocional. Tom entiende eso instintivamente a un nivel que nosotros solo podemos aspirar\u201d, se\u00f1ala el codirector de la serie Aaron Moorhead, y remata: \u201c\u00c9l es realmente el capit\u00e1n del barco Loki\u201d.<\/span><\/p>\n<p><strong><span style=\"color: #000000;\">Salvando la AVT<\/span><\/strong><\/p>\n<p><a href=\"https:\/\/elinformanteperu.com\/wp-content\/uploads\/2023\/10\/loki-segunda-temporada2.png\"><img decoding=\"async\" class=\"size-full wp-image-118361 aligncenter\" src=\"https:\/\/elinformanteperu.com\/wp-content\/uploads\/2023\/10\/loki-segunda-temporada2.png\" alt=\"\" width=\"923\" height=\"614\" srcset=\"https:\/\/elinformanteperu.com\/wp-content\/uploads\/2023\/10\/loki-segunda-temporada2.png 923w, https:\/\/elinformanteperu.com\/wp-content\/uploads\/2023\/10\/loki-segunda-temporada2-300x200.png 300w, https:\/\/elinformanteperu.com\/wp-content\/uploads\/2023\/10\/loki-segunda-temporada2-768x511.png 768w\" sizes=\"(max-width: 923px) 100vw, 923px\" \/><\/a><span style=\"color: #000000;\">En el \u00faltimo episodio de la primera temporada, Loki regresa a la AVT tras la fat\u00eddica decisi\u00f3n de Sylvie (Sophia Di Martino) de matar a Aquel Que Permanece (Jonathan Majors). Como consecuencia, el comienzo de la segunda temporada encuentra a Loki descubriendo que las cosas se ven muy distintas a como estaban cuando las dej\u00f3. Los desfases temporales est\u00e1n a la orden del d\u00eda y nadie est\u00e1 regulando las l\u00edneas del tiempo, y mucho menos el Telar Temporal, que est\u00e1 sobrecargado y muy cerca de estallar.<\/span><\/p>\n<p><span style=\"color: #000000;\">Explica el guionista Eric Martin: \u201cEn la primera temporada, el tema era desbaratar la AVT y en la segunda, el tema es mantenerla unida\u201d. En este contexto, la prueba para Loki es estar a la altura de las circunstancias. Habiendo luchado siempre con la noci\u00f3n de que \u00e9l era inherentemente malo y que estaba siempre condenado a empeorar las cosas, la nueva temporada lo lleva a sacrificarse para proteger a la gente que quiere. Loki se da cuenta de que, si bien quiere salvar la AVT, en realidad es a sus amigos a los que m\u00e1s quiere proteger.<\/span><\/p>\n<p><strong><span style=\"color: #000000;\">Una familia elegida que merece ser protegida<\/span><\/strong><\/p>\n<p><a href=\"https:\/\/elinformanteperu.com\/wp-content\/uploads\/2023\/10\/loki-segunda-temporada3.png\"><img decoding=\"async\" class=\"size-full wp-image-118362 aligncenter\" src=\"https:\/\/elinformanteperu.com\/wp-content\/uploads\/2023\/10\/loki-segunda-temporada3.png\" alt=\"\" width=\"919\" height=\"614\" srcset=\"https:\/\/elinformanteperu.com\/wp-content\/uploads\/2023\/10\/loki-segunda-temporada3.png 919w, https:\/\/elinformanteperu.com\/wp-content\/uploads\/2023\/10\/loki-segunda-temporada3-300x200.png 300w, https:\/\/elinformanteperu.com\/wp-content\/uploads\/2023\/10\/loki-segunda-temporada3-768x513.png 768w\" sizes=\"(max-width: 919px) 100vw, 919px\" \/><\/a><span style=\"color: #000000;\">S\u00ed, Loki tiene su c\u00edrculo de seres queridos. Antes del desembarco de la serie que lleva su nombre, el Dios de las Mentiras estaba asociado dentro del MCU a su familia asgardiana un tanto disfuncional: su medio hermano Thor (Chris Hemsworth) y su padre Od\u00edn (Anthony Hopkins). En Loki encontr\u00f3 una nueva familia. Explica Hiddleston: \u201cLuego de que Mobius y sus colegas de la AVT expusieran, destrozaran y reconstruyeran su sentido de identidad; y tambi\u00e9n luego de su conexi\u00f3n con Sylvie, Loki adquiri\u00f3 una nueva capacidad, una nueva consciencia para establecer conexiones con los dem\u00e1s y \u00e9l se da cuenta de que esas conexiones son todo lo que importa realmente, y que son conexiones que \u00e9l quiere conservar\u201d.<\/span><\/p>\n<p><span style=\"color: #000000;\">Contin\u00faa Martin: \u201cLo que Loki encontr\u00f3 en la AVT fue un hogar. Encontr\u00f3 a Mobius, que se convirti\u00f3 en probablemente su primer amigo de verdad de su vida. La AVT es un lugar que lo acept\u00f3. Es como una especie de isla de inadaptados, y \u00e9l encontr\u00f3 una manera de crear una vida para s\u00ed all\u00ed. Ahora es su hogar, y \u00e9l quiere protegerlo\u201d.<\/span><\/p>\n<p><span style=\"color: #000000;\">\u00abEs un personaje que, desde que lo he interpretado, ha estado buscando significado. Incluso cuando no era consciente de ello, estaba lleno de agravios, ira y desestabilizaci\u00f3n emocional porque no sent\u00eda que tuviera un prop\u00f3sito o significado. Estaba buscando significado en los lugares equivocados y ahora creo que ha encontrado una manera de darse un prop\u00f3sito, que es intentar reorganizarse, ayudar a Mobius, a la Cazadora B-15 y a la AVT\u201d, concluye Hiddleston.<\/span><\/p>\n<p><span style=\"color: #000000;\">La nueva temporada de Loki ya est\u00e1 disponible exclusivamente en Disney+ y presenta nuevos episodios todos los jueves a las 20:00 horas.<\/span><\/p>\n<p><iframe title=\"YouTube video player\" src=\"https:\/\/www.youtube-nocookie.com\/embed\/ApR5AS_-Ak4?si=_cxjigcSxF7RQA3g&amp;controls=0\" width=\"520\" height=\"315\" frameborder=\"0\" allowfullscreen=\"allowfullscreen\"><\/iframe><\/p>\n<p><iframe title=\"YouTube video player\" src=\"https:\/\/www.youtube-nocookie.com\/embed\/9h-ZlP-YmdU?si=Hi4FcZHxnOshgYsE&amp;controls=0\" width=\"520\" height=\"315\" frameborder=\"0\" allowfullscreen=\"allowfullscreen\"><span data-mce-type=\"bookmark\" style=\"display: inline-block; width: 0px; overflow: hidden; line-height: 0;\" class=\"mce_SELRES_start\">\ufeff<\/span><\/iframe><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ya se encuentra disponible \u201cA lo largo de los a\u00f1os\u201d, un nuevo contenido adicional en el que Kevin Feige, Kevin R. Wright y Tom Hiddleston reflexionan sobre el recorrido de Loki en el Universo Cinematogr\u00e1fico de Marvel Lima, 21 Octubre 2023, (El Informante Per\u00fa).- En la nueva temporada, se encuentra al Dios de las Mentiras [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":118359,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"rop_custom_images_group":[],"rop_custom_messages_group":[],"rop_publish_now":"initial","rop_publish_now_accounts":[],"rop_publish_now_history":[],"rop_publish_now_status":"pending","footnotes":""},"categories":[70,5745],"tags":[6053,6437],"class_list":["post-118358","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-farandula","category-lo-ultimo","tag-disney-plus","tag-loki"],"_links":{"self":[{"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/posts\/118358","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/comments?post=118358"}],"version-history":[{"count":1,"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/posts\/118358\/revisions"}],"predecessor-version":[{"id":118363,"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/posts\/118358\/revisions\/118363"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/media\/118359"}],"wp:attachment":[{"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/media?parent=118358"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/categories?post=118358"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/tags?post=118358"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}