{"id":115765,"date":"2022-07-10T22:55:34","date_gmt":"2022-07-11T03:55:34","guid":{"rendered":"https:\/\/elinformanteperu.com\/?p=115765"},"modified":"2022-07-10T22:55:34","modified_gmt":"2022-07-11T03:55:34","slug":"servir-implementa-sistema-de-citas-virtuales-para-atencion-de-consultas-laborales","status":"publish","type":"post","link":"https:\/\/elinformanteperu.com\/index.php\/2022\/07\/10\/servir-implementa-sistema-de-citas-virtuales-para-atencion-de-consultas-laborales\/","title":{"rendered":"SERVIR implementa sistema de citas virtuales para atenci\u00f3n de consultas laborales"},"content":{"rendered":"<p><span style=\"color: #000000;\"><strong>Lima, 10 de Julio 2022, (El Informante Per\u00fa).-<\/strong> Como parte de su compromiso de brindar asistencia t\u00e9cnica en materia de consultas laborales en la administraci\u00f3n p\u00fablica, la Autoridad Nacional del Servicio Civil \u2013 SERVIR pone a disposici\u00f3n de los servidores p\u00fablicos de todo el pa\u00eds su nuevo sistema de citas para atenci\u00f3n virtual especializada.<\/span><\/p>\n<p><span style=\"color: #000000;\">Este sistema se encuentra disponible desde el 1 de julio del presente a\u00f1o y permite que los servidores civiles puedan agendar una cita con un especialista de la entidad, quien se comunicar\u00e1 con el solicitante en el d\u00eda y horario que esta persona elija al momento de la solicitud.<\/span><\/p>\n<p><strong><span style=\"color: #000000;\">\u00bfC\u00f3mo acceder al sistema de citas virtuales de SERVIR?<\/span><\/strong><\/p>\n<p><span style=\"color: #000000;\">Para acceder al sistema de citas en l\u00ednea deben acceder al formulario de registro que se encuentra disponible en nuestra p\u00e1gina web: <strong>www.gob.pe\/servir<\/strong>; o tambi\u00e9n a trav\u00e9s del siguiente <a href=\"https:\/\/docs.google.com\/forms\/d\/e\/1FAIpQLSd1MQGjm7qpSMBkXxI2GliLZVboKbsZVgmHs-nj6R0FMMCKFg\/formResponse\"><strong>enlace<\/strong><\/a>.\u00a0<\/span><\/p>\n<p><strong><span style=\"color: #000000;\">\u00bfC\u00f3mo programar una cita virtual con un especialista de SERVIR?<\/span><\/strong><\/p>\n<p><span style=\"color: #000000;\">Para separar una cita, el servidor deber\u00e1 completar sus datos personales, se\u00f1alar el tema de consulta y seleccionar el momento en el que desea ser contactado. Luego de ello, SERVIR remitir\u00e1 al usuario, a trav\u00e9s de correo electr\u00f3nico, el enlace por d\u00f3nde se realizar\u00e1 la videollamada.<\/span><\/p>\n<p><span style=\"color: #000000;\">El tiempo estimado de atenci\u00f3n es de quince minutos. Por ello, es importante que el usuario tenga claro el tema de la consulta y preparadas las preguntas que quiere hacer al respecto.<\/span><\/p>\n<p><strong><span style=\"color: #000000;\">\u00bfQu\u00e9 temas se pueden abordar en la cita virtual?<\/span><\/strong><\/p>\n<p><span style=\"color: #000000;\">Una vez en la cita virtual, el o la especialista asignada atender\u00e1 preguntas relacionadas a temas laborales en la administraci\u00f3n p\u00fablica.<\/span><\/p>\n<p><span style=\"color: #000000;\">Es importante saber que SERVIR no atiende sobre los siguientes temas porque no son parte de sus competencias:<\/span><\/p>\n<p><span style=\"color: #000000;\">&#8211; Ingresos del personal del sector p\u00fablico (remuneraciones, bonificaciones, asignaciones, incentivos, otros de similar naturaleza, etc.).<\/span><\/p>\n<p><span style=\"color: #000000;\">&#8211; Contratos de locaci\u00f3n de servicios.<\/span><\/p>\n<p><span style=\"color: #000000;\">&#8211; Patrocinio legal individual.<\/span><\/p>\n<p><span style=\"color: #000000;\">&#8211; Casos judicializados.<\/span><\/p>\n<p><span style=\"color: #000000;\">&#8211; Verificaci\u00f3n de liquidaciones.<\/span><\/p>\n<p><span style=\"color: #000000;\">&#8211; Reconocimiento de subsidios y pensiones.<\/span><\/p>\n<p><strong><span style=\"color: #000000;\">\u00bfQu\u00e9 puedo hacer si tengo otras consultas que no est\u00e1n relacionadas al tema?<\/span><\/strong><\/p>\n<p><span style=\"color: #000000;\">Si tiene consultas sobre instrumentos de gesti\u00f3n y tr\u00e1nsito al r\u00e9gimen de la Ley 30057, puede comunicarse al tel\u00e9fono 01-2063370 opci\u00f3n 5.<\/span><\/p>\n<p><span style=\"color: #000000;\">Si la consulta es sobre recursos de apelaci\u00f3n ante el Tribunal del Servicio Civil, comun\u00edquese al tel\u00e9fono 01-2063370 opci\u00f3n 1 y luego la opci\u00f3n 3.<\/span><\/p>\n<p><span style=\"color: #000000;\">Adem\u00e1s, si tiene alguna duda sobre el proceso o sobre alg\u00fan otro tema que es competencia de SERVIR, puede escribirnos a info@servir.gob.pe<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Lima, 10 de Julio 2022, (El Informante Per\u00fa).- Como parte de su compromiso de brindar asistencia t\u00e9cnica en materia de consultas laborales en la administraci\u00f3n p\u00fablica, la Autoridad Nacional del Servicio Civil \u2013 SERVIR pone a disposici\u00f3n de los servidores p\u00fablicos de todo el pa\u00eds su nuevo sistema de citas para atenci\u00f3n virtual especializada. Este [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":115766,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"rop_custom_images_group":[],"rop_custom_messages_group":[],"rop_publish_now":"initial","rop_publish_now_accounts":[],"rop_publish_now_history":[],"rop_publish_now_status":"pending","footnotes":""},"categories":[10,5746,21],"tags":[1757],"class_list":["post-115765","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualidad-municipal","category-foto-noticias","category-orientacion","tag-servir"],"_links":{"self":[{"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/posts\/115765","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/comments?post=115765"}],"version-history":[{"count":1,"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/posts\/115765\/revisions"}],"predecessor-version":[{"id":115767,"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/posts\/115765\/revisions\/115767"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/media\/115766"}],"wp:attachment":[{"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/media?parent=115765"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/categories?post=115765"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/tags?post=115765"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}