{"id":112728,"date":"2022-03-04T23:10:44","date_gmt":"2022-03-05T04:10:44","guid":{"rendered":"https:\/\/elinformanteperu.com\/?p=112728"},"modified":"2022-03-04T23:17:30","modified_gmt":"2022-03-05T04:17:30","slug":"doctor-strange-benedict-cumberbatch-recibio-una-estrella-en-el-paseo-de-la-fama","status":"publish","type":"post","link":"https:\/\/elinformanteperu.com\/index.php\/2022\/03\/04\/doctor-strange-benedict-cumberbatch-recibio-una-estrella-en-el-paseo-de-la-fama\/","title":{"rendered":"Doctor Strange: Benedict Cumberbatch recibi\u00f3 una estrella en el Paseo de la Fama"},"content":{"rendered":"<p><strong><span style=\"color: #000000;\">A dos meses de la primera pel\u00edcula de Marvel Studios que se estrenar\u00e1 en 2022, Doctor Strange en el multiverso de la locura, donde Benedict Cumberbatch volver\u00e1 a interpretar al poderoso Vengador en una historia donde veremos diferentes versiones de los personajes m\u00e1s importantes.<\/span><\/strong><\/p>\n<p><span style=\"color: #000000;\"><strong>Lima, 04 Marzo 2022, (El Informante Per\u00fa).<\/strong>&#8211; Benedict Cumberbatch ha sido honrado con una estrella en el Paseo de la Fama de Hollywood. En la ceremonia estuvo presente Kevin Feige y dijo:<\/span><\/p>\n<p><span style=\"color: #000000;\">\u00abHay tantos papeles que has interpretado que te han hecho merecedor de este prestigioso honor. Fuiste un Hamlet incre\u00edble. Tambi\u00e9n fuiste un Sherlock Holmes incre\u00edble. Fuiste el segundo mejor Khan de la historia. Estuviste brillante en todos los roles ic\u00f3nicos, pero para nosotros y para millones en todo el mundo, te mereces este honor por ser el primero, el mejor, el m\u00e1s grande y el \u00fanico Doctor Strange\u00bb.<\/span><\/p>\n<p><span style=\"color: #000000;\">\u00abRecuerdo que nuestra primera reuni\u00f3n fue organizada como general, y quer\u00edamos presentarle este gran personaje, y antes de que pudi\u00e9ramos, dijo: Cu\u00e9ntame sobre Doctor Strange. Porque lo sab\u00edas. Porque en alg\u00fan lugar sab\u00edas qu\u00e9 era esto. Podr\u00eda ser y siempre has visto el tremendo potencial de este personaje. Por eso, te has convertido en el ancla de la MCU y el \u00fanico actor capaz de guiarnos a trav\u00e9s de la locura del Multiverso\u00bb.<\/span><\/p>\n<p><a href=\"https:\/\/elinformanteperu.com\/wp-content\/uploads\/2022\/03\/Doctor-Strange-Benedict-Cumberbatch-paseo-fama1.jpg\"><img fetchpriority=\"high\" decoding=\"async\" class=\" wp-image-112730 aligncenter\" src=\"https:\/\/elinformanteperu.com\/wp-content\/uploads\/2022\/03\/Doctor-Strange-Benedict-Cumberbatch-paseo-fama1.jpg\" alt=\"\" width=\"339\" height=\"390\" srcset=\"https:\/\/elinformanteperu.com\/wp-content\/uploads\/2022\/03\/Doctor-Strange-Benedict-Cumberbatch-paseo-fama1.jpg 409w, https:\/\/elinformanteperu.com\/wp-content\/uploads\/2022\/03\/Doctor-Strange-Benedict-Cumberbatch-paseo-fama1-261x300.jpg 261w\" sizes=\"(max-width: 339px) 100vw, 339px\" \/><\/a><span style=\"color: #000000;\">\u00bfDe qu\u00e9 tratar\u00e1 Doctor Strange en el multiverso de la locura?<\/span><\/p>\n<p><span style=\"color: #000000;\">Despu\u00e9s de poder ver a Benedict Cumberbatch en Spider-Man: No Way Home (2021), el actor regresar\u00e1 en la nueva entrega del Hechicero Supremo de Marvel Studios. Esta vez deber\u00e1 viajar por diferentes realidades para poder salvar al Universo de un gran peligro.<\/span><\/p>\n<p><span style=\"color: #000000;\">Doctor Strange en el multiverso de la locura se estrenar\u00e1 el 5 de mayo de 2022, en todos los cines del pa\u00eds.<\/span><\/p>\n<p><a href=\"https:\/\/elinformanteperu.com\/wp-content\/uploads\/2022\/03\/Doctor-Strange-Benedict-Cumberbatch-paseo-fama2.jpg\"><img decoding=\"async\" class=\" wp-image-112731 aligncenter\" src=\"https:\/\/elinformanteperu.com\/wp-content\/uploads\/2022\/03\/Doctor-Strange-Benedict-Cumberbatch-paseo-fama2.jpg\" alt=\"\" width=\"308\" height=\"383\" srcset=\"https:\/\/elinformanteperu.com\/wp-content\/uploads\/2022\/03\/Doctor-Strange-Benedict-Cumberbatch-paseo-fama2.jpg 408w, https:\/\/elinformanteperu.com\/wp-content\/uploads\/2022\/03\/Doctor-Strange-Benedict-Cumberbatch-paseo-fama2-241x300.jpg 241w\" sizes=\"(max-width: 308px) 100vw, 308px\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>A dos meses de la primera pel\u00edcula de Marvel Studios que se estrenar\u00e1 en 2022, Doctor Strange en el multiverso de la locura, donde Benedict Cumberbatch volver\u00e1 a interpretar al poderoso Vengador en una historia donde veremos diferentes versiones de los personajes m\u00e1s importantes. Lima, 04 Marzo 2022, (El Informante Per\u00fa).&#8211; Benedict Cumberbatch ha sido [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":112733,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"rop_custom_images_group":[],"rop_custom_messages_group":[],"rop_publish_now":"initial","rop_publish_now_accounts":[],"rop_publish_now_history":[],"rop_publish_now_status":"pending","footnotes":""},"categories":[7],"tags":[943,3349],"class_list":["post-112728","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-butaca","tag-benedict-cumberbatch","tag-doctor-strange"],"_links":{"self":[{"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/posts\/112728","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/comments?post=112728"}],"version-history":[{"count":1,"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/posts\/112728\/revisions"}],"predecessor-version":[{"id":112732,"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/posts\/112728\/revisions\/112732"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/media\/112733"}],"wp:attachment":[{"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/media?parent=112728"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/categories?post=112728"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/tags?post=112728"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}