{"id":110726,"date":"2022-01-16T18:26:57","date_gmt":"2022-01-16T23:26:57","guid":{"rendered":"https:\/\/elinformanteperu.com\/?p=110726"},"modified":"2022-01-16T18:26:57","modified_gmt":"2022-01-16T23:26:57","slug":"bolivia-reporta-dos-contagios-de-la-covid-19-en-delegacion-para-eliminatorias","status":"publish","type":"post","link":"https:\/\/elinformanteperu.com\/index.php\/2022\/01\/16\/bolivia-reporta-dos-contagios-de-la-covid-19-en-delegacion-para-eliminatorias\/","title":{"rendered":"Bolivia reporta dos contagios de la covid-19 en delegaci\u00f3n para eliminatorias"},"content":{"rendered":"<p><span style=\"color: #000000;\"><strong>Lima, 16 Enero 2022, (ANDINA).<\/strong>&#8211; La delegaci\u00f3n boliviana que inici\u00f3 la concentraci\u00f3n con miras a las pr\u00f3ximas fechas de las eliminatorias sudamericanas del Mundial de Catar 2022 report\u00f3 este domingo dos contagios de la covid-19.<\/span><\/p>\n<p><span style=\"color: #000000;\">Los contagiados son el futbolista Alexis Ribera y un miembro del cuerpo m\u00e9dico de la Verde, precis\u00f3 la Federaci\u00f3n Boliviana de F\u00fatbol en un comunicado de prensa.<\/span><\/p>\n<p><span style=\"color: #000000;\">Ambos \u00abson asintom\u00e1ticos y comenzaron con el tratamiento m\u00e9dico correspondiente\u00bb, agrega la nota.<\/span><\/p>\n<p><span style=\"color: #000000;\">Ribera, que milita en el Oriente Petrolero, fue incluido a \u00faltimo momento en la convocatoria del seleccionador de Bolivia, el venezolano C\u00e9sar Far\u00edas, para enfrentar a Venezuela y Chile en las pr\u00f3ximas fechas de las eliminatorias y un amistoso previo con Trinidad y Tobago.<\/span><\/p>\n<p><span style=\"color: #000000;\">Ocho de los 27 jugadores llamados por Far\u00edas ya se encuentran en la concentraci\u00f3n en La Paz, mientras que el The Strongest inform\u00f3 que sus cuatro futbolistas convocados se unir\u00e1n en las pr\u00f3ximas horas.<\/span><\/p>\n<p><span style=\"color: #000000;\">La FBF precis\u00f3 que los internacionales Luis Haqu\u00edn y Marcelo Martins Moreno, el m\u00e1ximo goleador de la clasificatoria sudamericana, se incorporar\u00e1n el lunes.<\/span><\/p>\n<p><span style=\"color: #000000;\">Adem\u00e1s de Ribera, el Bol\u00edvar de La Paz inform\u00f3 m\u00e1s temprano que cinco de los ocho jugadores &#8216;celestes&#8217; convocados a la selecci\u00f3n dieron positivo a la covid-19 y los otros tres ya se sumaron a la concentraci\u00f3n.<\/span><\/p>\n<p><span style=\"color: #000000;\">Bolivia visitar\u00e1 a Venezuela el 28 de enero en la decimoquinta jornada de las eliminatorias y recibir\u00e1 en La Paz a Chile el 1 de febrero por la decimosexta fecha.<\/span><\/p>\n<p><span style=\"color: #000000;\">Aunque va octava en la clasificaci\u00f3n sudamericana, la Verde de Far\u00edas no pierde la esperanza de lograr un cupo a Catar 2022 o al menos aspirar a la repesca.<\/span><\/p>\n<p><span style=\"color: #000000;\">La selecci\u00f3n boliviana tiene 15 puntos, dos menos que Colombia y Per\u00fa y uno menos que Chile y Uruguay.<\/span><\/p>\n<p><span style=\"color: #000000;\">Antes de los partidos de eliminatorias, la Verde se enfrentar\u00e1 el 21 de enero a su similar de Trinidad y Tobago en un amistoso en Sucre, la capital constitucional boliviana.<\/span><\/p>\n<blockquote class=\"twitter-tweet\">\n<p dir=\"ltr\" lang=\"es\">\ud83c\udde7\ud83c\uddf4PARTE M\u00c9DICO \ud83c\udde7\ud83c\uddf4 <a href=\"https:\/\/t.co\/v9hF18IcSy\">pic.twitter.com\/v9hF18IcSy<\/a><\/p>\n<p>\u2014 Federaci\u00f3n Boliviana de F\u00fatbol (@FBF_BO) <a href=\"https:\/\/twitter.com\/FBF_BO\/status\/1482755487783399430?ref_src=twsrc%5Etfw\">January 16, 2022<\/a><\/p><\/blockquote>\n<p><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Lima, 16 Enero 2022, (ANDINA).&#8211; La delegaci\u00f3n boliviana que inici\u00f3 la concentraci\u00f3n con miras a las pr\u00f3ximas fechas de las eliminatorias sudamericanas del Mundial de Catar 2022 report\u00f3 este domingo dos contagios de la covid-19. Los contagiados son el futbolista Alexis Ribera y un miembro del cuerpo m\u00e9dico de la Verde, precis\u00f3 la Federaci\u00f3n Boliviana [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":110727,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"rop_custom_images_group":[],"rop_custom_messages_group":[],"rop_publish_now":"initial","rop_publish_now_accounts":[],"rop_publish_now_history":[],"rop_publish_now_status":"pending","footnotes":""},"categories":[8],"tags":[168,4106],"class_list":["post-110726","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-disciplinas-deportivas","tag-bolivia","tag-eliminatorias-catar-2022"],"_links":{"self":[{"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/posts\/110726","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/comments?post=110726"}],"version-history":[{"count":1,"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/posts\/110726\/revisions"}],"predecessor-version":[{"id":110728,"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/posts\/110726\/revisions\/110728"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/media\/110727"}],"wp:attachment":[{"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/media?parent=110726"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/categories?post=110726"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/tags?post=110726"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}