{"id":110719,"date":"2022-01-16T17:02:46","date_gmt":"2022-01-16T22:02:46","guid":{"rendered":"https:\/\/elinformanteperu.com\/?p=110719"},"modified":"2022-01-16T17:02:46","modified_gmt":"2022-01-16T22:02:46","slug":"elecciones-2022-ap-participara-en-todas-las-regiones-y-municipios-posibles","status":"publish","type":"post","link":"https:\/\/elinformanteperu.com\/index.php\/2022\/01\/16\/elecciones-2022-ap-participara-en-todas-las-regiones-y-municipios-posibles\/","title":{"rendered":"Elecciones 2022: AP participar\u00e1 en todas las regiones y municipios posibles"},"content":{"rendered":"<p><strong><span style=\"color: #000000;\">Afirma Mes\u00edas Guevara, presidente de dicha agrupaci\u00f3n pol\u00edtica<\/span><\/strong><\/p>\n<p><span style=\"color: #000000;\"><strong>Lima, 16 Enero 2022, (ANDINA).-<\/strong> El presidente de Acci\u00f3n Popular (AP), Mes\u00edas Guevara, afirm\u00f3 que el objetivo de esta agrupaci\u00f3n pol\u00edtica es participar en el proceso de elecciones de este a\u00f1o en todas las regiones y municipios que se pueda.<\/span><\/p>\n<p><span style=\"color: #000000;\">En declaraciones a la Agencia Andina, manifest\u00f3 que aplicar\u00e1n la modalidad de un militante un voto en el proceso interno que se convocar\u00e1 en breve, con la finalidad de que todos los inscritos en el partido elijan a sus candidatos.<\/span><\/p>\n<p><span style=\"color: #000000;\">\u00abAcci\u00f3n Popular, en estos momentos, est\u00e1 con un objetivo: seg\u00fan la planificaci\u00f3n que venimos desarrollando, participemos en todas las regiones y todos los municipios que podamos\u00bb, manifest\u00f3.<\/span><\/p>\n<p><span style=\"color: #000000;\">Lea tambi\u00e9n: Somos Per\u00fa decidir\u00e1 candidato a alcald\u00eda de Lima mediante un militante un voto<\/span><\/p>\n<p><span style=\"color: #000000;\">Asimismo, indic\u00f3 que ser\u00e1 dif\u00edcil abarcar los m\u00e1s de 1,800 municipalidades en todo el pa\u00eds, pero se har\u00e1 el esfuerzo con miras al proceso de elecciones regionales y municipales del mes de octubre.<\/span><\/p>\n<p><span style=\"color: #000000;\">Adem\u00e1s, adelant\u00f3 que como presidente del partido convocar\u00e1 a un plenario para el 21 de enero, a fin de consolidar los acuerdos y participar activamente en el proceso electoral.<\/span><\/p>\n<p><span style=\"color: #000000;\">\u00abVamos a convocar este plenario solo y exclusivamente, como siempre lo hemos hecho, para fijar las reglas y las normas internas para poder participar, siempre lo hicimos de esa manera, y este tiene que ser el 21 de enero para cumplir el plazo interno que son cinco d\u00edas h\u00e1biles\u00bb, asegur\u00f3.<\/span><\/p>\n<p><strong><span style=\"color: #000000;\">Lima<\/span><\/strong><\/p>\n<p><span style=\"color: #000000;\">En cuanto a los precandidatos a la alcald\u00eda de Lima Metropolitana, adelant\u00f3 que hasta el momento hay tres, de entre los cuales saldr\u00e1 el que competir\u00e1 en la justa electoral y luego de la elecci\u00f3n interna, puesto que en Acci\u00f3n Popular \u00abno definimos candidatos a dedo\u00bb.<\/span><\/p>\n<p><span style=\"color: #000000;\">\u00abTengo entendido que estar\u00e1n participando el alcalde de San Borja, Alberto Tejada; el alcalde de Ate, Edde Cu\u00e9llar; y el exregidor de Lima, Luis Enrique G\u00e1lvez\u00bb, refiri\u00f3.<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Afirma Mes\u00edas Guevara, presidente de dicha agrupaci\u00f3n pol\u00edtica Lima, 16 Enero 2022, (ANDINA).- El presidente de Acci\u00f3n Popular (AP), Mes\u00edas Guevara, afirm\u00f3 que el objetivo de esta agrupaci\u00f3n pol\u00edtica es participar en el proceso de elecciones de este a\u00f1o en todas las regiones y municipios que se pueda. En declaraciones a la Agencia Andina, manifest\u00f3 [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":64248,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"rop_custom_images_group":[],"rop_custom_messages_group":[],"rop_publish_now":"initial","rop_publish_now_accounts":[],"rop_publish_now_history":[],"rop_publish_now_status":"pending","footnotes":""},"categories":[5],"tags":[326,3942],"class_list":["post-110719","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualidad-informativa","tag-accion-popular","tag-mesias-guevara"],"_links":{"self":[{"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/posts\/110719","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/comments?post=110719"}],"version-history":[{"count":1,"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/posts\/110719\/revisions"}],"predecessor-version":[{"id":110720,"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/posts\/110719\/revisions\/110720"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/media\/64248"}],"wp:attachment":[{"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/media?parent=110719"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/categories?post=110719"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/tags?post=110719"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}