{"id":108340,"date":"2021-11-23T19:18:47","date_gmt":"2021-11-24T00:18:47","guid":{"rendered":"https:\/\/elinformanteperu.com\/?p=108340"},"modified":"2021-11-23T19:24:59","modified_gmt":"2021-11-24T00:24:59","slug":"ocho-datos-esenciales-sobre-la-nueva-serie-de-marvel-hawkeye-que-se-estrena-este-24-de-noviembre","status":"publish","type":"post","link":"https:\/\/elinformanteperu.com\/index.php\/2021\/11\/23\/ocho-datos-esenciales-sobre-la-nueva-serie-de-marvel-hawkeye-que-se-estrena-este-24-de-noviembre\/","title":{"rendered":"Ocho datos esenciales sobre la nueva serie de Marvel, Hawkeye, que se estrena este 24 de noviembre"},"content":{"rendered":"<p><span style=\"color: #000000;\"><strong>Lima, 23 Noviembre 2021, (El Informante Per\u00fa).-<\/strong> El mi\u00e9rcoles 24 de noviembre estrena en Disney+ Hawkeye, la nueva serie de Marvel Studios exclusiva del servicio de streaming. Ambientada en la ciudad de Nueva York posterior al blip, la serie sigue al ex Vengador, Clint Barton (Jeremy Renner), en una misi\u00f3n aparentemente simple: reencontrarse con su familia en Navidad. Pero cuando la presencia de un enemigo del pasado de Barton amenaza con descarrilar mucho m\u00e1s que el esp\u00edritu festivo, se ve obligado a trabajar con Kate Bishop (Hailee Steinfled), una h\u00e1bil arquera de 22 a\u00f1os y su mayor fan, para detenerlo y llegar a tiempo a casa.<\/span><\/p>\n<p><span style=\"color: #000000;\">Estos ocho datos clave sobre la nueva producci\u00f3n brindan la preparaci\u00f3n perfecta para entrar en clima antes del estreno y disfrutar al m\u00e1ximo de las andanzas de Barton y Bishop.<\/span><\/p>\n<p><strong><span style=\"color: #000000;\">La historia explora un nuevo territorio<\/span><\/strong><\/p>\n<p><a href=\"https:\/\/elinformanteperu.com\/wp-content\/uploads\/2021\/11\/Hawkeye-1.png\"><img fetchpriority=\"high\" decoding=\"async\" class=\"size-full wp-image-108341 aligncenter\" src=\"https:\/\/elinformanteperu.com\/wp-content\/uploads\/2021\/11\/Hawkeye-1.png\" alt=\"\" width=\"409\" height=\"274\" srcset=\"https:\/\/elinformanteperu.com\/wp-content\/uploads\/2021\/11\/Hawkeye-1.png 409w, https:\/\/elinformanteperu.com\/wp-content\/uploads\/2021\/11\/Hawkeye-1-300x201.png 300w\" sizes=\"(max-width: 409px) 100vw, 409px\" \/><\/a><span style=\"color: #000000;\">\u00abTodav\u00eda hay muchas cosas sobre Hawkeye que no hemos explorado. La serie nos permite mostrar un nuevo lado de Clint Barton\u00bb, explica la productora ejecutiva de la serie Trinh Tran. El Universo Cinematogr\u00e1fico de Marvel (MCU, por sus siglas en ingl\u00e9s) mostr\u00f3 a Barton perdiendo a su familia en el blip y descargando su dolor, rabia y tristeza con todos los villanos del planeta. Bert, del equipo de direcci\u00f3n Bert &amp; Bertie, que dirige tres episodios de la serie, dice que el pasado reciente de Hawkeye es la ra\u00edz de la nueva serie. \u201cSufri\u00f3 una gran p\u00e9rdida, tanto en el blip como cuando perdi\u00f3 a Natasha. Eso estableci\u00f3 un punto de partida emocional muy interesante. Clint tendr\u00eda que renunciar a su pasado para dejar entrar a alguien nuevo. As\u00ed que la profundidad que pudimos extraer en su personaje fue un hermoso desaf\u00edo, y en las manos de un actor de m\u00faltiples talentos como Jeremy, sab\u00edamos que los fans no se sentir\u00edan decepcionados \u00ab, relata Bert.<\/span><\/p>\n<p><strong><span style=\"color: #000000;\">Tres directores est\u00e1n al frente de la serie<\/span><\/strong><\/p>\n<p><span style=\"color: #000000;\">Marvel Studios convoc\u00f3 a tres realizadores para llevar adelante la nueva serie. Junto a Bert, completan el tr\u00edo de directores de Hawkeye Rhys Thomas y Bertie. Conocido por su trabajo de direcci\u00f3n en el c\u00e9lebre programa Saturday Night Live, Thomas dirige tres de los seis episodios y tambi\u00e9n se desempe\u00f1a como productor ejecutivo de la serie. Por su parte, las realizadoras Bert &amp; Bernie, que est\u00e1n al frente de otros tres episodios, conforman un d\u00fao en ascenso, reconocido por su trabajo en la aclamada pel\u00edcula de 2019 Troop Zero y por numerosos proyectos para plataformas de streaming y televisi\u00f3n.<\/span><\/p>\n<p><a href=\"https:\/\/elinformanteperu.com\/wp-content\/uploads\/2021\/11\/Hawkeye1.png\"><img decoding=\"async\" class=\"size-full wp-image-108342 aligncenter\" src=\"https:\/\/elinformanteperu.com\/wp-content\/uploads\/2021\/11\/Hawkeye1.png\" alt=\"\" width=\"521\" height=\"219\" srcset=\"https:\/\/elinformanteperu.com\/wp-content\/uploads\/2021\/11\/Hawkeye1.png 521w, https:\/\/elinformanteperu.com\/wp-content\/uploads\/2021\/11\/Hawkeye1-300x126.png 300w\" sizes=\"(max-width: 521px) 100vw, 521px\" \/><\/a><strong><span style=\"color: #000000;\">Un nuevo personaje desembarca en el MCU<\/span><\/strong><\/p>\n<p><span style=\"color: #000000;\">Kate Bishop, el personaje interpretado por Hailee Steinfeld que une fuerzas con Barton, hace su primera aparici\u00f3n en el MCU a trav\u00e9s de Hawkeye. Seg\u00fan Bert, Bishop es la contraparte perfecta para Barton. \u201cEst\u00e1 llena de energ\u00eda de novato; es luchadora y de voluntad fuerte, con un profundo deseo de demostrar todo su potencial. La suya es una confianza refrescante que no siempre podemos explorar en personajes femeninos. Tiene habilidades incre\u00edbles con el arco y la flecha y nos encanta que sepa lo buena que es. Afortunadamente, Kate es el contraste de comedia de Clint, y eso la hace infinitamente querible\u201d, comenta Bert.<\/span><\/p>\n<p><strong><span style=\"color: #000000;\">El c\u00f3mic de Marvel hom\u00f3nimo sirvi\u00f3 de inspiraci\u00f3n<\/span><\/strong><\/p>\n<p><span style=\"color: #000000;\">La historia de Hawkeye, nutrida de diversas fuentes, est\u00e1 en parte inspirada en la exitosa serie de c\u00f3mics de Marvel del mismo nombre, escrita por Matt Fraction. Editados entre 2012 y 2015, los c\u00f3mics cuentan con ilustraciones del dibujante espa\u00f1ol David Aja.<\/span><\/p>\n<p><a href=\"https:\/\/elinformanteperu.com\/wp-content\/uploads\/2021\/11\/Hawkeye2.png\"><img decoding=\"async\" class=\"size-full wp-image-108343 aligncenter\" src=\"https:\/\/elinformanteperu.com\/wp-content\/uploads\/2021\/11\/Hawkeye2.png\" alt=\"\" width=\"422\" height=\"281\" srcset=\"https:\/\/elinformanteperu.com\/wp-content\/uploads\/2021\/11\/Hawkeye2.png 422w, https:\/\/elinformanteperu.com\/wp-content\/uploads\/2021\/11\/Hawkeye2-300x200.png 300w\" sizes=\"(max-width: 422px) 100vw, 422px\" \/><\/a><strong><span style=\"color: #000000;\">El elenco se completa con grandes talentos<\/span><\/strong><\/p>\n<p><span style=\"color: #000000;\">La serie no solo brilla con la presencia de Renner y Steinfeld, sino que adem\u00e1s cuenta con un talentoso reparto que da vida al resto de los personajes de la historia. Completan el elenco los actores y las actrices Vera Farmiga, Fra Fee, Tony Dalton, Zahn McClarnon y la debutante Alaqua Cox en el papel de \u201cMaya L\u00f3pez\u201d.<\/span><\/p>\n<p><strong><span style=\"color: #000000;\">El c\u00f3mic de Marvel hom\u00f3nimo sirvi\u00f3 de inspiraci\u00f3n<\/span><\/strong><\/p>\n<p><span style=\"color: #000000;\">La historia de Hawkeye est\u00e1 en parte inspirada en la exitosa serie de c\u00f3mics de Marvel del mismo nombre, escrita por Matt Fraction.\u00a0<\/span><\/p>\n<p><a href=\"https:\/\/elinformanteperu.com\/wp-content\/uploads\/2021\/11\/Hawkeye3.png\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-108344 aligncenter\" src=\"https:\/\/elinformanteperu.com\/wp-content\/uploads\/2021\/11\/Hawkeye3.png\" alt=\"\" width=\"409\" height=\"273\" srcset=\"https:\/\/elinformanteperu.com\/wp-content\/uploads\/2021\/11\/Hawkeye3.png 409w, https:\/\/elinformanteperu.com\/wp-content\/uploads\/2021\/11\/Hawkeye3-300x200.png 300w\" sizes=\"(max-width: 409px) 100vw, 409px\" \/><\/a><strong><span style=\"color: #000000;\">Hay un musical extraordinario dentro de la historia<\/span><\/strong><\/p>\n<p><span style=\"color: #000000;\">En la historia, Barton se encuentra en la ciudad de Nueva York porque ha sido invitado a ver un musical sobre Steve Rogers. A partir de este elemento del guion, el equipo creativo de la serie enfrent\u00f3 el singular desaf\u00edo de crear un musical de gran escala dentro de la serie. \u201cEste musical es un verdadero regalo a Broadway. Posiblemente sea el mejor musical jam\u00e1s escrito. Desafortunadamente, solo incluimos un fragmento en la serie, pero les aseguro que es la pieza m\u00e1s extraordinaria de teatro musical jam\u00e1s imaginada\u201d, se\u00f1ala Thomas. \u00bfUn dato extra? La m\u00fasica de la obra ficticia est\u00e1 creada por el reconocido d\u00fao de compositores Marc Shaiman y Scott Wittman, creadores de t\u00edtulos ic\u00f3nicos como Hairspray, Smash y El Regreso de Mary Poppins.<\/span><\/p>\n<p><strong><span style=\"color: #000000;\">Hailee Steinfeld comparte doble riesgo con Scarlett Johansson<\/span><\/strong><\/p>\n<p><span style=\"color: #000000;\">Para ponerse en la piel de un personaje que se considera la mejor arquera del mundo, Steinfeld pas\u00f3 por un entrenamiento extenso y variado. Luego de entrenar y recibir sus primeras clases de arquer\u00eda en Los \u00c1ngeles, la actriz desembarc\u00f3 en el set y se puso en manos de Heidi Moneymaker, coordinadora del equipo de escenas de riesgo de Hawkeye. Moneymaker es la doble de riesgo de Steinfeld en la serie y ha tenido el mismo rol para la actriz Scarlett Johansson, personificando a Black Widow en escenas de riesgo desde Iron Man 2 hasta la reciente Blaco Widow. Se\u00f1ala Steinfeld: \u201cFue tan maravillosa y paciente. Muchas veces, una secuencia de pelea parece incre\u00edblemente intrincada y muy abrumadora e intimidante. Es bueno tener a alguien que cree en ti y te empuje. Heidi y todo el equipo de especialistas siempre me hicieron sentir muy segura, lo cual es importante\u00bb.<\/span><\/p>\n<p><span style=\"color: #000000;\">Hawkeye estrena el 24 de noviembre, exclusivamente en Disney+, y presenta nuevos episodios todos los mi\u00e9rcoles.<\/span><\/p>\n<p><iframe title=\"YouTube video player\" src=\"https:\/\/www.youtube-nocookie.com\/embed\/EW9ayJSWa_k?controls=0\" width=\"520\" height=\"315\" frameborder=\"0\" allowfullscreen=\"allowfullscreen\"><span data-mce-type=\"bookmark\" style=\"display: inline-block; width: 0px; overflow: hidden; line-height: 0;\" class=\"mce_SELRES_start\">\ufeff<\/span><\/iframe><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Lima, 23 Noviembre 2021, (El Informante Per\u00fa).- El mi\u00e9rcoles 24 de noviembre estrena en Disney+ Hawkeye, la nueva serie de Marvel Studios exclusiva del servicio de streaming. Ambientada en la ciudad de Nueva York posterior al blip, la serie sigue al ex Vengador, Clint Barton (Jeremy Renner), en una misi\u00f3n aparentemente simple: reencontrarse con su [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":103015,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"rop_custom_images_group":[],"rop_custom_messages_group":[],"rop_publish_now":"initial","rop_publish_now_accounts":[],"rop_publish_now_history":[],"rop_publish_now_status":"pending","footnotes":""},"categories":[70],"tags":[6715,242,3808],"class_list":["post-108340","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-farandula","tag-hawkeye","tag-marvel","tag-marvel-comics"],"_links":{"self":[{"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/posts\/108340","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/comments?post=108340"}],"version-history":[{"count":1,"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/posts\/108340\/revisions"}],"predecessor-version":[{"id":108345,"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/posts\/108340\/revisions\/108345"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/media\/103015"}],"wp:attachment":[{"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/media?parent=108340"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/categories?post=108340"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/tags?post=108340"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}