{"id":104446,"date":"2021-09-01T18:52:46","date_gmt":"2021-09-01T23:52:46","guid":{"rendered":"https:\/\/elinformanteperu.com\/?p=104446"},"modified":"2021-09-01T18:52:46","modified_gmt":"2021-09-01T23:52:46","slug":"ipd-exige-a-aficionados-respetar-normas-establecidas-durante-el-peru-uruguay","status":"publish","type":"post","link":"https:\/\/elinformanteperu.com\/index.php\/2021\/09\/01\/ipd-exige-a-aficionados-respetar-normas-establecidas-durante-el-peru-uruguay\/","title":{"rendered":"IPD exige a aficionados respetar normas establecidas durante el Per\u00fa-Uruguay"},"content":{"rendered":"<p><span style=\"color: #000000;\"><strong>Lima, 01 Setiembre 2021, (ANDINA).-<\/strong> El presidente del Instituto Peruano del Deporte (IPD), Gustavo San Mart\u00edn, pidi\u00f3 a los espectadores presentes en el Estadio Nacional para ver el partido entre Per\u00fa y Uruguay respeten las normas de bioseguridad establecidas que fueron parte de los requisitos para que el Ministerio de Salud brinde el permiso correspondiente.<\/span><\/p>\n<p><span style=\"color: #000000;\">San Mart\u00edn salud\u00f3 la buena noticia sobre la presencia de la afici\u00f3n en el Estadio Nacional.<\/span><\/p>\n<p><span style=\"color: #000000;\">\u201cTendremos alrededor de 8000 personas con todas las medidas que ya estamos implementando en este momento en el estadio, vamos a reiniciar con eliminatorias y de acuerdo a eso iremos pasando a otro nivel de competencia\u201d.<\/span><\/p>\n<p><span style=\"color: #000000;\">\u201cEsperamos que la gente respete las normas y se vea que se puede hacer un trabajo organizado porque a partir de all\u00ed se puedan seguir brindando los permisos para otras actividades y no solamente para el f\u00fatbol\u201d, a\u00f1adi\u00f3 el titular del IPD.<\/span><\/p>\n<p><span style=\"color: #000000;\">El Ministerio de Salud inform\u00f3 que el aforo para presenciar los partidos Per\u00fa-Uruguay (2 de setiembre) y Per\u00fa-Venezuela (5 de setiembre) en el Estadio Nacional ser\u00e1 del 20% del aforo total de la sede deportiva, un aproximado de 8000 personas, las cuales deben contar con los siguientes requisitos: ser mayores de 18 a\u00f1os, vacunados con dosis completa contra la covid-19 y acreditar constancia digital de vacunaci\u00f3n nacional o internacional.<\/span><\/p>\n<p><span style=\"color: #000000;\">\u201cSe van a habilitar las 4 tribunas m\u00e1s los palcos, el porcentaje se aplica a cada una. El ingreso al Estadio Nacional est\u00e1 considerado de manera escalonada, norte y sur estar\u00e1n abiertas desde las 16:00 horas, y oriente y occidente se permite el ingreso con dos horas de anticipaci\u00f3n\u201d, se refiri\u00f3 el presidente del IPD con respecto a los accesos al Estadio Nacional.<\/span><\/p>\n<p><span style=\"color: #000000;\">Para finalizar el titular del IPD agreg\u00f3 que, \u201cLa recomendaci\u00f3n general es que no se quiten la mascarilla en ning\u00fan momento, invocamos a la poblaci\u00f3n a que respete las normas para que esto salga bien y que contin\u00fae asistiendo la gente a los partidos\u201d.<\/span><\/p>\n<p><span style=\"color: #000000;\">Los encuentros que tendr\u00e1 la selecci\u00f3n peruana de f\u00fatbol en el marco de las Clasificatorias al Mundial Qatar 2022, est\u00e1n programados para los d\u00edas 2 de setiembre a las 8:00 p. m., contra Uruguay y el 5 de setiembre a la misma hora contra Venezuela, ambos en el Estadio Nacional.<\/span><\/p>\n<p><a href=\"https:\/\/elinformanteperu.com\/wp-content\/uploads\/2020\/12\/estadio-nacional-final-2020.jpg\"><img fetchpriority=\"high\" decoding=\"async\" class=\"alignnone size-full wp-image-89007\" src=\"https:\/\/elinformanteperu.com\/wp-content\/uploads\/2020\/12\/estadio-nacional-final-2020.jpg\" alt=\"\" width=\"1800\" height=\"1200\" srcset=\"https:\/\/elinformanteperu.com\/wp-content\/uploads\/2020\/12\/estadio-nacional-final-2020.jpg 1800w, https:\/\/elinformanteperu.com\/wp-content\/uploads\/2020\/12\/estadio-nacional-final-2020-300x200.jpg 300w, https:\/\/elinformanteperu.com\/wp-content\/uploads\/2020\/12\/estadio-nacional-final-2020-1024x683.jpg 1024w, https:\/\/elinformanteperu.com\/wp-content\/uploads\/2020\/12\/estadio-nacional-final-2020-768x512.jpg 768w, https:\/\/elinformanteperu.com\/wp-content\/uploads\/2020\/12\/estadio-nacional-final-2020-1536x1024.jpg 1536w\" sizes=\"(max-width: 1800px) 100vw, 1800px\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Lima, 01 Setiembre 2021, (ANDINA).- El presidente del Instituto Peruano del Deporte (IPD), Gustavo San Mart\u00edn, pidi\u00f3 a los espectadores presentes en el Estadio Nacional para ver el partido entre Per\u00fa y Uruguay respeten las normas de bioseguridad establecidas que fueron parte de los requisitos para que el Ministerio de Salud brinde el permiso correspondiente. [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":104447,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"rop_custom_images_group":[],"rop_custom_messages_group":[],"rop_publish_now":"initial","rop_publish_now_accounts":[],"rop_publish_now_history":[],"rop_publish_now_status":"pending","footnotes":""},"categories":[8],"tags":[5017,920,417,6770],"class_list":["post-104446","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-disciplinas-deportivas","tag-gustavo-san-martin","tag-instituto-peruano-del-deporte","tag-ipd","tag-peru-uruguay"],"_links":{"self":[{"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/posts\/104446","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/comments?post=104446"}],"version-history":[{"count":1,"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/posts\/104446\/revisions"}],"predecessor-version":[{"id":104448,"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/posts\/104446\/revisions\/104448"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/media\/104447"}],"wp:attachment":[{"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/media?parent=104446"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/categories?post=104446"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/tags?post=104446"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}