{"id":104166,"date":"2021-08-26T20:51:01","date_gmt":"2021-08-27T01:51:01","guid":{"rendered":"https:\/\/elinformanteperu.com\/?p=104166"},"modified":"2021-08-26T20:51:01","modified_gmt":"2021-08-27T01:51:01","slug":"finalizo-el-rodaje-de-la-serie-exclusiva-de-star-santa-evita","status":"publish","type":"post","link":"https:\/\/elinformanteperu.com\/index.php\/2021\/08\/26\/finalizo-el-rodaje-de-la-serie-exclusiva-de-star-santa-evita\/","title":{"rendered":"Finaliz\u00f3 el rodaje de la serie exclusiva de Star+ \u00abSanta Evita\u00bb"},"content":{"rendered":"<p><span style=\"color: #000000;\"><span style=\"color: #000000;\"><b>La serie est\u00e1 basada en la novela hom\u00f3nima de Tom\u00e1s Eloy Mart\u00ednez\u00a0y sigue la historia del cuerpo embalsamado de Eva Per\u00f3n despu\u00e9s de su muerte<\/b><\/span><\/span><\/p>\n<p><span style=\"color: #000000;\"><strong>Lima, 26 Agosto 2021, (El Informante Per\u00fa).-<\/strong> Tras 19 semanas de grabaciones, Star+ anunci\u00f3 el final de las grabaciones de \u201cSanta Evita\u201d, la esperada serie del sello Star Original Productions que llegar\u00e1 en exclusiva a Star+, el nuevo servicio de streaming de The Walt Disney Latin America.<\/span><\/p>\n<p><span style=\"color: #000000;\">La nueva producci\u00f3n sigue la historia del cuerpo embalsamado de la m\u00edtica primera dama argentina Eva Per\u00f3n y est\u00e1 protagonizada por un reconocido elenco internacional, encabezado por Natalia Oreiro (Eva Per\u00f3n), Ernesto Alterio (Moori Koenig), Dar\u00edo Grandinetti (Juan Domingo Per\u00f3n), Francesc Orella (Dr. Ara) y Diego Vel\u00e1zquez (Mariano V\u00e1zquez).<\/span><\/p>\n<p><a href=\"https:\/\/elinformanteperu.com\/wp-content\/uploads\/2021\/08\/santa-evita1.jpg\"><img fetchpriority=\"high\" decoding=\"async\" class=\"alignnone size-full wp-image-104168\" src=\"https:\/\/elinformanteperu.com\/wp-content\/uploads\/2021\/08\/santa-evita1.jpg\" alt=\"\" width=\"560\" height=\"373\" srcset=\"https:\/\/elinformanteperu.com\/wp-content\/uploads\/2021\/08\/santa-evita1.jpg 560w, https:\/\/elinformanteperu.com\/wp-content\/uploads\/2021\/08\/santa-evita1-300x200.jpg 300w\" sizes=\"(max-width: 560px) 100vw, 560px\" \/><\/a><\/p>\n<p><span style=\"color: #000000;\">Esta historia compuesta por siete episodios cuenta con la producci\u00f3n ejecutiva de la actriz mexicana Salma Hayek y Pepe T\u00e1mez (ambos de la productora Ventanarosa), la direcci\u00f3n del realizador Rodrigo Garc\u00eda, quien tambi\u00e9n se desempe\u00f1a en esta producci\u00f3n como productor ejecutivo, y del cineasta, actor, director teatral y guionista argentino Alejandro Maci.<\/span><\/p>\n<p><span style=\"color: #000000;\">\u201cEstamos muy agradecidos con Disney por habernos invitado a participar en el rol de coproductores de Santa Evita, junto con Ventanarosa. Es un proyecto que ven\u00eda madurando hac\u00eda un largo tiempo y Non Stop se sum\u00f3 en el momento justo para aportar todo su potencial. El material est\u00e1 quedando incre\u00edble. Lo que se va a ver en la pantalla es de una factura muy pocas veces vista en Latinoam\u00e9rica\u201d, expres\u00f3 Patricio Rabuffetti, director general de Non Stop, compa\u00f1\u00eda que adem\u00e1s de la producci\u00f3n integral de la serie, tiene a su cargo la distribuci\u00f3n fuera de Latinoam\u00e9rica. \u201cContar con Salma Hayek como coproductora y trabajar con Rodrigo Garc\u00eda como director es una experiencia importante, no solo para este proyecto, sino para la industria en la regi\u00f3n\u201d, agreg\u00f3 Rabufetti.<\/span><\/p>\n<p><a href=\"https:\/\/elinformanteperu.com\/wp-content\/uploads\/2021\/08\/santa-evita3.jpg\"><img decoding=\"async\" class=\"alignnone size-full wp-image-104169\" src=\"https:\/\/elinformanteperu.com\/wp-content\/uploads\/2021\/08\/santa-evita3.jpg\" alt=\"\" width=\"560\" height=\"373\" srcset=\"https:\/\/elinformanteperu.com\/wp-content\/uploads\/2021\/08\/santa-evita3.jpg 560w, https:\/\/elinformanteperu.com\/wp-content\/uploads\/2021\/08\/santa-evita3-300x200.jpg 300w\" sizes=\"(max-width: 560px) 100vw, 560px\" \/><\/a><\/p>\n<p><span style=\"color: #000000;\">\u201cSanta Evita\u201d est\u00e1 basada en el best seller hom\u00f3nimo del escritor argentino Tom\u00e1s Eloy Mart\u00ednez, y sigue la intrigante historia del cuerpo embalsamado de Eva Per\u00f3n despu\u00e9s de su muerte, el cual se mantuvo a la espera de ser enterrado durante tres a\u00f1os para la construcci\u00f3n de un monumento que nunca se concret\u00f3. En 1955, las fuerzas militares de Argentina derrocaron al entonces presidente Juan Domingo Per\u00f3n y ocultaron el cuerpo de Evita durante 19 a\u00f1os, con el fin de evitar que se convirtiera en un arma contra el r\u00e9gimen. Antes de su muerte, Eva se hab\u00eda convertido en una potente figura pol\u00edtica como esposa del General Per\u00f3n, y su cad\u00e1ver errante sin sepultura influy\u00f3 en la pol\u00edtica del pa\u00eds durante m\u00e1s de dos d\u00e9cadas. \u201cSanta Evita\u201d es la historia de un cuerpo sin tumba y de la leyenda que naci\u00f3 en torno de \u00e9l.<\/span><\/p>\n<p><span style=\"color: #000000;\">\u201cSanta Evita\u201d se destaca por su alto valor y gran despliegue de producci\u00f3n: grabada en m\u00e1s de 40 locaciones de Buenos Aires, Argentina, la serie cont\u00f3 con la participaci\u00f3n de 120 actores y actrices, y 1300 extras, al tiempo que implic\u00f3 un meticuloso proceso de reconstrucci\u00f3n de \u00e9poca, de la mano de talentosos equipos locales de fotograf\u00eda, arte y vestuario, liderados por reconocidos profesionales creativos de la regi\u00f3n. Entre otros datos curiosos del rodaje, se destacan, por ejemplo, la presencia en escena de m\u00e1s de 80 veh\u00edculos antiguos en acci\u00f3n, as\u00ed como de 150 piezas de vestuario dise\u00f1adas especialmente para la serie.<\/span><\/p>\n<p><a href=\"https:\/\/elinformanteperu.com\/wp-content\/uploads\/2021\/08\/santa-evita4.jpg\"><img decoding=\"async\" class=\"alignnone size-full wp-image-104170\" src=\"https:\/\/elinformanteperu.com\/wp-content\/uploads\/2021\/08\/santa-evita4.jpg\" alt=\"\" width=\"560\" height=\"373\" srcset=\"https:\/\/elinformanteperu.com\/wp-content\/uploads\/2021\/08\/santa-evita4.jpg 560w, https:\/\/elinformanteperu.com\/wp-content\/uploads\/2021\/08\/santa-evita4-300x200.jpg 300w\" sizes=\"(max-width: 560px) 100vw, 560px\" \/><\/a><\/p>\n<p><span style=\"color: #000000;\">De esta manera, el nivel de producci\u00f3n de \u201cSanta Evita\u201d pone de relieve el talento t\u00e9cnico y art\u00edstico que hay en la regi\u00f3n, as\u00ed como la capacidad de producir proyectos de alta calidad para el mercado internacional, de la mano de profesionales de la industria del cine que han volcado su experiencia y talento al mundo de los contenidos de streaming.<\/span><\/p>\n<p><span style=\"color: #000000;\">\u201cSanta Evita\u201d llegar\u00e1 a Star+ en 2022.<\/span><\/p>\n<p><a href=\"https:\/\/elinformanteperu.com\/wp-content\/uploads\/2021\/08\/santa-evita2.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-104171\" src=\"https:\/\/elinformanteperu.com\/wp-content\/uploads\/2021\/08\/santa-evita2.jpg\" alt=\"\" width=\"560\" height=\"373\" srcset=\"https:\/\/elinformanteperu.com\/wp-content\/uploads\/2021\/08\/santa-evita2.jpg 560w, https:\/\/elinformanteperu.com\/wp-content\/uploads\/2021\/08\/santa-evita2-300x200.jpg 300w\" sizes=\"(max-width: 560px) 100vw, 560px\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La serie est\u00e1 basada en la novela hom\u00f3nima de Tom\u00e1s Eloy Mart\u00ednez\u00a0y sigue la historia del cuerpo embalsamado de Eva Per\u00f3n despu\u00e9s de su muerte Lima, 26 Agosto 2021, (El Informante Per\u00fa).- Tras 19 semanas de grabaciones, Star+ anunci\u00f3 el final de las grabaciones de \u201cSanta Evita\u201d, la esperada serie del sello Star Original Productions [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":104167,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"rop_custom_images_group":[],"rop_custom_messages_group":[],"rop_publish_now":"initial","rop_publish_now_accounts":[],"rop_publish_now_history":[],"rop_publish_now_status":"pending","footnotes":""},"categories":[70],"tags":[3296,791,6764,6754],"class_list":["post-104166","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-farandula","tag-natalia-oreiro","tag-salma-hayek","tag-santa-evita","tag-star-plus"],"_links":{"self":[{"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/posts\/104166","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/comments?post=104166"}],"version-history":[{"count":1,"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/posts\/104166\/revisions"}],"predecessor-version":[{"id":104172,"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/posts\/104166\/revisions\/104172"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/media\/104167"}],"wp:attachment":[{"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/media?parent=104166"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/categories?post=104166"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/tags?post=104166"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}