{"id":104164,"date":"2021-08-26T20:35:08","date_gmt":"2021-08-27T01:35:08","guid":{"rendered":"https:\/\/elinformanteperu.com\/?p=104164"},"modified":"2021-08-26T20:35:08","modified_gmt":"2021-08-27T01:35:08","slug":"spencer-descubre-en-el-trailer-a-krisen-stewart-como-la-princesa-diana","status":"publish","type":"post","link":"https:\/\/elinformanteperu.com\/index.php\/2021\/08\/26\/spencer-descubre-en-el-trailer-a-krisen-stewart-como-la-princesa-diana\/","title":{"rendered":"\u201cSpencer\u201d: Descubre en el Trailer a Krisen Stewart como la Princesa Diana"},"content":{"rendered":"<p><strong><span style=\"color: #000000;\">La cinta tendr\u00e1 su estreno exclusivo en el \u2018Festival de Cine de Venecia\u2019<\/span><\/strong><\/p>\n<p><span style=\"color: #000000;\"><strong>Lima, 26 Agosto 2021, (El Informante Per\u00fa).-<\/strong> El tr\u00e1iler del proyecto m\u00e1s reciente del Director chileno, Pablo Larra\u00edn, impacta con una Kristen Stewart irreconocible interpretando a la princesa Diana. Ella es la protagonista de la cinta \u201cSpencer\u201d. La cinta estar\u00e1 pr\u00f3xima a estrenarse en nuestros cines locales.<\/span><\/p>\n<p><span style=\"color: #000000;\">\u00abKristen es una de las grandes actrices de la actualidad\u00bb, dijo el director de &#8216;Spencer&#8217;, Pablo Larra\u00edn, a Deadline. \u00abPuede ser muy misteriosa y muy fr\u00e1gil, pero tambi\u00e9n puede ser muy fuerte, que es justamente lo que necesitamos&#8230; Es hermoso ver la manera en que respondi\u00f3 al guion y la forma en la que est\u00e1 abordando al personaje\u00bb.<\/span><\/p>\n<p><span style=\"color: #000000;\">Varios largometrajes y series han logrado mostrar algunas de las referencias que tuvo su figura ante el pueblo, en las que profundizamos sobre sus emociones antes, durante y despu\u00e9s de su matrimonio. Ahora una nueva oportunidad para explorar una parte de lo que vivi\u00f3, est\u00e1 en pleno desarrollo para la cinta llamada \u201cSpencer\u201d que protagonizar\u00e1 Kristen Stewart y dirigida por el galardonado Pablo Larra\u00edn.<\/span><\/p>\n<p><span style=\"color: #000000;\">\u2018El Festival del Cine de Venecia 2021\u2019 ser\u00e1 el evento donde se estrenar\u00e1 la cinta \u201cSpencer\u201d. Es por esto que, se ha robado la atenci\u00f3n del p\u00fablico en general, pues este festival es uno de los m\u00e1s importantes en el cual, se han proyectado filmes ganadores de varios premios de la academia.<\/span><\/p>\n<p><span style=\"color: #000000;\">Esta pel\u00edcula es dirigida por el reconocido director chileno, Pablo Larra\u00edn, quien nos trajo largometrajes exitosos y galardonados de la vida de \u2018Neruda\u2019 y \u2018Jackie\u2019. Ahora, nos trae la historia oculta de Lady Di.<\/span><\/p>\n<p><iframe title=\"YouTube video player\" src=\"https:\/\/www.youtube-nocookie.com\/embed\/0QzJKWdRus4?controls=0\" width=\"520\" height=\"315\" frameborder=\"0\" allowfullscreen=\"allowfullscreen\"><\/iframe><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La cinta tendr\u00e1 su estreno exclusivo en el \u2018Festival de Cine de Venecia\u2019 Lima, 26 Agosto 2021, (El Informante Per\u00fa).- El tr\u00e1iler del proyecto m\u00e1s reciente del Director chileno, Pablo Larra\u00edn, impacta con una Kristen Stewart irreconocible interpretando a la princesa Diana. Ella es la protagonista de la cinta \u201cSpencer\u201d. La cinta estar\u00e1 pr\u00f3xima a [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":104071,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"rop_custom_images_group":[],"rop_custom_messages_group":[],"rop_publish_now":"initial","rop_publish_now_accounts":[],"rop_publish_now_history":[],"rop_publish_now_status":"pending","footnotes":""},"categories":[7],"tags":[573,936,6760],"class_list":["post-104164","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-butaca","tag-diamond-films-peru","tag-kristen-stewart","tag-spencer"],"_links":{"self":[{"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/posts\/104164","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/comments?post=104164"}],"version-history":[{"count":1,"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/posts\/104164\/revisions"}],"predecessor-version":[{"id":104165,"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/posts\/104164\/revisions\/104165"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/media\/104071"}],"wp:attachment":[{"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/media?parent=104164"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/categories?post=104164"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/tags?post=104164"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}