{"id":104160,"date":"2021-08-26T20:28:51","date_gmt":"2021-08-27T01:28:51","guid":{"rendered":"https:\/\/elinformanteperu.com\/?p=104160"},"modified":"2021-08-26T20:28:51","modified_gmt":"2021-08-27T01:28:51","slug":"shang-chi-se-inicio-preventa-de-entradas-en-todo-el-peru","status":"publish","type":"post","link":"https:\/\/elinformanteperu.com\/index.php\/2021\/08\/26\/shang-chi-se-inicio-preventa-de-entradas-en-todo-el-peru\/","title":{"rendered":"\u00abShang -Chi\u00bb: se inici\u00f3 preventa de entradas en todo el Per\u00fa"},"content":{"rendered":"<p><strong><span style=\"color: #000000;\">Desde las 7:00 a.m. de hoy se inici\u00f3 la preventa de los boletos para la esperada pel\u00edcula \u00abMarvel\u00bb a nivel nacional.<\/span><\/strong><\/p>\n<p><span style=\"color: #000000;\"><strong>Lima, 26 Agosto 2021, (El Informante Per\u00fa).-<\/strong> Desde hoy, jueves 26 de agosto, ya se pueden comprar las entradas para el estreno de \u00abShang-Chi\u00bb. La cinta llegar\u00e1 a todas las salas peruanas este 2 de septiembre.<\/span><\/p>\n<p><span style=\"color: #000000;\">Los boletos para \u00abShang-Chi\u00bb ya pueden ser adquiridos en todas las boleter\u00edas de los cines a nivel nacional o ingresando a la web o App de Cinemark, Cineplanet, Cin\u00e9polis, UVK, Cinestar y en Autocine Lima Park. Cabe indicar que todas las salas contar\u00e1n con distintas funciones para todos los fan\u00e1ticos del Universo Cinematogr\u00e1fico de Marvel (UCM).<\/span><\/p>\n<p><span style=\"color: #000000;\">\u00abShang-Chi\u00bb es una de las pel\u00edculas de superh\u00e9roes m\u00e1s esperadas del a\u00f1o y ya se tiene todo listo para el estreno, que tendr\u00e1 lugar el 2 de septiembre en Per\u00fa y en gran parte de cines del planeta.<\/span><\/p>\n<p><a href=\"https:\/\/elinformanteperu.com\/wp-content\/uploads\/2021\/08\/Shang-Chi.jpg\"><img fetchpriority=\"high\" decoding=\"async\" class=\" wp-image-104162 aligncenter\" src=\"https:\/\/elinformanteperu.com\/wp-content\/uploads\/2021\/08\/Shang-Chi.jpg\" alt=\"\" width=\"374\" height=\"373\" srcset=\"https:\/\/elinformanteperu.com\/wp-content\/uploads\/2021\/08\/Shang-Chi.jpg 458w, https:\/\/elinformanteperu.com\/wp-content\/uploads\/2021\/08\/Shang-Chi-300x300.jpg 300w, https:\/\/elinformanteperu.com\/wp-content\/uploads\/2021\/08\/Shang-Chi-150x150.jpg 150w, https:\/\/elinformanteperu.com\/wp-content\/uploads\/2021\/08\/Shang-Chi-60x60.jpg 60w, https:\/\/elinformanteperu.com\/wp-content\/uploads\/2021\/08\/Shang-Chi-50x50.jpg 50w\" sizes=\"(max-width: 374px) 100vw, 374px\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Desde las 7:00 a.m. de hoy se inici\u00f3 la preventa de los boletos para la esperada pel\u00edcula \u00abMarvel\u00bb a nivel nacional. Lima, 26 Agosto 2021, (El Informante Per\u00fa).- Desde hoy, jueves 26 de agosto, ya se pueden comprar las entradas para el estreno de \u00abShang-Chi\u00bb. La cinta llegar\u00e1 a todas las salas peruanas este 2 [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":104161,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"rop_custom_images_group":[],"rop_custom_messages_group":[],"rop_publish_now":"initial","rop_publish_now_accounts":[],"rop_publish_now_history":[],"rop_publish_now_status":"pending","footnotes":""},"categories":[7,5745],"tags":[242,6763],"class_list":["post-104160","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-butaca","category-lo-ultimo","tag-marvel","tag-shang-chi"],"_links":{"self":[{"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/posts\/104160","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/comments?post=104160"}],"version-history":[{"count":1,"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/posts\/104160\/revisions"}],"predecessor-version":[{"id":104163,"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/posts\/104160\/revisions\/104163"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/media\/104161"}],"wp:attachment":[{"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/media?parent=104160"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/categories?post=104160"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/tags?post=104160"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}