{"id":103192,"date":"2021-08-05T00:53:02","date_gmt":"2021-08-05T05:53:02","guid":{"rendered":"https:\/\/elinformanteperu.com\/?p=103192"},"modified":"2021-08-05T00:53:02","modified_gmt":"2021-08-05T05:53:02","slug":"lactancia-materna-protege-contra-el-cancer","status":"publish","type":"post","link":"https:\/\/elinformanteperu.com\/index.php\/2021\/08\/05\/lactancia-materna-protege-contra-el-cancer\/","title":{"rendered":"\u00bfLactancia materna protege contra el c\u00e1ncer?"},"content":{"rendered":"<p><span style=\"color: #000000;\"><strong>Lima, 04 Agosto 2021, (El Informante Per\u00fa).-<\/strong> La leche materna es el mejor alimento que una madre puede ofrecer a su hijo al nacer, siendo una importante fuente de energ\u00eda, protecci\u00f3n y nutrientes preferentemente hasta los 24 meses.<\/span><\/p>\n<p><span style=\"color: #000000;\">Adem\u00e1s de todo esto, el embarazo y el hecho de amamantar crea un factor protector contra el c\u00e1ncer de mama debido a la actividad hormonal que se produce en las mujeres durante ese periodo, refiri\u00f3 el Dr. Mauricio Le\u00f3n Rivera, director m\u00e9dico del Centro Detector del C\u00e1ncer y jefe de la Unidad de Mastolog\u00eda de la Cl\u00ednica Ricardo Palma.<\/span><\/p>\n<p><span style=\"color: #000000;\">Asimismo, explic\u00f3 que la maduraci\u00f3n de las c\u00e9lulas mamarias, desde el estado prepuberal hasta el desarrollo de los conductos y lobulillos durante la lactancia, hace que las c\u00e9lulas se diferencien volvi\u00e9ndose m\u00e1s resistentes a las influencias carcinog\u00e9nicas o da\u00f1inas de las hormonas, del alcohol o de la comida chatarra.<\/span><\/p>\n<p><span style=\"color: #000000;\">Tambi\u00e9n dijo que este proceso natural se desarrolla especialmente en mujeres j\u00f3venes, sin embargo, cuando se realiza despu\u00e9s de los 40 a\u00f1os disminuye la protecci\u00f3n contra estos males.<\/span><\/p>\n<p><span style=\"color: #000000;\">\u201c\u201cEl problema actual es que las mujeres por distintas razones dan de lactar menos a sus hijos o simplemente no lo hacen utilizando leches industrializadas de alto costo. Esto podr\u00eda ser perjudicial para la madre y el hijo debido a que no benefician al organismo con este mecanismo defensivo\u201d, agreg\u00f3 el experto.<\/span><\/p>\n<p><span style=\"color: #000000;\">No obstante, el Dr. Le\u00f3n Rivera mencion\u00f3 que lo m\u00e1s importante adem\u00e1s del buen h\u00e1bito de la lactancia materna es el diagn\u00f3stico temprano del c\u00e1ncer, por ello, es importante que las mujeres a partir de los 30 a\u00f1os deben realizarse el examen f\u00edsico con un especialista (mast\u00f3logo) y complementarlo con una mamograf\u00eda a partir de los 40 a\u00f1os de edad.<\/span><\/p>\n<p><span style=\"color: #000000;\">Cabe mencionar, que la Semana Mundial de Lactancia Materna se celebra en todos los pa\u00edses del 01 al 07 de agosto de cada a\u00f1o, con el objetivo de promover sus beneficios en las madres y en sus hijos.<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Lima, 04 Agosto 2021, (El Informante Per\u00fa).- La leche materna es el mejor alimento que una madre puede ofrecer a su hijo al nacer, siendo una importante fuente de energ\u00eda, protecci\u00f3n y nutrientes preferentemente hasta los 24 meses. Adem\u00e1s de todo esto, el embarazo y el hecho de amamantar crea un factor protector contra el [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":103193,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"rop_custom_images_group":[],"rop_custom_messages_group":[],"rop_publish_now":"initial","rop_publish_now_accounts":[],"rop_publish_now_history":[],"rop_publish_now_status":"pending","footnotes":""},"categories":[10],"tags":[395,394],"class_list":["post-103192","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualidad-municipal","tag-clinica-ricardo-palma","tag-mauricio-leon-rivera"],"_links":{"self":[{"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/posts\/103192","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/comments?post=103192"}],"version-history":[{"count":1,"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/posts\/103192\/revisions"}],"predecessor-version":[{"id":103194,"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/posts\/103192\/revisions\/103194"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/media\/103193"}],"wp:attachment":[{"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/media?parent=103192"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/categories?post=103192"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/tags?post=103192"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}