{"id":103102,"date":"2021-08-03T00:01:52","date_gmt":"2021-08-03T05:01:52","guid":{"rendered":"https:\/\/elinformanteperu.com\/?p=103102"},"modified":"2021-08-03T00:01:52","modified_gmt":"2021-08-03T05:01:52","slug":"coronavirus-90-de-hospitalizados-y-en-uci-corresponde-a-pacientes-no-vacunados","status":"publish","type":"post","link":"https:\/\/elinformanteperu.com\/index.php\/2021\/08\/03\/coronavirus-90-de-hospitalizados-y-en-uci-corresponde-a-pacientes-no-vacunados\/","title":{"rendered":"Coronavirus: 90% de hospitalizados y en UCI corresponde a pacientes no vacunados"},"content":{"rendered":"<p><strong><span style=\"color: #000000;\">Especialistas exhortan a la poblaci\u00f3n vacunarse y cumplir con recibir las dos dosis de la vacuna contra el covid-19<\/span><\/strong><\/p>\n<p><span style=\"color: #000000;\"><strong>Lima, 02 Agosto 2021, (ANDINA).-<\/strong> El 90% de los pacientes que se encuentran hospitalizados o en una unidad de cuidados intensivos por la covid-19 son personas que no se aplicaron la vacuna contra el virus y son menores de 50 a\u00f1os, revel\u00f3 el expresidente de la Sociedad Peruana de Medicina Intensiva (Sopemi), Jes\u00fas Valverde.<\/span><\/p>\n<p><span style=\"color: #000000;\">En di\u00e1logo con la agencia Andina, Valverde explic\u00f3 que los hospitales nacionales est\u00e1n registrando esa tendencia, como tambi\u00e9n la presencia de pacientes entre los 50 y 60 a\u00f1os que se aplicaron solo una dosis de la vacuna.<\/span><\/p>\n<p><span style=\"color: #000000;\">\u201cEs una tendencia que se mantiene en los hospitales nacionales. Ahora las personas no vacunadas (contra el covid-19) est\u00e1n ocupando el lugar de los pacientes que est\u00e1n saliendo de alta\u201d, coment\u00f3.<\/span><\/p>\n<p><span style=\"color: #000000;\">Valverde, m\u00e9dico intensivista del hospital Dos de Mayo, confirm\u00f3 que la aplicaci\u00f3n de las dos dosis de la vacuna tiene resultados positivos porque ya no se reportan formas severas de la enfermedad en adultos mayores ni en personas con comorbilidades.<\/span><\/p>\n<p><span style=\"color: #000000;\">Dijo que, gracias a la inmunizaci\u00f3n completa contra la covid-19, los casos graves y de mortalidad han descendido, por lo que exhort\u00f3 a la poblaci\u00f3n a vacunarse y completar sus dosis, continuar con las medidas sanitarias y aprender a controlar otras enfermedades asociadas.<\/span><\/p>\n<p><span style=\"color: #000000;\">\u201cLas personas deben seguir cumpliendo el distanciamiento social, lavado de manos, usar mascarilla y doble protecci\u00f3n en lugares cerrados. Pero, adem\u00e1s, deben aprender a controlar la diabetes, la hipertensi\u00f3n y la obesidad, cambiar su cultura\u201d, precis\u00f3.<\/span><\/p>\n<p><strong><span style=\"color: #000000;\">Inmunidad reba\u00f1o<\/span><\/strong><\/p>\n<p><span style=\"color: #000000;\">Por su parte el m\u00e9dico infect\u00f3logo, Leslie Soto, revel\u00f3 que, en el caso del hospital Cayetano Heredia, donde labora, de cada 50 personas que llegan a UCI, 40 no se han aplicado la vacuna, ocho se aplicaron una dosis y dos cumplieron con la inmunizaci\u00f3n completa.<\/span><\/p>\n<p><span style=\"color: #000000;\">Adem\u00e1s, record\u00f3 que, de acuerdo a un informe del Ministerio de Salud (Minsa), de febrero a junio de este a\u00f1o en el pa\u00eds han fallecido 265 m\u00e9dicos por diferentes causas.<\/span><\/p>\n<p><span style=\"color: #000000;\">Detall\u00f3 que, de los 265 galenos fallecidos en ese periodo, 60 fueron a causa de la covid-19, y que, de este grupo de contagiados con el virus, 39 no ten\u00edan ninguna vacuna, 14 solo recibi\u00f3 una dosis y 7 las dos.<\/span><\/p>\n<p><span style=\"color: #000000;\">\u201cLa vacuna protege de la mortalidad, no importa la marca, es un arma m\u00e1s para combatir la covid-19, si se suma a las otras medidas de prevenci\u00f3n las personas estar\u00e1n 99.9 por ciento protegidas\u201d, acot\u00f3.<\/span><\/p>\n<p><span style=\"color: #000000;\">En esa l\u00ednea, Soto se\u00f1al\u00f3 que, debido a la presencia de diversas variantes del coronavirus, en el Per\u00fa se debe inmunizar al 80% de la poblaci\u00f3n para alcanzar la inmunidad de reba\u00f1o, y que ya no es suficiente alcanzar al 70% de vacunados con las dos dosis.<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Especialistas exhortan a la poblaci\u00f3n vacunarse y cumplir con recibir las dos dosis de la vacuna contra el covid-19 Lima, 02 Agosto 2021, (ANDINA).- El 90% de los pacientes que se encuentran hospitalizados o en una unidad de cuidados intensivos por la covid-19 son personas que no se aplicaron la vacuna contra el virus y [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":103103,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"rop_custom_images_group":[],"rop_custom_messages_group":[],"rop_publish_now":"initial","rop_publish_now_accounts":[],"rop_publish_now_history":[],"rop_publish_now_status":"pending","footnotes":""},"categories":[10],"tags":[388,431,5939],"class_list":["post-103102","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualidad-municipal","tag-ministerio-de-salud","tag-minsa","tag-vacunacion"],"_links":{"self":[{"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/posts\/103102","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/comments?post=103102"}],"version-history":[{"count":1,"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/posts\/103102\/revisions"}],"predecessor-version":[{"id":103104,"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/posts\/103102\/revisions\/103104"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/media\/103103"}],"wp:attachment":[{"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/media?parent=103102"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/categories?post=103102"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/tags?post=103102"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}