{"id":103079,"date":"2021-08-02T20:37:45","date_gmt":"2021-08-03T01:37:45","guid":{"rendered":"https:\/\/elinformanteperu.com\/?p=103079"},"modified":"2021-08-02T20:39:55","modified_gmt":"2021-08-03T01:39:55","slug":"serie-chiclayo-de-mis-amores-se-estrena-en-setiembre-en-peru-y-chile","status":"publish","type":"post","link":"https:\/\/elinformanteperu.com\/index.php\/2021\/08\/02\/serie-chiclayo-de-mis-amores-se-estrena-en-setiembre-en-peru-y-chile\/","title":{"rendered":"Serie \u00abChiclayo de mis amores\u00bb se estrena en setiembre en Per\u00fa y Chile"},"content":{"rendered":"<p><span style=\"color: #000000;\"><strong>Lima, 02 Agosto 2021, (ANDINA).-<\/strong> La serie peruana \u201cChiclayo de mis amores\u201d, protagonizada por Gerardo Zamora y Ana Claudia P\u00e9rez, se estrenar\u00e1 el pr\u00f3ximo mes de setiembre tanto en nuestro pa\u00eds como en Chile.<\/span><\/p>\n<p><span style=\"color: #000000;\">\u201cChiclayo de mis amores\u201d cuenta con cap\u00edtulos grabados \u00edntegramente en el norte del Per\u00fa, bajo la direcci\u00f3n general de Lot Plus. Las grabaciones empezaron en el mes del Bicentenario y se estrena por la se\u00f1al de Best Cable en Per\u00fa y Tevex en Chile.<\/span><\/p>\n<p><span style=\"color: #000000;\">La serie es protagonizada por Gerardo Zamora, quien se\u00f1ala que su personaje destaca por su tenacidad y perseverancia \u00abque tenemos las personas tenemos para sobreponernos a las adversidades y seguir adelante\u201d. El actor se\u00f1ala que la serie \u00abChiclayo de mis amores tiene todos los ingredientes para cautivar al p\u00fablico, tanto en personajes como en historia y locaciones. Me parece que tiene una gran proyecci\u00f3n\u201d.<\/span><\/p>\n<p><span style=\"color: #000000;\">Por su parte, la actriz Ana Claudia P\u00e9rez detalla que su personaje llamando Jessica \u00abes una chica honesta que detesta las mentiras. El director, Horacio Vergara, se ha inspirado en historias reales para darle vida a los personajes. La historia es muy potente y con un final que nadie esperar\u00eda. La gente realmente se enamorar\u00e1 de cada uno de los personajes y van a querer ver una segunda temporada\u201d.<\/span><\/p>\n<p><span style=\"color: #000000;\">\u201cConforme nos vayamos acercando al final se ir\u00e1n revelando diferentes circunstancias que nos har\u00e1n pensar si realmente la historia termina o todav\u00eda tenemos mucho por ver\u201d, asegura Zamora sobre la historia de su personaje \u00abMiguel\u00bb, un joven chepenano y sobre el de \u00bb Jessica\u00bb, la bella hija del mejor m\u00e9dico de la ciudad.<\/span><\/p>\n<p><span style=\"color: #000000;\">En el reparto tambi\u00e9n figuran actores chiclayanos como Anel Posada Tello, Rub\u00e9n Villegas, Asher y Aar\u00f3n D\u00edaz Guerrero, Lucas Erna\u00fa, Perla Cortez, Darwin Delgado, Erick Delgado, Eddy Yno\u00f1an, Pedro Chirinos, Giuliana Rivas, Javier Onofre, Duberl\u00ed Romero y Brunella Linares.<\/span><\/p>\n<p><span style=\"color: #000000;\">Junto a ellos Mar\u00eda Gastelo, Mirla Chinguel, Jord\u00e1n Cervera, Luz Zeta, Max Vallejos, Jovana Collantes, Luis Montalb\u00e1n, Jes\u00fas Panta, Luisa V\u00e9lez, Priscila Semp\u00e9n, Geraldine Cobos, C\u00e9sar Rom\u00e1n, Zulema Ram\u00edrez, Fernando Cacho, Willim Corsi y Carlos Curinambe.<\/span><\/p>\n<p><iframe title=\"YouTube video player\" src=\"https:\/\/www.youtube-nocookie.com\/embed\/I8XwpM8DQ_0?controls=0\" width=\"520\" height=\"315\" frameborder=\"0\" allowfullscreen=\"allowfullscreen\"><span data-mce-type=\"bookmark\" style=\"display: inline-block; width: 0px; overflow: hidden; line-height: 0;\" class=\"mce_SELRES_start\">\ufeff<\/span><\/iframe><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Lima, 02 Agosto 2021, (ANDINA).- La serie peruana \u201cChiclayo de mis amores\u201d, protagonizada por Gerardo Zamora y Ana Claudia P\u00e9rez, se estrenar\u00e1 el pr\u00f3ximo mes de setiembre tanto en nuestro pa\u00eds como en Chile. \u201cChiclayo de mis amores\u201d cuenta con cap\u00edtulos grabados \u00edntegramente en el norte del Per\u00fa, bajo la direcci\u00f3n general de Lot Plus. [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":103080,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"rop_custom_images_group":[],"rop_custom_messages_group":[],"rop_publish_now":"initial","rop_publish_now_accounts":[],"rop_publish_now_history":[],"rop_publish_now_status":"pending","footnotes":""},"categories":[70],"tags":[6719,6718,5677,6720],"class_list":["post-103079","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-farandula","tag-ana-claudia-perez","tag-chiclayo-de-mis-amores","tag-gerardo-zamora","tag-series-peru"],"_links":{"self":[{"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/posts\/103079","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/comments?post=103079"}],"version-history":[{"count":1,"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/posts\/103079\/revisions"}],"predecessor-version":[{"id":103081,"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/posts\/103079\/revisions\/103081"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/media\/103080"}],"wp:attachment":[{"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/media?parent=103079"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/categories?post=103079"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/elinformanteperu.com\/index.php\/wp-json\/wp\/v2\/tags?post=103079"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}